
{"id":4427,"date":"2014-11-24T23:00:00","date_gmt":"2014-11-24T23:00:00","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/?p=4427"},"modified":"2018-06-01T10:19:08","modified_gmt":"2018-06-01T10:19:08","slug":"il-design-cresce-medio-oriente-grazie-wall-y","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/it\/blog\/il-design-cresce-medio-oriente-grazie-wall-y\/","title":{"rendered":"IL DESIGN CRESCE IN MEDIO ORIENTE GRAZIE A WALL-Y"},"content":{"rendered":"<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-75359 size-full\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/11\/wally_middleeast.png\" alt=\"\" width=\"1240\" height=\"500\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/11\/wally_middleeast.png 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/11\/wally_middleeast-300x121.png 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/11\/wally_middleeast-768x310.png 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/11\/wally_middleeast-1024x413.png 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/11\/wally_middleeast-224x90.png 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/11\/wally_middleeast-124x50.png 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/11\/wally_middleeast-570x230.png 570w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n\r\nConiugare design ed eleganza alla protezione termica ed acustica della casa \u00e8 possibile, grazie a WALL-Y, la nostra griglia in PEHD vergine per la realizzazione di giardini verticali.\r\nOggi siamo in Medio Oriente, dove abbiamo contribuito alla valorizzazione di un residence le cui pareti sono state rivestite con 700 griglie di WALL-Y bianco, utilizzate come sostegno per piante rampicanti e ornamentali. Ideale sia su edifici esistenti che di nuova realizzazione grazie alla sua semplicit\u00e0 di installazione, WALL-Y non teme gli agenti atmosferici e le escursioni termiche, migliora le prestazioni energetiche dell&#8217;edificio rendendolo al tempo stesso pi\u00f9 bello e confortevole.","protected":false},"excerpt":{"rendered":"<p>Coniugare design ed eleganza alla protezione termica ed acustica della casa \u00e8 possibile, grazie a WALL-Y, la nostra griglia in PEHD vergine per la realizzazione di giardini verticali. Oggi siamo in Medio Oriente, dove abbiamo contribuito alla valorizzazione di un residence le cui pareti sono state rivestite con 700 griglie [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":75359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[40],"tags":[],"class_list":["post-4427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novita"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IL DESIGN CRESCE IN MEDIO ORIENTE GRAZIE A WALL-Y &#8211; Geoplast<\/title>\n<meta name=\"description\" content=\"Coniugare design ed eleganza alla protezione termica ed acustica della casa \u00e8 possibile, grazie a WALL-Y, la nostra griglia in PEHD vergine per la realizzazione di giardini verticali.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/il-design-cresce-medio-oriente-grazie-wall-y\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL DESIGN CRESCE IN MEDIO ORIENTE GRAZIE A WALL-Y &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Coniugare design ed eleganza alla protezione termica ed acustica della casa \u00e8 possibile, grazie a WALL-Y, la nostra griglia in PEHD vergine per la realizzazione di giardini verticali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/it\/blog\/il-design-cresce-medio-oriente-grazie-wall-y\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-24T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-01T10:19:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/11\/wally_middleeast.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nikola Tosic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nikola Tosic\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/il-design-cresce-medio-oriente-grazie-wall-y\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/il-design-cresce-medio-oriente-grazie-wall-y\\\/\"},\"author\":{\"name\":\"Nikola Tosic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/person\\\/0feabc79985006722a394123a98c8065\"},\"headline\":\"IL DESIGN CRESCE IN MEDIO ORIENTE GRAZIE A WALL-Y\",\"datePublished\":\"2014-11-24T23:00:00+00:00\",\"dateModified\":\"2018-06-01T10:19:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/il-design-cresce-medio-oriente-grazie-wall-y\\\/\"},\"wordCount\":107,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/il-design-cresce-medio-oriente-grazie-wall-y\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/wally_middleeast.png\",\"articleSection\":[\"Novit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/il-design-cresce-medio-oriente-grazie-wall-y\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/il-design-cresce-medio-oriente-grazie-wall-y\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/il-design-cresce-medio-oriente-grazie-wall-y\\\/\",\"name\":\"IL DESIGN CRESCE IN MEDIO ORIENTE GRAZIE A WALL-Y &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/il-design-cresce-medio-oriente-grazie-wall-y\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/il-design-cresce-medio-oriente-grazie-wall-y\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/wally_middleeast.png\",\"datePublished\":\"2014-11-24T23:00:00+00:00\",\"dateModified\":\"2018-06-01T10:19:08+00:00\",\"description\":\"Coniugare design ed eleganza alla protezione termica ed acustica della casa \u00e8 possibile, grazie a WALL-Y, la nostra griglia in PEHD vergine per la realizzazione di giardini verticali.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/il-design-cresce-medio-oriente-grazie-wall-y\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/il-design-cresce-medio-oriente-grazie-wall-y\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/wally_middleeast.png\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/wally_middleeast.png\",\"width\":1240,\"height\":500},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/person\\\/0feabc79985006722a394123a98c8065\",\"name\":\"Nikola Tosic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g\",\"caption\":\"Nikola Tosic\"},\"sameAs\":[\"https:\\\/\\\/www.geoplastglobal.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL DESIGN CRESCE IN MEDIO ORIENTE GRAZIE A WALL-Y &#8211; Geoplast","description":"Coniugare design ed eleganza alla protezione termica ed acustica della casa \u00e8 possibile, grazie a WALL-Y, la nostra griglia in PEHD vergine per la realizzazione di giardini verticali.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/it\/blog\/il-design-cresce-medio-oriente-grazie-wall-y\/","og_locale":"it_IT","og_type":"article","og_title":"IL DESIGN CRESCE IN MEDIO ORIENTE GRAZIE A WALL-Y &#8211; Geoplast","og_description":"Coniugare design ed eleganza alla protezione termica ed acustica della casa \u00e8 possibile, grazie a WALL-Y, la nostra griglia in PEHD vergine per la realizzazione di giardini verticali.","og_url":"https:\/\/www.geoplastglobal.com\/it\/blog\/il-design-cresce-medio-oriente-grazie-wall-y\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2014-11-24T23:00:00+00:00","article_modified_time":"2018-06-01T10:19:08+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/11\/wally_middleeast.png","type":"image\/png"}],"author":"Nikola Tosic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Nikola Tosic"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/il-design-cresce-medio-oriente-grazie-wall-y\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/il-design-cresce-medio-oriente-grazie-wall-y\/"},"author":{"name":"Nikola Tosic","@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/person\/0feabc79985006722a394123a98c8065"},"headline":"IL DESIGN CRESCE IN MEDIO ORIENTE GRAZIE A WALL-Y","datePublished":"2014-11-24T23:00:00+00:00","dateModified":"2018-06-01T10:19:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/il-design-cresce-medio-oriente-grazie-wall-y\/"},"wordCount":107,"commentCount":0,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/il-design-cresce-medio-oriente-grazie-wall-y\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/11\/wally_middleeast.png","articleSection":["Novit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.geoplastglobal.com\/it\/blog\/il-design-cresce-medio-oriente-grazie-wall-y\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/il-design-cresce-medio-oriente-grazie-wall-y\/","url":"https:\/\/www.geoplastglobal.com\/it\/blog\/il-design-cresce-medio-oriente-grazie-wall-y\/","name":"IL DESIGN CRESCE IN MEDIO ORIENTE GRAZIE A WALL-Y &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/il-design-cresce-medio-oriente-grazie-wall-y\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/il-design-cresce-medio-oriente-grazie-wall-y\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/11\/wally_middleeast.png","datePublished":"2014-11-24T23:00:00+00:00","dateModified":"2018-06-01T10:19:08+00:00","description":"Coniugare design ed eleganza alla protezione termica ed acustica della casa \u00e8 possibile, grazie a WALL-Y, la nostra griglia in PEHD vergine per la realizzazione di giardini verticali.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/it\/blog\/il-design-cresce-medio-oriente-grazie-wall-y\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/il-design-cresce-medio-oriente-grazie-wall-y\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/11\/wally_middleeast.png","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/11\/wally_middleeast.png","width":1240,"height":500},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/it\/#website","url":"https:\/\/www.geoplastglobal.com\/it\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/it\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/person\/0feabc79985006722a394123a98c8065","name":"Nikola Tosic","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g","caption":"Nikola Tosic"},"sameAs":["https:\/\/www.geoplastglobal.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts\/4427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/comments?post=4427"}],"version-history":[{"count":4,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts\/4427\/revisions"}],"predecessor-version":[{"id":75369,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts\/4427\/revisions\/75369"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/media?parent=4427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/categories?post=4427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/tags?post=4427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}