
{"id":3894,"date":"2015-03-29T22:00:00","date_gmt":"2015-03-29T22:00:00","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/?p=3894"},"modified":"2018-07-02T08:38:32","modified_gmt":"2018-07-02T08:38:32","slug":"mosbuild-2015","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/it\/blog\/mosbuild-2015\/","title":{"rendered":"Mosbuild 2015"},"content":{"rendered":"<div id=\"article\" class=\"node node-article clearfix\">\r\n<div class=\"centrato\">\r\n<div id=\"breadcrumb\" class=\"clearfix\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-74047 size-full\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/03\/mosbuild.png\" alt=\"\" width=\"1240\" height=\"500\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/03\/mosbuild.png 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/03\/mosbuild-300x121.png 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/03\/mosbuild-768x310.png 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/03\/mosbuild-1024x413.png 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/03\/mosbuild-224x90.png 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/03\/mosbuild-124x50.png 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/03\/mosbuild-570x230.png 570w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/><\/div>\r\n<div class=\"content clearfix\">\r\n<div class=\"articolo\">\r\n\r\nDal 14 al 17 Aprile 2015, Geoplast sar\u00e0 presente all&#8217;edizione 2015 della MOSBUILD a Mosca. Questa fiera \u00e8 il pi\u00f9 grande Expo sulle costruzioni in Russia e Europa dell&#8217;Est che per permette alle pi\u00f9 grandi compagnie leader internazionali, che si dedicano al campo della costruzione, della restaurazione e della finitura, di lanciare e presentare i propri prodotti.\r\n\r\nVeniteci a trovare al padiglione 2, Sala 1, stand C235!\r\nVi aspettiamo!\r\n\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"centrato socialsharethis\">\r\n\r\n<label>Consiglia questo articolo:<\/label>\r\n<div class=\"sharethis-buttons\">\r\n<div class=\"sharethis-wrapper\"><\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"comments\"><\/div>\r\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Dal 14 al 17 Aprile 2015, Geoplast sar\u00e0 presente all&#8217;edizione 2015 della MOSBUILD a Mosca. Questa fiera \u00e8 il pi\u00f9 grande Expo sulle costruzioni in Russia e Europa dell&#8217;Est che per permette alle pi\u00f9 grandi compagnie leader internazionali, che si dedicano al campo della costruzione, della restaurazione e della finitura, [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":74047,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[40],"tags":[],"class_list":["post-3894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novita"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mosbuild 2015 &#8211; Geoplast<\/title>\n<meta name=\"description\" content=\"Dal 14 al 17 Aprile 2015, Geoplast sar\u00e0 presente all&#039;edizione 2015 della MOSBUILD a Mosca.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/mosbuild-2015\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mosbuild 2015 &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Dal 14 al 17 Aprile 2015, Geoplast sar\u00e0 presente all&#039;edizione 2015 della MOSBUILD a Mosca.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/it\/blog\/mosbuild-2015\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-29T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-02T08:38:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/03\/mosbuild.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nikola Tosic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nikola Tosic\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/mosbuild-2015\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/mosbuild-2015\\\/\"},\"author\":{\"name\":\"Nikola Tosic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/person\\\/0feabc79985006722a394123a98c8065\"},\"headline\":\"Mosbuild 2015\",\"datePublished\":\"2015-03-29T22:00:00+00:00\",\"dateModified\":\"2018-07-02T08:38:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/mosbuild-2015\\\/\"},\"wordCount\":68,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/mosbuild-2015\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/mosbuild.png\",\"articleSection\":[\"Novit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/mosbuild-2015\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/mosbuild-2015\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/mosbuild-2015\\\/\",\"name\":\"Mosbuild 2015 &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/mosbuild-2015\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/mosbuild-2015\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/mosbuild.png\",\"datePublished\":\"2015-03-29T22:00:00+00:00\",\"dateModified\":\"2018-07-02T08:38:32+00:00\",\"description\":\"Dal 14 al 17 Aprile 2015, Geoplast sar\u00e0 presente all'edizione 2015 della MOSBUILD a Mosca.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/mosbuild-2015\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/mosbuild-2015\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/mosbuild.png\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/mosbuild.png\",\"width\":1240,\"height\":500},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/person\\\/0feabc79985006722a394123a98c8065\",\"name\":\"Nikola Tosic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g\",\"caption\":\"Nikola Tosic\"},\"sameAs\":[\"https:\\\/\\\/www.geoplastglobal.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mosbuild 2015 &#8211; Geoplast","description":"Dal 14 al 17 Aprile 2015, Geoplast sar\u00e0 presente all'edizione 2015 della MOSBUILD a Mosca.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/it\/blog\/mosbuild-2015\/","og_locale":"it_IT","og_type":"article","og_title":"Mosbuild 2015 &#8211; Geoplast","og_description":"Dal 14 al 17 Aprile 2015, Geoplast sar\u00e0 presente all'edizione 2015 della MOSBUILD a Mosca.","og_url":"https:\/\/www.geoplastglobal.com\/it\/blog\/mosbuild-2015\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2015-03-29T22:00:00+00:00","article_modified_time":"2018-07-02T08:38:32+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/03\/mosbuild.png","type":"image\/png"}],"author":"Nikola Tosic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Nikola Tosic"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/mosbuild-2015\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/mosbuild-2015\/"},"author":{"name":"Nikola Tosic","@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/person\/0feabc79985006722a394123a98c8065"},"headline":"Mosbuild 2015","datePublished":"2015-03-29T22:00:00+00:00","dateModified":"2018-07-02T08:38:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/mosbuild-2015\/"},"wordCount":68,"commentCount":0,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/mosbuild-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/03\/mosbuild.png","articleSection":["Novit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.geoplastglobal.com\/it\/blog\/mosbuild-2015\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/mosbuild-2015\/","url":"https:\/\/www.geoplastglobal.com\/it\/blog\/mosbuild-2015\/","name":"Mosbuild 2015 &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/mosbuild-2015\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/mosbuild-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/03\/mosbuild.png","datePublished":"2015-03-29T22:00:00+00:00","dateModified":"2018-07-02T08:38:32+00:00","description":"Dal 14 al 17 Aprile 2015, Geoplast sar\u00e0 presente all'edizione 2015 della MOSBUILD a Mosca.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/it\/blog\/mosbuild-2015\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/mosbuild-2015\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/03\/mosbuild.png","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2014\/03\/mosbuild.png","width":1240,"height":500},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/it\/#website","url":"https:\/\/www.geoplastglobal.com\/it\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/it\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/person\/0feabc79985006722a394123a98c8065","name":"Nikola Tosic","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g","caption":"Nikola Tosic"},"sameAs":["https:\/\/www.geoplastglobal.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts\/3894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/comments?post=3894"}],"version-history":[{"count":4,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts\/3894\/revisions"}],"predecessor-version":[{"id":77722,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts\/3894\/revisions\/77722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/media\/74047"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/media?parent=3894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/categories?post=3894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/tags?post=3894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}