
{"id":164130,"date":"2021-12-30T05:23:52","date_gmt":"2021-12-30T05:23:52","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/?p=164130"},"modified":"2025-06-19T14:15:55","modified_gmt":"2025-06-19T14:15:55","slug":"le-nostre-previsioni-sulle-tendenze-edilizie-del-2022","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/it\/blog\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\/","title":{"rendered":"Le nostre previsioni sulle tendenze edilizie del 2022"},"content":{"rendered":"<h3>Mirco Pegoraro, CEO &#038; Product Designer<\/h3>\r\n\r\nNel 2022 le problematiche sismiche passeranno in secondo piano a favore della sostenibilit\u00e0 che sar\u00e0 un tema predominante in tutti i settori delle costruzioni. I prodotti in plastica riciclata Geoplast saranno sempre pi\u00f9 richiesti dal mercato perch\u00e9 sono in grado di ridurre le emissioni di CO2 e hanno un basso impatto energetico. Questo vale in particolare per le soluzioni di fondazioni e solai. Un&#8217;altra questione importante sar\u00e0 l&#8217;invarianza idraulica. Gli sviluppi urbani dovranno iniziare a integrare gli spazi verdi pubblici con una gestione sostenibile dell&#8217;acqua piovana, che dovrebbe a sua volta aumentare la domanda di soluzioni verdi e idriche. Tutto ci\u00f2 si tradurr\u00e0 in un aumento della redditivit\u00e0 dei progetti che implementeranno questo tipo di misure.\r\n\r\n<a href=\"mailto: mirco.pegoraro@geoplastglobal.com\">mirco.pegoraro@geoplastglobal.com<\/a>\r\nSegui Mirco su <a href=\"https:\/\/www.linkedin.com\/in\/mircopegoraro\/\" rel=\"noopener\" target=\"_blank\">LinkedIn<\/a>\r\n\r\n<h3>Luca Zausa, CSO Global<\/h3>\r\n\r\nLa resilienza urbana e l&#8217;uso ridotto delle risorse saranno i temi dominanti della costruzione di edifici nel 2022. Le persone stanno diventando sempre pi\u00f9 consapevoli delle questioni ambientali, in particolare quelle relative alle aree urbane, come la gestione delle acque piovane e una generale carenza di materie prime. La nuova normativa sar\u00e0 spinta a consolidare l&#8217;opinione pubblica, che inevitabilmente influenzer\u00e0 l&#8217;andamento del mercato nel prossimo anno.\r\n\r\n<a href=\"mailto: luca.zausa@geoplastglobal.com\">luca.zausa@geoplastglobal.com<\/a>\r\nSegui Luca su <a href=\"https:\/\/www.linkedin.com\/in\/luca-zausa-a306341\/\" rel=\"noopener\" target=\"_blank\">LinkedIn<\/a>\r\n\r\n<h3>Francesco Guidetti, Direttore Tecnico<\/h3>\r\n\r\nA mio parere l&#8217;implementazione del BIM diventer\u00e0 un punto centrale nel processo di progettazione nel 2022. I modelli BIM consentiranno agli ingegneri e agli investitori immobiliari di pianificare l&#8217;uso dei materiali, le prestazioni energetiche, i costi e la manutenzione in modo molto pi\u00f9 efficiente, il che influenzer\u00e0 in modo significativo la sostenibilit\u00e0 e redditivit\u00e0 degli edifici.\r\n\r\nA seguito delle conclusioni del G20, la riduzione dell&#8217;impronta di carbonio sar\u00e0 un altro tema centrale del prossimo anno. Progettisti e appaltatori saranno sfidati su due fronti: da un lato l&#8217;immobiliare che chieder\u00e0 di avere \u201cedifici verdi\u201d, dall&#8217;altro la necessit\u00e0 di trovare un modo per costruire con meno emissioni di gas serra.\r\n\r\n<a href=\"mailto: francesco.guidetti@geoplastglobal.com\">francesco.guidetti@geoplastglobal.com<\/a>\r\nSegui Francesco su <a href=\"https:\/\/www.linkedin.com\/in\/francesco-guidetti-42464021\/\" rel=\"noopener\" target=\"_blank\">LinkedIn<\/a>\r\n\r\n<h3>Nikola Tosic, CMO<\/h3>\r\n\r\nInvestitori, architetti, ingegneri, societ\u00e0 di costruzioni e le vendite immobiliari avranno tutti difficolt\u00e0 a consolidare i crescenti requisiti di sostenibilit\u00e0 (normativa, clienti, pubblico) e le loro esigenze aziendali. Anche se la maggior parte vorr\u00e0 implementare la sostenibilit\u00e0 nei propri progetti, sar\u00e0 bloccata dalla mancanza di know-how e di accesso all&#8217;innovazione. Come reazione a questo problema, ci sar\u00e0 una crescita accelerata per soluzioni di redditivit\u00e0 sostenibile nelle costruzioni. Dominer\u00e0 il mercato chi ha know-how e prodotti in grado di rendere i progetti pi\u00f9 sostenibili e redditizi.\r\n\r\n<a href=\"mailto: nikola@openinnovation.me\">nikola@openinnovation.me<\/a>\r\nSegui Nikola su <a href=\"https:\/\/www.linkedin.com\/in\/nikolatosic\/\" rel=\"noopener\" target=\"_blank\">LinkedIn<\/a>\r\n\r\n<h3>Paolo Pirotto, COO<\/h3>\r\n\r\nLe emissioni di carbonio saranno oggetto di particolare attenzione nel mercato delle costruzioni il prossimo anno poich\u00e9 sono gi\u00e0 ampiamente riconosciute come la causa principale del cambiamento climatico. Secondo la nostra recente indagine BIM Object, il 75 % dei 2,500 AECO (architetti, ingegneri, imprese edili e proprietari) pone la sostenibilit\u00e0 come la questione pi\u00f9 importante nella costruzione degli edifici.\r\n\r\nUn&#8217;altra tendenza evidenziata dall&#8217;indagine \u00e8 legata all&#8217;importanza della digitalizzazione per il mercato delle costruzioni. La maggioranza (46 %) di AECO prevede di trovare informazioni sui nuovi prodotti online. Le aziende dovranno prestare maggiore attenzione a questo problema per facilitare un processo di progettazione pi\u00f9 rapido ed efficiente.\r\n\r\n<a href=\"mailto: paolo.pirotto@geoplastglobal.com\">paolo.pirotto@geoplastglobal.com<\/a>\r\nSegui Paolo su <a href=\"https:\/\/www.linkedin.com\/in\/paolo-pirotto-7abb81136\/\" rel=\"noopener\" target=\"_blank\">LinkedIn<\/a>\r\n\r\n<h3>Roberto Cecchinato, Responsabile vendite, Europa occidentale e centrale, Africa settentrionale e occidentale<\/h3>\r\n\r\nL&#8217;uso dell&#8217;energia sar\u00e0 un tema importante il prossimo anno. Milioni di edifici non sono pronti per gli standard energetici contemporanei e dovranno essere aggiornati. Inoltre, il riscaldamento globale sta cambiando i modelli meteorologici: l&#8217;intensit\u00e0 delle precipitazioni aumenter\u00e0, richiedendo miglioramenti all&#8217;infrastruttura di gestione delle acque piovane.\r\n\r\n<a href=\"mailto: roberto.cecchinato@geoplastglobal.com\">roberto.cecchinato@geoplastglobal.com<\/a>\r\nSegui Roberto su <a href=\"https:\/\/www.linkedin.com\/in\/roberto-cecchinato-2a82574\/\" rel=\"noopener\" target=\"_blank\">LinkedIn<\/a>\r\n\r\n<h3>Alessandro Gagliardi, Responsabile Vendite, EAM APAC, Africa orientale e sub-sahariana<\/h3>\r\n\r\nNel 2022, il mercato delle costruzioni sar\u00e0 principalmente focalizzato sulla sostenibilit\u00e0 (edifici a basso impatto energetico e riutilizzo dei materiali) e sulla digitalizzazione (BIM). L&#8217;attenzione al cambiamento climatico provocher\u00e0 un crescente interesse per gli edifici verdi (giardini pensili, facciate verdi) e la gestione sostenibile delle acque piovane per la prevenzione dalle inondazioni.\r\n\r\n<a href=\"mailto: alessandro.gagliardi@geoplastglobal.com\">alessandro.gagliardi@geoplastglobal.com<\/a>\r\nSegui Alessandro su <a href=\"https:\/\/www.linkedin.com\/in\/alessandro-gagliardi-0595862\/\" rel=\"noopener\" target=\"_blank\">LinkedIn<\/a>\r\n\r\n<h3>p.s. Buon anno!<\/h3>\r\n","protected":false},"excerpt":{"rendered":"<p>Mirco Pegoraro, CEO &#038; Product Designer Nel 2022 le problematiche sismiche passeranno in secondo piano a favore della sostenibilit\u00e0 che sar\u00e0 un tema predominante in tutti i settori delle costruzioni. I prodotti in plastica riciclata Geoplast saranno sempre pi\u00f9 richiesti dal mercato perch\u00e9 sono in grado di ridurre le emissioni [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":164131,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[40],"tags":[3519,3520,1573,3521,2755],"class_list":["post-164130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novita","tag-2022-it","tag-construction-industry-it","tag-geoplast-it","tag-industria-di-costruzioni","tag-redditivita-sostenibile"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le nostre previsioni sulle tendenze edilizie del 2022 &#8211; Geoplast<\/title>\n<meta name=\"description\" content=\"2021 was a busy year that gave us important insights into construction industry trends. Here are our team\u2019s 2022 predictions\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le nostre previsioni sulle tendenze edilizie del 2022 &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"2021 was a busy year that gave us important insights into construction industry trends. Here are our team\u2019s 2022 predictions\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/it\/blog\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-30T05:23:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-19T14:15:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/12\/Il-2022-e-lanno-della-redditivita-sostenibile.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jelena Zivancevic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jelena Zivancevic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\\\/\"},\"author\":{\"name\":\"Jelena Zivancevic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\"},\"headline\":\"Le nostre previsioni sulle tendenze edilizie del 2022\",\"datePublished\":\"2021-12-30T05:23:52+00:00\",\"dateModified\":\"2025-06-19T14:15:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\\\/\"},\"wordCount\":695,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Il-2022-e-lanno-della-redditivita-sostenibile.jpg\",\"keywords\":[\"2022\",\"Construction industry\",\"Geoplast\",\"Industria di costruzioni\",\"Redditivit\u00e0 Sostenibile\"],\"articleSection\":[\"Novit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\\\/\",\"name\":\"Le nostre previsioni sulle tendenze edilizie del 2022 &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Il-2022-e-lanno-della-redditivita-sostenibile.jpg\",\"datePublished\":\"2021-12-30T05:23:52+00:00\",\"dateModified\":\"2025-06-19T14:15:55+00:00\",\"description\":\"2021 was a busy year that gave us important insights into construction industry trends. Here are our team\u2019s 2022 predictions\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Il-2022-e-lanno-della-redditivita-sostenibile.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Il-2022-e-lanno-della-redditivita-sostenibile.jpg\",\"width\":1240,\"height\":500,\"caption\":\"Il 2022 \u00e8 l'anno della redditivit\u00e0 sostenibile\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\",\"name\":\"Jelena Zivancevic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"caption\":\"Jelena Zivancevic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le nostre previsioni sulle tendenze edilizie del 2022 &#8211; Geoplast","description":"2021 was a busy year that gave us important insights into construction industry trends. Here are our team\u2019s 2022 predictions","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/it\/blog\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\/","og_locale":"it_IT","og_type":"article","og_title":"Le nostre previsioni sulle tendenze edilizie del 2022 &#8211; Geoplast","og_description":"2021 was a busy year that gave us important insights into construction industry trends. Here are our team\u2019s 2022 predictions","og_url":"https:\/\/www.geoplastglobal.com\/it\/blog\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2021-12-30T05:23:52+00:00","article_modified_time":"2025-06-19T14:15:55+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/12\/Il-2022-e-lanno-della-redditivita-sostenibile.jpg","type":"image\/jpeg"}],"author":"Jelena Zivancevic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Jelena Zivancevic","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\/"},"author":{"name":"Jelena Zivancevic","@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad"},"headline":"Le nostre previsioni sulle tendenze edilizie del 2022","datePublished":"2021-12-30T05:23:52+00:00","dateModified":"2025-06-19T14:15:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\/"},"wordCount":695,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/12\/Il-2022-e-lanno-della-redditivita-sostenibile.jpg","keywords":["2022","Construction industry","Geoplast","Industria di costruzioni","Redditivit\u00e0 Sostenibile"],"articleSection":["Novit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\/","url":"https:\/\/www.geoplastglobal.com\/it\/blog\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\/","name":"Le nostre previsioni sulle tendenze edilizie del 2022 &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/12\/Il-2022-e-lanno-della-redditivita-sostenibile.jpg","datePublished":"2021-12-30T05:23:52+00:00","dateModified":"2025-06-19T14:15:55+00:00","description":"2021 was a busy year that gave us important insights into construction industry trends. Here are our team\u2019s 2022 predictions","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/it\/blog\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/le-nostre-previsioni-sulle-tendenze-edilizie-del-2022\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/12\/Il-2022-e-lanno-della-redditivita-sostenibile.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/12\/Il-2022-e-lanno-della-redditivita-sostenibile.jpg","width":1240,"height":500,"caption":"Il 2022 \u00e8 l'anno della redditivit\u00e0 sostenibile"},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/it\/#website","url":"https:\/\/www.geoplastglobal.com\/it\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/it\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad","name":"Jelena Zivancevic","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","caption":"Jelena Zivancevic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts\/164130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/comments?post=164130"}],"version-history":[{"count":1,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts\/164130\/revisions"}],"predecessor-version":[{"id":164142,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts\/164130\/revisions\/164142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/media\/164131"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/media?parent=164130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/categories?post=164130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/tags?post=164130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}