
{"id":163760,"date":"2021-12-23T05:18:15","date_gmt":"2021-12-23T05:18:15","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/?p=163760"},"modified":"2026-05-07T07:42:36","modified_gmt":"2026-05-07T07:42:36","slug":"buon-natale-e-felice-anno-nuovo-da-geoplast","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/it\/blog\/buon-natale-e-felice-anno-nuovo-da-geoplast\/","title":{"rendered":"Buon Natale e Felice Anno Nuovo da Geoplast"},"content":{"rendered":"Vi vogliamo augurare un Buon Natale e tutto il meglio per l\u2019anno nuovo!\r\n\r\nCi auguriamo inoltre che non abbiate tagliato un albero vero ma che ne abbiate utilizzato uno in plastica riciclata. \ud83d\ude42\r\n\r\nLa deforestazione \u00e8 responsabile del <a href=\"https:\/\/www.nationalgeographic.com\/environment\/article\/deforestation\" target=\"_blank\" rel=\"noopener\">23 %<\/a> delle emissioni globali di gas serra. Il riciclaggio della plastica <a href=\"https:\/\/medium.com\/@catchfoundationngo\/top-10-benefits-of-recycling-plastic-63de62075ceb\" target=\"_blank\" rel=\"noopener\">avvantaggia<\/a> l&#8217;ambiente riducendo l&#8217;uso di combustibili fossili, diminuendo i rifiuti in discarica e conservando le risorse naturali.\r\n\r\nGrazie per il vostro continuo supporto, non vediamo l&#8217;ora di lavorare con voi anche nei prossimi anni.\r\n\r\nDa parte di tutte le persone in Geoplast","protected":false},"excerpt":{"rendered":"<p>Vi vogliamo augurare un Buon Natale e tutto il meglio per l\u2019anno nuovo! Ci auguriamo inoltre che non abbiate tagliato un albero vero ma che ne abbiate utilizzato uno in plastica riciclata. \ud83d\ude42 La deforestazione \u00e8 responsabile del 23 % delle emissioni globali di gas serra. Il riciclaggio della plastica [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":163761,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2871],"tags":[3498,3499,3459],"class_list":["post-163760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-redditivita-sostenibile","tag-buon-natale","tag-felice-anno-nuovo","tag-plastica-riciclata"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Buon Natale e Felice Anno Nuovo da Geoplast &#8211; Geoplast<\/title>\n<meta name=\"description\" content=\"Buon Natale da Geoplast e un in bocca al lupo per il nuovo anno! Speriamo che quest&#039;anno abbiate usato un albero in plastica riciclata.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/buon-natale-e-felice-anno-nuovo-da-geoplast\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buon Natale e Felice Anno Nuovo da Geoplast &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Buon Natale da Geoplast e un in bocca al lupo per il nuovo anno! Speriamo che quest&#039;anno abbiate usato un albero in plastica riciclata.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/it\/blog\/buon-natale-e-felice-anno-nuovo-da-geoplast\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-23T05:18:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T07:42:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/12\/Geoplast-blog-Buon-Natale-e-Felice-Anno-Nuovo-da-Geoplast.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jelena Zivancevic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jelena Zivancevic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/buon-natale-e-felice-anno-nuovo-da-geoplast\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/buon-natale-e-felice-anno-nuovo-da-geoplast\\\/\"},\"author\":{\"name\":\"Jelena Zivancevic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\"},\"headline\":\"Buon Natale e Felice Anno Nuovo da Geoplast\",\"datePublished\":\"2021-12-23T05:18:15+00:00\",\"dateModified\":\"2026-05-07T07:42:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/buon-natale-e-felice-anno-nuovo-da-geoplast\\\/\"},\"wordCount\":100,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/buon-natale-e-felice-anno-nuovo-da-geoplast\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Geoplast-blog-Buon-Natale-e-Felice-Anno-Nuovo-da-Geoplast.jpg\",\"keywords\":[\"Buon Natale\",\"Felice Anno Nuovo\",\"plastica riciclata\"],\"articleSection\":[\"Redditivit\u00e0 Sostenibile\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/buon-natale-e-felice-anno-nuovo-da-geoplast\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/buon-natale-e-felice-anno-nuovo-da-geoplast\\\/\",\"name\":\"Buon Natale e Felice Anno Nuovo da Geoplast &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/buon-natale-e-felice-anno-nuovo-da-geoplast\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/buon-natale-e-felice-anno-nuovo-da-geoplast\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Geoplast-blog-Buon-Natale-e-Felice-Anno-Nuovo-da-Geoplast.jpg\",\"datePublished\":\"2021-12-23T05:18:15+00:00\",\"dateModified\":\"2026-05-07T07:42:36+00:00\",\"description\":\"Buon Natale da Geoplast e un in bocca al lupo per il nuovo anno! Speriamo che quest'anno abbiate usato un albero in plastica riciclata.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/buon-natale-e-felice-anno-nuovo-da-geoplast\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/buon-natale-e-felice-anno-nuovo-da-geoplast\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Geoplast-blog-Buon-Natale-e-Felice-Anno-Nuovo-da-Geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Geoplast-blog-Buon-Natale-e-Felice-Anno-Nuovo-da-Geoplast.jpg\",\"width\":1240,\"height\":500,\"caption\":\"Geoplast blog Buon Natale e Felice Anno Nuovo da Geoplast\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\",\"name\":\"Jelena Zivancevic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"caption\":\"Jelena Zivancevic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Buon Natale e Felice Anno Nuovo da Geoplast &#8211; Geoplast","description":"Buon Natale da Geoplast e un in bocca al lupo per il nuovo anno! Speriamo che quest'anno abbiate usato un albero in plastica riciclata.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/it\/blog\/buon-natale-e-felice-anno-nuovo-da-geoplast\/","og_locale":"it_IT","og_type":"article","og_title":"Buon Natale e Felice Anno Nuovo da Geoplast &#8211; Geoplast","og_description":"Buon Natale da Geoplast e un in bocca al lupo per il nuovo anno! Speriamo che quest'anno abbiate usato un albero in plastica riciclata.","og_url":"https:\/\/www.geoplastglobal.com\/it\/blog\/buon-natale-e-felice-anno-nuovo-da-geoplast\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2021-12-23T05:18:15+00:00","article_modified_time":"2026-05-07T07:42:36+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/12\/Geoplast-blog-Buon-Natale-e-Felice-Anno-Nuovo-da-Geoplast.jpg","type":"image\/jpeg"}],"author":"Jelena Zivancevic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Jelena Zivancevic","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/buon-natale-e-felice-anno-nuovo-da-geoplast\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/buon-natale-e-felice-anno-nuovo-da-geoplast\/"},"author":{"name":"Jelena Zivancevic","@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad"},"headline":"Buon Natale e Felice Anno Nuovo da Geoplast","datePublished":"2021-12-23T05:18:15+00:00","dateModified":"2026-05-07T07:42:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/buon-natale-e-felice-anno-nuovo-da-geoplast\/"},"wordCount":100,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/buon-natale-e-felice-anno-nuovo-da-geoplast\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/12\/Geoplast-blog-Buon-Natale-e-Felice-Anno-Nuovo-da-Geoplast.jpg","keywords":["Buon Natale","Felice Anno Nuovo","plastica riciclata"],"articleSection":["Redditivit\u00e0 Sostenibile"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/buon-natale-e-felice-anno-nuovo-da-geoplast\/","url":"https:\/\/www.geoplastglobal.com\/it\/blog\/buon-natale-e-felice-anno-nuovo-da-geoplast\/","name":"Buon Natale e Felice Anno Nuovo da Geoplast &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/buon-natale-e-felice-anno-nuovo-da-geoplast\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/buon-natale-e-felice-anno-nuovo-da-geoplast\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/12\/Geoplast-blog-Buon-Natale-e-Felice-Anno-Nuovo-da-Geoplast.jpg","datePublished":"2021-12-23T05:18:15+00:00","dateModified":"2026-05-07T07:42:36+00:00","description":"Buon Natale da Geoplast e un in bocca al lupo per il nuovo anno! Speriamo che quest'anno abbiate usato un albero in plastica riciclata.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/it\/blog\/buon-natale-e-felice-anno-nuovo-da-geoplast\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/buon-natale-e-felice-anno-nuovo-da-geoplast\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/12\/Geoplast-blog-Buon-Natale-e-Felice-Anno-Nuovo-da-Geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/12\/Geoplast-blog-Buon-Natale-e-Felice-Anno-Nuovo-da-Geoplast.jpg","width":1240,"height":500,"caption":"Geoplast blog Buon Natale e Felice Anno Nuovo da Geoplast"},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/it\/#website","url":"https:\/\/www.geoplastglobal.com\/it\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/it\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad","name":"Jelena Zivancevic","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","caption":"Jelena Zivancevic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts\/163760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/comments?post=163760"}],"version-history":[{"count":3,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts\/163760\/revisions"}],"predecessor-version":[{"id":163828,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts\/163760\/revisions\/163828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/media\/163761"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/media?parent=163760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/categories?post=163760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/tags?post=163760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}