
{"id":143571,"date":"2021-01-06T14:19:43","date_gmt":"2021-01-06T14:19:43","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/blog\/our-2020-favorite-posts\/"},"modified":"2021-03-12T11:57:49","modified_gmt":"2021-03-12T11:57:49","slug":"i-nostri-post-preferiti-mese-per-mese-nel-2020","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/it\/blog\/i-nostri-post-preferiti-mese-per-mese-nel-2020\/","title":{"rendered":"I nostri post preferiti mese per mese nel 2020"},"content":{"rendered":"Il 2020 \u00e8 stato un anno diverso in cui abbiamo fatto del nostro meglio per rimanere fedeli alla nostra visione e ai nostri clienti. I nostri articoli preferiti mese per mese raccontano la nostra storia del 2020:\r\n\r\n<h2>Gennaio 2020<\/h2>\t\r\n<a href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/5-esempi-di-progetti-sostenibili-e-redditizi\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" style=\"max-width: 50%;\" src=\"\/wp-content\/uploads\/2020\/01\/Marmara.jpg\" alt=\"\" \/><p style=\"font-size: 1.2em;\">5 esempi di progetti sostenibili e redditizi<\/p><\/a>\r\n\r\n<h2>Febbraio 2020<\/h2>\t\r\n<a href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/informazioni-su-costruzioni-ingegneria-e-architettura-con-geoplastglobal-com-risorse\/\" rel=\"noopener\" target=\"_blank\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/01\/Resources-IT.jpg\" alt=\"\" style=\"max-width: 50%;\" \/><p style=\"font-size: 1.2em;\">Informazioni su costruzioni, ingegneria e architettura con GeoplastGlobal.com Risorse<\/p><\/a>\r\n\r\n<h2>Marzo 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/i-progetti-di-costruzione-sono-piu-redditizi-con-le-fondazioni-di-geoplast\/\" rel=\"noopener\" target=\"_blank\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2020\/03\/Modulo-construction-site-Symbiosis-Milan.jpg\" alt=\"\" style=\"max-width: 50%;\" \/><p style=\"font-size: 1.2em;\">I progetti di costruzione sono pi\u00f9 redditizi con le Fondazioni di Geoplast<\/p><\/a>\r\n\r\n<h2>Aprile 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/il-risparmio-sui-costi-e-la-redditivita-nelledilizia-diventeranno-piu-importanti-dopo-la-crisi-del-coronavirus\/\" rel=\"noopener\" target=\"_blank\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2020\/01\/Completa-Despar.jpg\" alt=\"\" style=\"max-width: 50%;\" \/><p style=\"font-size: 1.2em;\">Il risparmio sui costi e la redditivit\u00e0 nell\u2019edilizia diventeranno pi\u00f9 importanti dopo la crisi del Coronavirus<\/p><\/a>\r\n\r\n<h2>Maggio 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/5-nuovi-progetti-lean-redditizi-e-sostenibili-di-geoplast\/\" rel=\"noopener\" target=\"_blank\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2020\/05\/all-5-us-projects-2.jpg\" alt=\"\" style=\"max-width: 50%;\" \/><p style=\"font-size: 1.2em;\">5 nuovi progetti lean, redditizi e sostenibili di Geoplast<\/p><\/a>\r\n\r\n<h2>Giugno 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/i-nostri-ultimi-progetti-di-casseforme-e-fondazioni\/\" rel=\"noopener\" target=\"_blank\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2020\/06\/Legoland-1.jpg\" alt=\"\" style=\"max-width: 50%;\" \/><p style=\"font-size: 1.2em;\">I nostri ultimi progetti di Casseforme e Fondazioni<\/p><\/a>\r\n\r\n<h2>Luglio 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/aquabox-il-nuovo-prodotto-geoplast-per-la-gestione-delle-acque-meteoriche-che-migliora-la-redditivita-e-la-resilienza\/\" rel=\"noopener\" target=\"_blank\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2020\/07\/Aquabox-Cover.jpg\" alt=\"\" style=\"max-width: 50%;\" \/><p style=\"font-size: 1.2em;\">Aquabox \u2013 Il nuovo prodotto Geoplast per la gestione delle acque meteoriche che migliora la redditivit\u00e0 e la resilienza<\/p><\/a>\r\n\r\n<h2>Agosto 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/aquabox-e-3-volte-piu-performante-della-ghiaia\/\" rel=\"noopener\" target=\"_blank\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/01\/Aquabox-vs-Gravel-cover.jpg\" alt=\"\" style=\"max-width: 50%;\" \/><p style=\"font-size: 1.2em;\">Aquabox \u00e8 3 volte pi\u00f9 performante della ghiaia<\/p><\/a>\r\n\r\n<h2>Settembre 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/100-modi-per-realizzare-progetti-di-costruzione-migliori\/\" rel=\"noopener\" target=\"_blank\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/01\/100-WAYS-4-IT.jpg\" alt=\"\" style=\"max-width: 50%;\" \/><p style=\"font-size: 1.2em;\">100 modi per realizzare progetti di costruzione migliori<\/p><\/a>\r\n\r\n<h2>Ottobre 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/i-3-metodi-migliori-per-lammodernamento-sostenibile-degli-edifici-esistenti\/\" rel=\"noopener\" target=\"_blank\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/01\/craighouse-1.png\" alt=\"\" style=\"max-width: 50%;\" \/><p style=\"font-size: 1.2em;\">I 3 metodi migliori per l\u2019ammodernamento sostenibile degli edifici esistenti<\/p><\/a>\r\n\r\n<h2>Novembre 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/video-delle-facili-installazioni-di-casseforme-geopanel-geotub-geopanel-star\/\" rel=\"noopener\" target=\"_blank\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2020\/11\/FORMWORK-VIDEOS.jpg\" alt=\"\" style=\"max-width: 50%;\" \/><p style=\"font-size: 1.2em;\">Video delle facili installazioni di casseforme Geopanel, Geotub, Geopanel Star<\/p><\/a>\r\n\r\n<h2>Dicembre 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/le-nostre-previsioni-per-il-2021\/\" rel=\"noopener\" target=\"_blank\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/01\/Geoplast-2021-Blog-Post-IT-1.jpg\" alt=\"\" style=\"max-width: 50%;\" \/><p style=\"font-size: 1.2em;\">Le nostre previsioni per il 2021<\/p><\/a>","protected":false},"excerpt":{"rendered":"<p>Il 2020 \u00e8 stato un anno diverso in cui abbiamo fatto del nostro meglio per rimanere fedeli alla nostra visione e ai nostri clienti. I nostri articoli preferiti mese per mese raccontano la nostra storia del 2020: Gennaio 2020 5 esempi di progetti sostenibili e redditizi Febbraio 2020 Informazioni su [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":143573,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4859,40],"tags":[3109,3111],"class_list":["post-143571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-about-us-it","category-novita","tag-2020-it","tag-visione"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I nostri post preferiti mese per mese nel 2020 &#8211; Geoplast<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/it\/blog\/i-nostri-post-preferiti-mese-per-mese-nel-2020\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I nostri post preferiti mese per mese nel 2020 &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Il 2020 \u00e8 stato un anno diverso in cui abbiamo fatto del nostro meglio per rimanere fedeli alla nostra visione e ai nostri clienti. I nostri articoli preferiti mese per mese raccontano la nostra storia del 2020: Gennaio 2020 5 esempi di progetti sostenibili e redditizi Febbraio 2020 Informazioni su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/it\/blog\/i-nostri-post-preferiti-mese-per-mese-nel-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-06T14:19:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-12T11:57:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/01\/2020-geoplast-italian.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jelena Zivancevic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jelena Zivancevic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/i-nostri-post-preferiti-mese-per-mese-nel-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/i-nostri-post-preferiti-mese-per-mese-nel-2020\\\/\"},\"author\":{\"name\":\"Jelena Zivancevic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\"},\"headline\":\"I nostri post preferiti mese per mese nel 2020\",\"datePublished\":\"2021-01-06T14:19:43+00:00\",\"dateModified\":\"2021-03-12T11:57:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/i-nostri-post-preferiti-mese-per-mese-nel-2020\\\/\"},\"wordCount\":171,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/i-nostri-post-preferiti-mese-per-mese-nel-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/2020-geoplast-italian.jpg\",\"keywords\":[\"2020\",\"visione\"],\"articleSection\":[\"Chi siamo\",\"Novit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/i-nostri-post-preferiti-mese-per-mese-nel-2020\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/i-nostri-post-preferiti-mese-per-mese-nel-2020\\\/\",\"name\":\"I nostri post preferiti mese per mese nel 2020 &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/i-nostri-post-preferiti-mese-per-mese-nel-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/i-nostri-post-preferiti-mese-per-mese-nel-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/2020-geoplast-italian.jpg\",\"datePublished\":\"2021-01-06T14:19:43+00:00\",\"dateModified\":\"2021-03-12T11:57:49+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/i-nostri-post-preferiti-mese-per-mese-nel-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/blog\\\/i-nostri-post-preferiti-mese-per-mese-nel-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/2020-geoplast-italian.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/2020-geoplast-italian.jpg\",\"width\":1240,\"height\":500},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/it\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\",\"name\":\"Jelena Zivancevic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"caption\":\"Jelena Zivancevic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I nostri post preferiti mese per mese nel 2020 &#8211; Geoplast","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/it\/blog\/i-nostri-post-preferiti-mese-per-mese-nel-2020\/","og_locale":"it_IT","og_type":"article","og_title":"I nostri post preferiti mese per mese nel 2020 &#8211; Geoplast","og_description":"Il 2020 \u00e8 stato un anno diverso in cui abbiamo fatto del nostro meglio per rimanere fedeli alla nostra visione e ai nostri clienti. I nostri articoli preferiti mese per mese raccontano la nostra storia del 2020: Gennaio 2020 5 esempi di progetti sostenibili e redditizi Febbraio 2020 Informazioni su [&hellip;]","og_url":"https:\/\/www.geoplastglobal.com\/it\/blog\/i-nostri-post-preferiti-mese-per-mese-nel-2020\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2021-01-06T14:19:43+00:00","article_modified_time":"2021-03-12T11:57:49+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/01\/2020-geoplast-italian.jpg","type":"image\/jpeg"}],"author":"Jelena Zivancevic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Jelena Zivancevic","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/i-nostri-post-preferiti-mese-per-mese-nel-2020\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/i-nostri-post-preferiti-mese-per-mese-nel-2020\/"},"author":{"name":"Jelena Zivancevic","@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad"},"headline":"I nostri post preferiti mese per mese nel 2020","datePublished":"2021-01-06T14:19:43+00:00","dateModified":"2021-03-12T11:57:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/i-nostri-post-preferiti-mese-per-mese-nel-2020\/"},"wordCount":171,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/i-nostri-post-preferiti-mese-per-mese-nel-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/01\/2020-geoplast-italian.jpg","keywords":["2020","visione"],"articleSection":["Chi siamo","Novit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/i-nostri-post-preferiti-mese-per-mese-nel-2020\/","url":"https:\/\/www.geoplastglobal.com\/it\/blog\/i-nostri-post-preferiti-mese-per-mese-nel-2020\/","name":"I nostri post preferiti mese per mese nel 2020 &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/i-nostri-post-preferiti-mese-per-mese-nel-2020\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/i-nostri-post-preferiti-mese-per-mese-nel-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/01\/2020-geoplast-italian.jpg","datePublished":"2021-01-06T14:19:43+00:00","dateModified":"2021-03-12T11:57:49+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/it\/blog\/i-nostri-post-preferiti-mese-per-mese-nel-2020\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.geoplastglobal.com\/it\/blog\/i-nostri-post-preferiti-mese-per-mese-nel-2020\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/01\/2020-geoplast-italian.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/01\/2020-geoplast-italian.jpg","width":1240,"height":500},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/it\/#website","url":"https:\/\/www.geoplastglobal.com\/it\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/it\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/it\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad","name":"Jelena Zivancevic","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","caption":"Jelena Zivancevic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts\/143571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/comments?post=143571"}],"version-history":[{"count":7,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts\/143571\/revisions"}],"predecessor-version":[{"id":143621,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/posts\/143571\/revisions\/143621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/media\/143573"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/media?parent=143571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/categories?post=143571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/it\/wp-json\/wp\/v2\/tags?post=143571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}