
{"id":65289,"date":"2018-03-01T15:17:17","date_gmt":"2018-03-01T15:17:17","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/?p=65289"},"modified":"2022-11-22T11:09:51","modified_gmt":"2022-11-22T11:09:51","slug":"runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/fr\/blog\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\/","title":{"rendered":"Runfloor pour l&rsquo;am\u00e9nagement de parkings en gravier: \u00e9tude de cas Grimsby"},"content":{"rendered":"<a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/vert\/runfloor\/\" target=\"_blank\" rel=\"noopener\">Runfloor<\/a>, dalle \u00e0 haute performance pour surfaces carrossables p\u00e9rmeables, peut \u00e9galement \u00eatre utilis\u00e9e pour la cr\u00e9ation de <strong>parkings en gravier<\/strong>.\r\n\r\nSes principaux avantages sont:\r\n<ul>\r\n \t<li>La<strong> r\u00e9sistance \u00e0 la compression<\/strong>: \u00e9gale \u00e0<strong> 500 tonnes \/ m2<\/strong>;<\/li>\r\n \t<li>Les excellentes caract\u00e9ristiques de <strong>drainage<\/strong>, avec une <strong>perm\u00e9abilit\u00e9 jusqu&rsquo; \u00e0 85%<\/strong>;<\/li>\r\n \t<li>L&rsquo;installation extr\u00eamement <strong>facile<\/strong>, gr\u00e2ce \u00e0 la fermeture \u00e0 ba\u00efonnette<\/li>\r\n<\/ul>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/vert\/runfloor\/\" target=\"_blank\" rel=\"noopener\">Runfloor<\/a> est id\u00e9al pour les parkings ou les zones de transit. En effet, gr\u00e2ce \u00e0 sa structure renforc\u00e9e, il offre une grande r\u00e9sistance aux contraintes li\u00e9es au passage des voitures ou \u00e0 tout autre moyen. La g\u00e9om\u00e9trie particuli\u00e8re des cellules offre en effet une capacit\u00e9 portante sup\u00e9rieure \u00e0 celle d&rsquo;autres syst\u00e8mes traditionnels. De plus, la grille est fabriqu\u00e9e en poly\u00e9thyl\u00e8ne basse densit\u00e9, ce qui garantit g\u00e9n\u00e9ralement des performances plus \u00e9lev\u00e9es, m\u00eame \u00e0 tr\u00e8s basse temp\u00e9rature.\r\n<h3><strong>Runfloor pour l&rsquo;agrandissement d&rsquo;un parking dans une zone industrielle, \u00e0 Grimsby, Royaume-Uni\r\n<\/strong><\/h3>\r\nR\u00e9cemment, notre distributeur anglais <a href=\"https:\/\/www.sure-green.com\/\" target=\"_blank\" rel=\"noopener\">Sure Green<\/a> a utilis\u00e9 <a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/vert\/runfloor\/\" target=\"_blank\" rel=\"noopener\">Runfloor<\/a> pour la cr\u00e9ation d&rsquo;un parking \u00e0 usage quotidien \u00e0 <strong>Grimsby<\/strong>, <strong>au Royaume-Uni<\/strong>.\r\n\r\nLe parking a \u00e9t\u00e9 cr\u00e9\u00e9 \u00e0 l&rsquo;ext\u00e9rieur de Survitec, une entreprise en expansion situ\u00e9e dans une zone industrielle tr\u00e8s fr\u00e9quent\u00e9e, o\u00f9 le <strong>manque de places disponibles<\/strong> s&rsquo;est av\u00e9r\u00e9 un probl\u00e8me important. L&rsquo;entreprise avait besoin d&rsquo;une solution qui permettait un parking de tous les jours, dans toutes les conditions m\u00e9t\u00e9orologiques, rentable et drainant en fonction des conditions de planification requises.\r\n\r\n&nbsp;\r\n\r\n<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-66667 size-full aligncenter\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2018\/03\/Runfloor_2.jpg\" alt=\"\" width=\"1240\" height=\"500\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2018\/03\/Runfloor_2.jpg 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2018\/03\/Runfloor_2-300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2018\/03\/Runfloor_2-768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2018\/03\/Runfloor_2-1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2018\/03\/Runfloor_2-224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2018\/03\/Runfloor_2-124x50.jpg 124w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n\r\n&nbsp;\r\n\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/vert\/runfloor\/\" target=\"_blank\" rel=\"noopener\">Runfloor<\/a> a \u00e9t\u00e9 choisi parce qu&rsquo;il pouvait parfaitement r\u00e9pondre \u00e0 toutes ces exigences. Dans ce cas, il s&rsquo;agissait d&rsquo;un gravier mixte de granulom\u00e9trie angulaire, aussi bien pour la liti\u00e8re que pour le remplissage des grilles.\r\n\r\nL&rsquo;entreprise dispose d\u00e9sormais d&rsquo;un parking qui peut \u00eatre utilis\u00e9 toute l&rsquo;ann\u00e9e. Il est enti\u00e8rement autovideur, conforme aux derni\u00e8res exigences en mati\u00e8re de drainage urbain durable (SUDS) et les co\u00fbts globaux ont \u00e9t\u00e9 r\u00e9duits en raison de l&rsquo;absence de d\u00e9penses suppl\u00e9mentaires pour le drainage par trop-plein\r\n\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/les-solutions\/vert\/\" target=\"_blank\" rel=\"noopener\">En savoir plus sur les Solutions pour le Vert Geoplast<\/a>\r\n\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/projects\/runfloor-pour-lamnagement-de-parkings-en-gravier-tude-de-cas-grimsby\" target=\"_blank\" rel=\"noopener\">En savoir plus sur le projet<\/a>","protected":false},"excerpt":{"rendered":"<p>Runfloor, dalle \u00e0 haute performance pour surfaces carrossables p\u00e9rmeables, peut \u00e9galement \u00eatre utilis\u00e9e pour la cr\u00e9ation de parkings en gravier. Ses principaux avantages sont: La r\u00e9sistance \u00e0 la compression: \u00e9gale \u00e0 500 tonnes \/ m2; Les excellentes caract\u00e9ristiques de drainage, avec une perm\u00e9abilit\u00e9 jusqu&rsquo; \u00e0 85%; L&rsquo;installation extr\u00eamement facile, gr\u00e2ce [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":66660,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[72,77],"tags":[562,561,1896,1671],"class_list":["post-65289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projets-fr","category-vert","tag-parkings-drainants","tag-parkings-en-gravier","tag-runfloor-fr","tag-solutions-vertes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Runfloor pour l&#039;am\u00e9nagement de parkings en gravier: \u00e9tude de cas Grimsby &#8211; Geoplast<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Runfloor pour l&#039;am\u00e9nagement de parkings en gravier: \u00e9tude de cas Grimsby &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Runfloor, dalle \u00e0 haute performance pour surfaces carrossables p\u00e9rmeables, peut \u00e9galement \u00eatre utilis\u00e9e pour la cr\u00e9ation de parkings en gravier. Ses principaux avantages sont: La r\u00e9sistance \u00e0 la compression: \u00e9gale \u00e0 500 tonnes \/ m2; Les excellentes caract\u00e9ristiques de drainage, avec une perm\u00e9abilit\u00e9 jusqu&rsquo; \u00e0 85%; L&rsquo;installation extr\u00eamement facile, gr\u00e2ce [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-01T15:17:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-22T11:09:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2018\/03\/Runfloor_Green.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nikola Tosic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nikola Tosic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\\\/\"},\"author\":{\"name\":\"Nikola Tosic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/person\\\/0feabc79985006722a394123a98c8065\"},\"headline\":\"Runfloor pour l&rsquo;am\u00e9nagement de parkings en gravier: \u00e9tude de cas Grimsby\",\"datePublished\":\"2018-03-01T15:17:17+00:00\",\"dateModified\":\"2022-11-22T11:09:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\\\/\"},\"wordCount\":382,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Runfloor_Green.jpg\",\"keywords\":[\"Parkings drainants\",\"Parkings en gravier\",\"Runfloor\",\"Solutions vertes\"],\"articleSection\":[\"Projets\",\"Vert\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\\\/\",\"name\":\"Runfloor pour l'am\u00e9nagement de parkings en gravier: \u00e9tude de cas Grimsby &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Runfloor_Green.jpg\",\"datePublished\":\"2018-03-01T15:17:17+00:00\",\"dateModified\":\"2022-11-22T11:09:51+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Runfloor_Green.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Runfloor_Green.jpg\",\"width\":1240,\"height\":500},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/person\\\/0feabc79985006722a394123a98c8065\",\"name\":\"Nikola Tosic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g\",\"caption\":\"Nikola Tosic\"},\"sameAs\":[\"https:\\\/\\\/www.geoplastglobal.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Runfloor pour l'am\u00e9nagement de parkings en gravier: \u00e9tude de cas Grimsby &#8211; Geoplast","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/fr\/blog\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\/","og_locale":"fr_FR","og_type":"article","og_title":"Runfloor pour l'am\u00e9nagement de parkings en gravier: \u00e9tude de cas Grimsby &#8211; Geoplast","og_description":"Runfloor, dalle \u00e0 haute performance pour surfaces carrossables p\u00e9rmeables, peut \u00e9galement \u00eatre utilis\u00e9e pour la cr\u00e9ation de parkings en gravier. Ses principaux avantages sont: La r\u00e9sistance \u00e0 la compression: \u00e9gale \u00e0 500 tonnes \/ m2; Les excellentes caract\u00e9ristiques de drainage, avec une perm\u00e9abilit\u00e9 jusqu&rsquo; \u00e0 85%; L&rsquo;installation extr\u00eamement facile, gr\u00e2ce [&hellip;]","og_url":"https:\/\/www.geoplastglobal.com\/fr\/blog\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2018-03-01T15:17:17+00:00","article_modified_time":"2022-11-22T11:09:51+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2018\/03\/Runfloor_Green.jpg","type":"image\/jpeg"}],"author":"Nikola Tosic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Nikola Tosic","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\/"},"author":{"name":"Nikola Tosic","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/person\/0feabc79985006722a394123a98c8065"},"headline":"Runfloor pour l&rsquo;am\u00e9nagement de parkings en gravier: \u00e9tude de cas Grimsby","datePublished":"2018-03-01T15:17:17+00:00","dateModified":"2022-11-22T11:09:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\/"},"wordCount":382,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2018\/03\/Runfloor_Green.jpg","keywords":["Parkings drainants","Parkings en gravier","Runfloor","Solutions vertes"],"articleSection":["Projets","Vert"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\/","url":"https:\/\/www.geoplastglobal.com\/fr\/blog\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\/","name":"Runfloor pour l'am\u00e9nagement de parkings en gravier: \u00e9tude de cas Grimsby &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2018\/03\/Runfloor_Green.jpg","datePublished":"2018-03-01T15:17:17+00:00","dateModified":"2022-11-22T11:09:51+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/fr\/blog\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/runfloor-pour-lamenagement-de-parkings-en-gravier-etude-de-cas-grimsby\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2018\/03\/Runfloor_Green.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2018\/03\/Runfloor_Green.jpg","width":1240,"height":500},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/fr\/#website","url":"https:\/\/www.geoplastglobal.com\/fr\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/person\/0feabc79985006722a394123a98c8065","name":"Nikola Tosic","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g","caption":"Nikola Tosic"},"sameAs":["https:\/\/www.geoplastglobal.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/65289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/comments?post=65289"}],"version-history":[{"count":5,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/65289\/revisions"}],"predecessor-version":[{"id":67431,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/65289\/revisions\/67431"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/media\/66660"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/media?parent=65289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/categories?post=65289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/tags?post=65289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}