
{"id":189652,"date":"2023-12-20T14:18:54","date_gmt":"2023-12-20T14:18:54","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/?p=189652"},"modified":"2023-12-21T10:54:00","modified_gmt":"2023-12-21T10:54:00","slug":"nos-evenements-les-plus-marquants-de-2023","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/fr\/blog\/nos-evenements-les-plus-marquants-de-2023\/","title":{"rendered":"Nos \u00e9v\u00e9nements les plus marquants de 2023"},"content":{"rendered":"<style>\r\n.columns-wrapper.two-columns .column.column-1 {width: 33%;}\r\n.columns-wrapper.two-columns .column.column-2 {width: 66%;}\r\n@media screen and (max-width: 900px) {\r\n.columns-wrapper.two-columns .column {width: 50% !important;}\r\n}\r\n@media screen and (max-width: 768px) {\r\n.columns-wrapper.two-columns .column {\r\nwidth: 100% !important;\r\n}\r\n.column-2 {padding-left: 0px !important;}\r\n}\r\n.columns-wrapper:hover h2,.columns-wrapper:hover p {color: #f5842b !important;}\r\n<\/style>\r\n\r\nNous avons eu une ann\u00e9e 2023 charg\u00e9e et fructueuse qui nous a donn\u00e9 de nombreuses raisons de faire la f\u00eate. Nous  avons continu\u00e9 \u00e0 rendre davantage de projets durablement rentables, nous avons annonc\u00e9 de nouveaux produits et  certifications, remport\u00e9 une proc\u00e9dure de brevet et c\u00e9l\u00e9br\u00e9 le passage \u00e0 l\u2019\u00e2ge adulte de Geopanel. Vous trouverez ci dessous une s\u00e9lection de nos \u00e9v\u00e9nements les plus marquants de 2023. \r\n\r\n<div class=\"columns-wrapper two-columns\" style=\"padding-left:0px;\">\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/elevetor-max-le-plus-important-ajout-a-la-famille-elevetor\/\" target=\"_blank\" rel=\"noopener\">\r\n<div class=\"post-page column column-1\" style=\"padding-left:0px; margin-top:33px;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/FR-Elevetor-Max.jpg\" alt=\"Elevetor Max \u2013 le plus important ajout \u00e0 la famille Elevetor\" width=\"1240\" height=\"500\" class=\"alignnone size-full wp-image-179767\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/FR-Elevetor-Max.jpg 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/FR-Elevetor-Max-300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/FR-Elevetor-Max-1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/FR-Elevetor-Max-768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/FR-Elevetor-Max-224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/FR-Elevetor-Max-124x50.jpg 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/FR-Elevetor-Max-570x230.jpg 570w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n<\/div>\r\n<div class=\"column column-2\" style=\"padding-top:0px;\">\r\n<h2>Elevetor Max &#8211; le plus grand ajout \u00e0 la famille Elevator<\/h2>\r\n<p>Cette ann\u00e9e, nous avons lanc\u00e9 Elevator Max, qui propose 3 tailles de tubes suppl\u00e9mentaires et un coffrage sup\u00e9rieur  encore plus grand, pour une capacit\u00e9 de charge allant jusqu&rsquo;\u00e0 5 000 kg\/m2.<\/p>\r\n<\/div><\/a><\/div>\r\n\r\n\r\n<div class=\"post-page columns-wrapper two-columns\" style=\"padding-left:0px;\">\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/le-calculateur-nouveau-nautilus-evo-fem-est-disponible-en-ligne\/\" target=\"_blank\" rel=\"noopener\">\r\n<div class=\"column column-1\" style=\"padding-left:0px; margin-top:33px;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/07\/Le-calculateur-Nouveau-Nautilus-Evo-FEM-est-disponible-en-ligne.jpg\" alt=\"Le calculateur Nouveau Nautilus Evo FEM est disponible en ligne\" width=\"1240\" height=\"500\" class=\"alignnone size-full wp-image-184854\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/07\/Le-calculateur-Nouveau-Nautilus-Evo-FEM-est-disponible-en-ligne.jpg 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/07\/Le-calculateur-Nouveau-Nautilus-Evo-FEM-est-disponible-en-ligne-300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/07\/Le-calculateur-Nouveau-Nautilus-Evo-FEM-est-disponible-en-ligne-1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/07\/Le-calculateur-Nouveau-Nautilus-Evo-FEM-est-disponible-en-ligne-768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/07\/Le-calculateur-Nouveau-Nautilus-Evo-FEM-est-disponible-en-ligne-224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/07\/Le-calculateur-Nouveau-Nautilus-Evo-FEM-est-disponible-en-ligne-124x50.jpg 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/07\/Le-calculateur-Nouveau-Nautilus-Evo-FEM-est-disponible-en-ligne-570x230.jpg 570w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n<\/div>\r\n<div class=\"column column-2\" style=\"padding-top:0px;\">\r\n<h2>La calculatrice du Nouveau Nautilus Evo FEM est disponible en ligne<\/h2>\r\n<p>Nous avons publi\u00e9 un nouvel outil en ligne gratuit pour vous aider \u00e0 analyser les param\u00e8tres techniques des dalles  all\u00e9g\u00e9es fabriqu\u00e9es avec le Nouveau Nautilus Evo. <\/p>\r\n<\/div><\/a><\/div>\r\n\r\n\r\n<div class=\"post-page columns-wrapper two-columns\" style=\"padding-left:0px;\">\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/la-fabrication-de-geoplast-reduit-les-besoins-energetiques-de-30-grace-a-des-machines-entierement-electriques\/\" target=\"_blank\" rel=\"noopener\">\r\n<div class=\"column column-1\" style=\"padding-left:0px; margin-top:33px;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/08\/La-fabrication-de-Geoplast-reduit-les-besoins-energetiques-de-30-grace-a-des-machines-entierement-electriques-scaled.jpg\" alt=\"La fabrication de Geoplast r\u00e9duit les besoins \u00e9nerg\u00e9tiques de 30 % gr\u00e2ce \u00e0 des machines enti\u00e8rement \u00e9lectriques\" width=\"2560\" height=\"1033\" class=\"alignnone size-full wp-image-186109\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/08\/La-fabrication-de-Geoplast-reduit-les-besoins-energetiques-de-30-grace-a-des-machines-entierement-electriques-scaled.jpg 2560w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/08\/La-fabrication-de-Geoplast-reduit-les-besoins-energetiques-de-30-grace-a-des-machines-entierement-electriques-300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/08\/La-fabrication-de-Geoplast-reduit-les-besoins-energetiques-de-30-grace-a-des-machines-entierement-electriques-1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/08\/La-fabrication-de-Geoplast-reduit-les-besoins-energetiques-de-30-grace-a-des-machines-entierement-electriques-768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/08\/La-fabrication-de-Geoplast-reduit-les-besoins-energetiques-de-30-grace-a-des-machines-entierement-electriques-1536x620.jpg 1536w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/08\/La-fabrication-de-Geoplast-reduit-les-besoins-energetiques-de-30-grace-a-des-machines-entierement-electriques-2048x826.jpg 2048w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/08\/La-fabrication-de-Geoplast-reduit-les-besoins-energetiques-de-30-grace-a-des-machines-entierement-electriques-224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/08\/La-fabrication-de-Geoplast-reduit-les-besoins-energetiques-de-30-grace-a-des-machines-entierement-electriques-124x50.jpg 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/08\/La-fabrication-de-Geoplast-reduit-les-besoins-energetiques-de-30-grace-a-des-machines-entierement-electriques-570x230.jpg 570w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\r\n<\/div>\r\n<div class=\"column column-2\" style=\"padding-top:0px;\">\r\n<h2>La fabrication Geoplast r\u00e9duit les besoins \u00e9nerg\u00e9tiques de 30 %<\/h2>\r\n<p>Nous sommes fiers d&rsquo;avoir am\u00e9lior\u00e9 nos lignes de fabrication avec de nouvelles machines de moulage par injection pour  r\u00e9duire la consommation d&rsquo;\u00e9lectricit\u00e9 et augmenter la productivit\u00e9 et les \u00e9conomies de maintenance.<\/p>\r\n<\/div><\/a><\/div>\r\n\r\n\r\n<div class=\"post-page columns-wrapper two-columns\" style=\"padding-left:0px;\">\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/certificat-aquabox-cstb\/\" target=\"_blank\" rel=\"noopener\">\r\n<div class=\"column column-1\" style=\"padding-left:0px; margin-top:33px;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/09\/Certificat-Aquabox-CSTB.jpg\" alt=\"Certificat Aquabox CSTB\" width=\"1240\" height=\"500\" class=\"alignnone size-full wp-image-186864\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/09\/Certificat-Aquabox-CSTB.jpg 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/09\/Certificat-Aquabox-CSTB-300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/09\/Certificat-Aquabox-CSTB-1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/09\/Certificat-Aquabox-CSTB-768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/09\/Certificat-Aquabox-CSTB-224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/09\/Certificat-Aquabox-CSTB-124x50.jpg 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/09\/Certificat-Aquabox-CSTB-570x230.jpg 570w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n<\/div>\r\n<div class=\"column column-2\" style=\"padding-top:0px;\">\r\n<h2>Certificat Aquabox CSTB <\/h2>\r\n<p>Aquabox a satisfait aux exigences de la certification CSTB, \u00e0 la suite des tests de qualit\u00e9 approfondis effectu\u00e9s par des  laboratoires internationaux accr\u00e9dit\u00e9s selon les normes de l&rsquo;UE. <\/p>\r\n<\/div><\/a><\/div>\r\n\r\n\r\n<div class=\"post-page columns-wrapper two-columns\" style=\"padding-left:0px;\">\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/skynet-le-seul-coffrage-leger-de-remplissage-conforme-a-leurocode\/\" target=\"_blank\" rel=\"noopener\">\r\n<div class=\"column column-1\" style=\"padding-left:0px; margin-top:33px;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/Skynet-Le-seul-coffrage-leger-de-remplissage-conforme-a-lEurocode.jpg\" alt=\"Skynet - Le seul coffrage l\u00e9ger de remplissage conforme \u00e0 l\u2019Eurocode\" width=\"1240\" height=\"500\" class=\"alignnone size-full wp-image-180093\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/Skynet-Le-seul-coffrage-leger-de-remplissage-conforme-a-lEurocode.jpg 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/Skynet-Le-seul-coffrage-leger-de-remplissage-conforme-a-lEurocode-300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/Skynet-Le-seul-coffrage-leger-de-remplissage-conforme-a-lEurocode-1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/Skynet-Le-seul-coffrage-leger-de-remplissage-conforme-a-lEurocode-768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/Skynet-Le-seul-coffrage-leger-de-remplissage-conforme-a-lEurocode-224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/Skynet-Le-seul-coffrage-leger-de-remplissage-conforme-a-lEurocode-124x50.jpg 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/Skynet-Le-seul-coffrage-leger-de-remplissage-conforme-a-lEurocode-570x230.jpg 570w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n<\/div>\r\n<div class=\"column column-2\" style=\"padding-top:0px;\">\r\n<h2>Skynet &#8211; le seul coffrage de remplissage l\u00e9ger conforme \u00e0 l&rsquo;Eurocode <\/h2>\r\n<p>Skynet \u00e9tait notre nouveau coffrage de remplissage l\u00e9ger qui cr\u00e9e des dalles en b\u00e9ton nervur\u00e9es et des colonnes  porteuses \u00e9lev\u00e9es conformes aux codes internationaux. <\/p>\r\n<\/div><\/a><\/div>\r\n\r\n\r\n<div class=\"post-page columns-wrapper two-columns\" style=\"padding-left:0px;\">\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/joyeux-18eme-anniversaire-geopanel\/\" target=\"_blank\" rel=\"noopener\">\r\n<div class=\"column column-1\" style=\"padding-left:0px; margin-top:33px;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/10\/Joyeux-18eme-anniversaire-Geopanel.jpg\" alt=\"Joyeux 18\u00e8me anniversaire Geopanel!\" width=\"1240\" height=\"500\" class=\"alignnone size-full wp-image-187358\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/10\/Joyeux-18eme-anniversaire-Geopanel.jpg 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/10\/Joyeux-18eme-anniversaire-Geopanel-300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/10\/Joyeux-18eme-anniversaire-Geopanel-1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/10\/Joyeux-18eme-anniversaire-Geopanel-768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/10\/Joyeux-18eme-anniversaire-Geopanel-224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/10\/Joyeux-18eme-anniversaire-Geopanel-124x50.jpg 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/10\/Joyeux-18eme-anniversaire-Geopanel-570x230.jpg 570w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n<\/div>\r\n<div class=\"column column-2\" style=\"padding-top:0px;\">\r\n<h2>Joyeux anniversaire, Geopanel!<\/h2>\r\n<p>Le 12 octobre, nous avons c\u00e9l\u00e9br\u00e9 les 18 ans \u00e0 partir le moment o\u00f9 Mirco Pegoraro, PDG de Geoplast, a invent\u00e9 le  coffrage en plastique recycl\u00e9 Geopanel et r\u00e9volutionn\u00e9 l&rsquo;industrie de la construction.<\/p>\r\n<\/div><\/a><\/div>\r\n\r\n<div class=\"post-page columns-wrapper two-columns\" style=\"padding-left:0px;\">\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/geoplast-remporte-la-finale-a-loffice-europeen-des-brevets\/\" target=\"_blank\" rel=\"noopener\">\r\n<div class=\"column column-1\" style=\"padding-left:0px; margin-top:33px;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/Geoplast-remporte-la-finale-a-lOffice-europeen-des-brevets-1.jpg\" alt=\"Geoplast remporte la finale \u00e0 l&#039;Office europ\u00e9en des brevets\" width=\"1240\" height=\"500\" class=\"alignnone size-full wp-image-188500\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/Geoplast-remporte-la-finale-a-lOffice-europeen-des-brevets-1.jpg 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/Geoplast-remporte-la-finale-a-lOffice-europeen-des-brevets-1-300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/Geoplast-remporte-la-finale-a-lOffice-europeen-des-brevets-1-1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/Geoplast-remporte-la-finale-a-lOffice-europeen-des-brevets-1-768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/Geoplast-remporte-la-finale-a-lOffice-europeen-des-brevets-1-224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/Geoplast-remporte-la-finale-a-lOffice-europeen-des-brevets-1-124x50.jpg 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/Geoplast-remporte-la-finale-a-lOffice-europeen-des-brevets-1-570x230.jpg 570w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n<\/div>\r\n<div class=\"column column-2\" style=\"padding-top:0px;\">\r\n<h2>Victoire finale de Geoplast \u00e0 l&rsquo;Office Europ\u00e9en des Brevets<\/h2>\r\n<p>Le 17 octobre, la Chambre de Recours de l&rsquo;Office europ\u00e9en des brevets a confirm\u00e9 la validit\u00e9 du brevet europ\u00e9en EP 1  538 277 B1 de Geoplast (recours no T2759\/19-3.2.03). <\/p>\r\n<\/div><\/a><\/div>\r\n\r\n<div class=\"post-page columns-wrapper two-columns\" style=\"padding-left:0px;\">\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/modulo-est-certifie-par-epd\/\" target=\"_blank\" rel=\"noopener\">\r\n<div class=\"column column-1\" style=\"padding-left:0px; margin-top:33px;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/Modulo-est-certifie-par-EPD.jpg\" alt=\"Modulo est certifi\u00e9 par EPD!\" width=\"1240\" height=\"500\" class=\"alignnone size-full wp-image-188645\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/Modulo-est-certifie-par-EPD.jpg 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/Modulo-est-certifie-par-EPD-300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/Modulo-est-certifie-par-EPD-1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/Modulo-est-certifie-par-EPD-768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/Modulo-est-certifie-par-EPD-224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/Modulo-est-certifie-par-EPD-124x50.jpg 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/Modulo-est-certifie-par-EPD-570x230.jpg 570w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n<\/div>\r\n<div class=\"column column-2\" style=\"padding-top:0px;\">\r\n<h2>Modulo est certifi\u00e9 EPD! <\/h2>\r\n<p>Modulo a \u00e9t\u00e9 le premier de nombreux produits certifi\u00e9s par le syst\u00e8me international EPD (Environmental Product  D\u00e9claration).<\/p>\r\n<\/div><\/a><\/div>\r\n\r\n\r\n&nbsp;\r\n<a class=\"button--cat-l\" href=\"https:\/\/www.geoplastglobal.com\/fr\/contacts\/\" target=\"_blank\" rel=\"noopener\">CONTACTEZ NOS EXPERTS<\/a>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n","protected":false},"excerpt":{"rendered":"<p>Nous avons eu une ann\u00e9e 2023 charg\u00e9e et fructueuse qui nous a donn\u00e9 de nombreuses raisons de faire la f\u00eate. Nous avons continu\u00e9 \u00e0 rendre davantage de projets durablement rentables, nous avons annonc\u00e9 de nouveaux produits et certifications, remport\u00e9 une proc\u00e9dure de brevet et c\u00e9l\u00e9br\u00e9 le passage \u00e0 l\u2019\u00e2ge adulte [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":189696,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2872],"tags":[4061,3503,1676,4062],"class_list":["post-189652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rentabilite-durable","tag-2023-fr","tag-bonne-annee","tag-durabilite","tag-nouvelle-annee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nos \u00e9v\u00e9nements les plus marquants de 2023 &#8211; Geoplast<\/title>\n<meta name=\"description\" content=\"Nous avons eu une ann\u00e9e 2023 charg\u00e9e et fructueuse qui nous a donn\u00e9 de nombreuses raisons de f\u00eater. Vous trouverez ci-dessous une s\u00e9lection de nos \u00e9v\u00e9nements les plus marquants de 2023.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/nos-evenements-les-plus-marquants-de-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nos \u00e9v\u00e9nements les plus marquants de 2023 &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Nous avons eu une ann\u00e9e 2023 charg\u00e9e et fructueuse qui nous a donn\u00e9 de nombreuses raisons de f\u00eater. Vous trouverez ci-dessous une s\u00e9lection de nos \u00e9v\u00e9nements les plus marquants de 2023.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/nos-evenements-les-plus-marquants-de-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-20T14:18:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-21T10:54:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/12\/Nos-evenements-les-plus-marquants-de-2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jelena Zivancevic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jelena Zivancevic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/nos-evenements-les-plus-marquants-de-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/nos-evenements-les-plus-marquants-de-2023\\\/\"},\"author\":{\"name\":\"Jelena Zivancevic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\"},\"headline\":\"Nos \u00e9v\u00e9nements les plus marquants de 2023\",\"datePublished\":\"2023-12-20T14:18:54+00:00\",\"dateModified\":\"2023-12-21T10:54:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/nos-evenements-les-plus-marquants-de-2023\\\/\"},\"wordCount\":384,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/nos-evenements-les-plus-marquants-de-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Nos-evenements-les-plus-marquants-de-2023.jpg\",\"keywords\":[\"2023\",\"bonne ann\u00e9e\",\"Durabilit\u00e9\",\"Nouvelle ann\u00e9e\"],\"articleSection\":[\"Rentabilit\u00e9 Durable\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/nos-evenements-les-plus-marquants-de-2023\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/nos-evenements-les-plus-marquants-de-2023\\\/\",\"name\":\"Nos \u00e9v\u00e9nements les plus marquants de 2023 &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/nos-evenements-les-plus-marquants-de-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/nos-evenements-les-plus-marquants-de-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Nos-evenements-les-plus-marquants-de-2023.jpg\",\"datePublished\":\"2023-12-20T14:18:54+00:00\",\"dateModified\":\"2023-12-21T10:54:00+00:00\",\"description\":\"Nous avons eu une ann\u00e9e 2023 charg\u00e9e et fructueuse qui nous a donn\u00e9 de nombreuses raisons de f\u00eater. Vous trouverez ci-dessous une s\u00e9lection de nos \u00e9v\u00e9nements les plus marquants de 2023.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/nos-evenements-les-plus-marquants-de-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/nos-evenements-les-plus-marquants-de-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Nos-evenements-les-plus-marquants-de-2023.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Nos-evenements-les-plus-marquants-de-2023.jpg\",\"width\":1240,\"height\":500,\"caption\":\"Nos \u00e9v\u00e9nements les plus marquants de 2023\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\",\"name\":\"Jelena Zivancevic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"caption\":\"Jelena Zivancevic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nos \u00e9v\u00e9nements les plus marquants de 2023 &#8211; Geoplast","description":"Nous avons eu une ann\u00e9e 2023 charg\u00e9e et fructueuse qui nous a donn\u00e9 de nombreuses raisons de f\u00eater. Vous trouverez ci-dessous une s\u00e9lection de nos \u00e9v\u00e9nements les plus marquants de 2023.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/fr\/blog\/nos-evenements-les-plus-marquants-de-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"Nos \u00e9v\u00e9nements les plus marquants de 2023 &#8211; Geoplast","og_description":"Nous avons eu une ann\u00e9e 2023 charg\u00e9e et fructueuse qui nous a donn\u00e9 de nombreuses raisons de f\u00eater. Vous trouverez ci-dessous une s\u00e9lection de nos \u00e9v\u00e9nements les plus marquants de 2023.","og_url":"https:\/\/www.geoplastglobal.com\/fr\/blog\/nos-evenements-les-plus-marquants-de-2023\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2023-12-20T14:18:54+00:00","article_modified_time":"2023-12-21T10:54:00+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/12\/Nos-evenements-les-plus-marquants-de-2023.jpg","type":"image\/jpeg"}],"author":"Jelena Zivancevic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Jelena Zivancevic","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/nos-evenements-les-plus-marquants-de-2023\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/nos-evenements-les-plus-marquants-de-2023\/"},"author":{"name":"Jelena Zivancevic","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad"},"headline":"Nos \u00e9v\u00e9nements les plus marquants de 2023","datePublished":"2023-12-20T14:18:54+00:00","dateModified":"2023-12-21T10:54:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/nos-evenements-les-plus-marquants-de-2023\/"},"wordCount":384,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/nos-evenements-les-plus-marquants-de-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/12\/Nos-evenements-les-plus-marquants-de-2023.jpg","keywords":["2023","bonne ann\u00e9e","Durabilit\u00e9","Nouvelle ann\u00e9e"],"articleSection":["Rentabilit\u00e9 Durable"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/nos-evenements-les-plus-marquants-de-2023\/","url":"https:\/\/www.geoplastglobal.com\/fr\/blog\/nos-evenements-les-plus-marquants-de-2023\/","name":"Nos \u00e9v\u00e9nements les plus marquants de 2023 &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/nos-evenements-les-plus-marquants-de-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/nos-evenements-les-plus-marquants-de-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/12\/Nos-evenements-les-plus-marquants-de-2023.jpg","datePublished":"2023-12-20T14:18:54+00:00","dateModified":"2023-12-21T10:54:00+00:00","description":"Nous avons eu une ann\u00e9e 2023 charg\u00e9e et fructueuse qui nous a donn\u00e9 de nombreuses raisons de f\u00eater. Vous trouverez ci-dessous une s\u00e9lection de nos \u00e9v\u00e9nements les plus marquants de 2023.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/fr\/blog\/nos-evenements-les-plus-marquants-de-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/nos-evenements-les-plus-marquants-de-2023\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/12\/Nos-evenements-les-plus-marquants-de-2023.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/12\/Nos-evenements-les-plus-marquants-de-2023.jpg","width":1240,"height":500,"caption":"Nos \u00e9v\u00e9nements les plus marquants de 2023"},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/fr\/#website","url":"https:\/\/www.geoplastglobal.com\/fr\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad","name":"Jelena Zivancevic","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","caption":"Jelena Zivancevic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/189652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/comments?post=189652"}],"version-history":[{"count":3,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/189652\/revisions"}],"predecessor-version":[{"id":189655,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/189652\/revisions\/189655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/media\/189696"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/media?parent=189652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/categories?post=189652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/tags?post=189652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}