
{"id":169184,"date":"2022-04-20T05:04:45","date_gmt":"2022-04-20T05:04:45","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/?p=169184"},"modified":"2022-07-12T10:48:30","modified_gmt":"2022-07-12T10:48:30","slug":"rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/fr\/blog\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\/","title":{"rendered":"Rejoignez notre \u00e9v\u00e9nement de discussion ouverte:  Villes durables avec l&rsquo;Universit\u00e9 de Trente et Geoplast"},"content":{"rendered":"Nous nous sommes associ\u00e9s \u00e0 <a href=\"https:\/\/www.unitn.it\/en\" rel=\"noopener noreferrer\" target=\"_blank\">l&rsquo;Universit\u00e9 de Trente<\/a> pour notre prochain \u00e9v\u00e9nement de discussion ouverte \u00e0 15h00  CET le mercredi 27 avril 2022. Vous aurez l&rsquo;occasion d\u2018\u00e9changer avec nos experts sur le sujet des villes durables en  g\u00e9n\u00e9ral et \u00e9galement de vous concentrer sur la r\u00e9silience urbaine face aux inondations et les infrastructures  hydrauliques.\r\n\r\nCet \u00e9v\u00e9nement est ouvert \u00e0 tout le monde. Vous pouvez \u00e9couter ou engager la discussion avec les experts. \r\n\r\nLa discussion se d\u00e9roulera via Zoom sous la forme d&rsquo;une discussion ouverte mod\u00e9r\u00e9e. Vous parlerez avec:  \r\n<ul>\r\n<li><a href=\"https:\/\/www.linkedin.com\/in\/giuseppe-formetta-5923175b\/\" rel=\"noopener noreferrer\" target=\"_blank\">Giuseppe Formetta<\/a>, professeur assistant, Universit\u00e9 de Trente, <\/li>\r\n<li><a href=\"https:\/\/www.linkedin.com\/in\/alessandra-marzadri-7b7433161\/\" rel=\"noopener noreferrer\" target=\"_blank\">Alessandra Marzadri<\/a>, professeure associ\u00e9e, Universit\u00e9 de Trente, <\/li>\r\n<li><a href=\"https:\/\/www.linkedin.com\/in\/mircopegoraro\/\" rel=\"noopener noreferrer\" target=\"_blank\">Mirco Pegoraro<\/a>,  PDG de Geoplast,<\/li>\r\n<li><a href=\"https:\/\/www.linkedin.com\/in\/luca-zausa-a306341\/\" rel=\"noopener noreferrer\" target=\"_blank\">Luca Zausa<\/a>, CSO Global de Geoplast.<\/li>\r\n<\/ul>\r\n\r\nVoici quelques sujets qui viennent \u00e0 l&rsquo;esprit: \r\n<ul>\r\n<li>Quels sont les grands enjeux dans les villes li\u00e9s au changement climatique?<\/li>\r\n<li>Que peuvent faire les ing\u00e9nieurs civils et les architectes pour am\u00e9liorer la durabilit\u00e9 des villes?<\/li>\r\n<li>Quelles innovations Geoplast propose-t-il dans le domaine de l&rsquo;eau pour am\u00e9liorer la r\u00e9silience urbaine?<\/li>\r\n<li>Quels sont les avantages des innovations de l&rsquo;eau de Geoplast par rapport aux alternatives?<\/li>\r\n<\/ul>\r\n\r\n\r\n<font size=\"+2\"><a href=\"https:\/\/us06web.zoom.us\/webinar\/register\/WN_Wz_2wGovRlCeg39DASs6wA\" rel=\"noopener noreferrer\" target=\"_blank\">Inscrivez-vous \u00e0 l&rsquo;\u00e9v\u00e9nement de discussion ouverte<\/a><\/font> \r\n\r\nDur\u00e9e: 45 minutes\r\nLangue: <strong>italien et anglais<\/strong>\r\n<a href=\"https:\/\/zoom.us\/download\" rel=\"noopener noreferrer\" target=\"_blank\">T\u00e9l\u00e9chargez Zoom<\/a>\r\n","protected":false},"excerpt":{"rendered":"<p>Nous nous sommes associ\u00e9s \u00e0 l&rsquo;Universit\u00e9 de Trente pour notre prochain \u00e9v\u00e9nement de discussion ouverte \u00e0 15h00 CET le mercredi 27 avril 2022. Vous aurez l&rsquo;occasion d\u2018\u00e9changer avec nos experts sur le sujet des villes durables en g\u00e9n\u00e9ral et \u00e9galement de vous concentrer sur la r\u00e9silience urbaine face aux inondations [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":169122,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[733],"tags":[3352,1676,2153,3667],"class_list":["post-169184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-webinar-fr","tag-discussion-ouverte","tag-durabilite","tag-resilience-urbaine","tag-university-of-trento-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rejoignez notre \u00e9v\u00e9nement de discussion ouverte: Villes durables avec l&#039;Universit\u00e9 de Trente et Geoplast &#8211; Geoplast<\/title>\n<meta name=\"description\" content=\"Nous sommes heureux d&#039;annoncer que nous nous sommes associ\u00e9s \u00e0 l\u2019Universit\u00e9 de Trente pour une discussion ouverte sur les villes durables.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rejoignez notre \u00e9v\u00e9nement de discussion ouverte: Villes durables avec l&#039;Universit\u00e9 de Trente et Geoplast &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Nous sommes heureux d&#039;annoncer que nous nous sommes associ\u00e9s \u00e0 l\u2019Universit\u00e9 de Trente pour une discussion ouverte sur les villes durables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-20T05:04:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-12T10:48:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/04\/Trento-post-FR-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jelena Zivancevic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jelena Zivancevic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\\\/\"},\"author\":{\"name\":\"Jelena Zivancevic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\"},\"headline\":\"Rejoignez notre \u00e9v\u00e9nement de discussion ouverte: Villes durables avec l&rsquo;Universit\u00e9 de Trente et Geoplast\",\"datePublished\":\"2022-04-20T05:04:45+00:00\",\"dateModified\":\"2022-07-12T10:48:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\\\/\"},\"wordCount\":225,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Trento-post-FR-1.jpg\",\"keywords\":[\"discussion ouverte\",\"Durabilit\u00e9\",\"R\u00e9silience urbaine\",\"University of Trento\"],\"articleSection\":[\"Webinar\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\\\/\",\"name\":\"Rejoignez notre \u00e9v\u00e9nement de discussion ouverte: Villes durables avec l'Universit\u00e9 de Trente et Geoplast &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Trento-post-FR-1.jpg\",\"datePublished\":\"2022-04-20T05:04:45+00:00\",\"dateModified\":\"2022-07-12T10:48:30+00:00\",\"description\":\"Nous sommes heureux d'annoncer que nous nous sommes associ\u00e9s \u00e0 l\u2019Universit\u00e9 de Trente pour une discussion ouverte sur les villes durables.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Trento-post-FR-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Trento-post-FR-1.jpg\",\"width\":1240,\"height\":500,\"caption\":\"Villes durables avec l'Universit\u00e9 de Trente et Geoplast\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\",\"name\":\"Jelena Zivancevic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"caption\":\"Jelena Zivancevic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rejoignez notre \u00e9v\u00e9nement de discussion ouverte: Villes durables avec l'Universit\u00e9 de Trente et Geoplast &#8211; Geoplast","description":"Nous sommes heureux d'annoncer que nous nous sommes associ\u00e9s \u00e0 l\u2019Universit\u00e9 de Trente pour une discussion ouverte sur les villes durables.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/fr\/blog\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\/","og_locale":"fr_FR","og_type":"article","og_title":"Rejoignez notre \u00e9v\u00e9nement de discussion ouverte: Villes durables avec l'Universit\u00e9 de Trente et Geoplast &#8211; Geoplast","og_description":"Nous sommes heureux d'annoncer que nous nous sommes associ\u00e9s \u00e0 l\u2019Universit\u00e9 de Trente pour une discussion ouverte sur les villes durables.","og_url":"https:\/\/www.geoplastglobal.com\/fr\/blog\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2022-04-20T05:04:45+00:00","article_modified_time":"2022-07-12T10:48:30+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/04\/Trento-post-FR-1.jpg","type":"image\/jpeg"}],"author":"Jelena Zivancevic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Jelena Zivancevic","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\/"},"author":{"name":"Jelena Zivancevic","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad"},"headline":"Rejoignez notre \u00e9v\u00e9nement de discussion ouverte: Villes durables avec l&rsquo;Universit\u00e9 de Trente et Geoplast","datePublished":"2022-04-20T05:04:45+00:00","dateModified":"2022-07-12T10:48:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\/"},"wordCount":225,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/04\/Trento-post-FR-1.jpg","keywords":["discussion ouverte","Durabilit\u00e9","R\u00e9silience urbaine","University of Trento"],"articleSection":["Webinar"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\/","url":"https:\/\/www.geoplastglobal.com\/fr\/blog\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\/","name":"Rejoignez notre \u00e9v\u00e9nement de discussion ouverte: Villes durables avec l'Universit\u00e9 de Trente et Geoplast &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/04\/Trento-post-FR-1.jpg","datePublished":"2022-04-20T05:04:45+00:00","dateModified":"2022-07-12T10:48:30+00:00","description":"Nous sommes heureux d'annoncer que nous nous sommes associ\u00e9s \u00e0 l\u2019Universit\u00e9 de Trente pour une discussion ouverte sur les villes durables.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/fr\/blog\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/rejoignez-notre-evenement-de-discussion-ouverte-villes-durables-avec-luniversite-de-trente-et-geoplast\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/04\/Trento-post-FR-1.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/04\/Trento-post-FR-1.jpg","width":1240,"height":500,"caption":"Villes durables avec l'Universit\u00e9 de Trente et Geoplast"},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/fr\/#website","url":"https:\/\/www.geoplastglobal.com\/fr\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad","name":"Jelena Zivancevic","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","caption":"Jelena Zivancevic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/169184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/comments?post=169184"}],"version-history":[{"count":2,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/169184\/revisions"}],"predecessor-version":[{"id":169200,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/169184\/revisions\/169200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/media\/169122"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/media?parent=169184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/categories?post=169184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/tags?post=169184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}