
{"id":159163,"date":"2021-09-08T09:19:02","date_gmt":"2021-09-08T09:19:02","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/blog\/how-can-architects-improve-urban-resilience-to-the-climate-crisis\/"},"modified":"2022-11-22T11:44:03","modified_gmt":"2022-11-22T11:44:03","slug":"comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/fr\/blog\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\/","title":{"rendered":"Comment les architectes peuvent-ils am\u00e9liorer la  r\u00e9silience urbaine dans la crise climatique?"},"content":{"rendered":"Les ph\u00e9nom\u00e8nes m\u00e9t\u00e9orologiques extr\u00eames provoqu\u00e9s par le r\u00e9chauffement climatique augmentent en fr\u00e9quence et en intensit\u00e9, ce qui rend urgente l&rsquo;am\u00e9lioration de la r\u00e9silience dans les zones urbaines. Entre les d\u00e9fis nets z\u00e9ro et le secteur de la construction inerte, les architectes sont sur le point de trouver des solutions efficaces et durables pour leurs projets. \r\n\r\nNous avons con\u00e7u une vaste gamme de solutions pour aider les architectes \u00e0 construire des villes plus r\u00e9silientes et elles sont pr\u00eates \u00e0 \u00eatre utilis\u00e9es d\u00e8s demain: \r\n\r\n<h3>Am\u00e9lioration de la perm\u00e9abilit\u00e9 du sol avec des surfaces d&rsquo;herbe et de gravier<\/h3>\r\n\r\nL&rsquo;un des plus gros probl\u00e8mes de la croissance urbaine est l&rsquo;imperm\u00e9abilit\u00e9 des surfaces d&rsquo;asphalte qui intensifie les  probl\u00e8mes d\u00e9j\u00e0 critiques d&rsquo;inondations et d&rsquo;\u00eelots de chaleur urbains. L&rsquo;utilisation d&rsquo;herbe et de gravier autant que possible  est essentiel pour am\u00e9liorer le drainage naturel du sol en milieu urbain.\r\n\r\nGeoplast a d\u00e9velopp\u00e9 plusieurs syst\u00e8mes de rev\u00eatements de sol en plastique recycl\u00e9 tels que <a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/vert\/geoflor\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geoflor<\/a>, <a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/vert\/geograss\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geograss<\/a>, <a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/vert\/runfloor\/\" rel=\"noopener noreferrer\" target=\"_blank\">Runfloor<\/a>, <a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/vert\/salvaverde\/\" rel=\"noopener noreferrer\" target=\"_blank\">Salvaverde<\/a> et <a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/vert\/geogravel\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geogravel<\/a> que les architectes peuvent utiliser pour <a href=\"https:\/\/www.geoplastglobal.com\/fr\/les-solutions\/vert\/solution-parking-sur-gazon-existant\/\" rel=\"noopener noreferrer\" target=\"_blank\">convertir les zones existantes<\/a> ou <a href=\"https:\/\/www.geoplastglobal.com\/fr\/les-solutions\/vert\/zones-de-passage-et-stationnement\/\" rel=\"noopener noreferrer\" target=\"_blank\">cr\u00e9er de nouvelles zones<\/a> perm\u00e9ables pour l&rsquo;acc\u00e8s des pi\u00e9tons et des v\u00e9hicules <a href=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/geoflor-rendez-votre-stationnement-vert-en-1-heure\/\" rel=\"noopener noreferrer\" target=\"_blank\">en quelques heures<\/a>.\r\n\r\n<h3>Att\u00e9nuer les inondations par une gestion efficace des eaux pluviales <\/h3>\r\n\r\nLes projets qui sont bas\u00e9s uniquement sur les anciens \u00e9gouts de la ville pour la gestion des eaux pluviales ne sont plus  une option acceptable. Les r\u00e9centes inondations ont soulign\u00e9 le besoin de solutions plus efficaces et durables, capables  d&rsquo;am\u00e9liorer les syst\u00e8mes d&rsquo;\u00e9gouts existants ou ceux qui vont fonctionner ind\u00e9pendamment.\r\n\r\nLes bassins souterrains cr\u00e9\u00e9s avec <a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/eau\/aquabox\/\" rel=\"noopener noreferrer\" target=\"_blank\">Aquabox<\/a>, <a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/eau\/nouveau-elevetor-tank\/\" rel=\"noopener noreferrer\" target=\"_blank\">Nouveau Elevetor Tank<\/a>, <a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/eau\/drening\/\" rel=\"noopener noreferrer\" target=\"_blank\">Drening<\/a> et <a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/eau\/drainpanel\/\" rel=\"noopener noreferrer\" target=\"_blank\">Drainpanel<\/a>, ainsi que les syst\u00e8mes de  drainage de surface tels que <a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/eau\/geocell\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geocell<\/a>, sont con\u00e7us pour g\u00e9rer avec succ\u00e8s l&rsquo;afflux d&rsquo;eau de pluie sous les <a href=\"https:\/\/www.geoplastglobal.com\/fr\/les-solutions\/eau\/drainage-de-eau-dans-les-batiments-residentiels-et-commerciaux\/\" rel=\"noopener noreferrer\" target=\"_blank\">b\u00e2timents<\/a> et <a href=\"https:\/\/www.geoplastglobal.com\/fr\/les-solutions\/eau\/drainage-des-parkings\/\" rel=\"noopener noreferrer\" target=\"_blank\">les zones pav\u00e9es<\/a> et permettre la r\u00e9cup\u00e9ration de l&rsquo;eau pour <a href=\"https:\/\/www.geoplastglobal.com\/fr\/les-solutions\/eau\/irrigation-des-parcs-et-jardins-publics\/\" rel=\"noopener noreferrer\" target=\"_blank\">l&rsquo;irrigation<\/a>, <a href=\"https:\/\/www.geoplastglobal.com\/fr\/les-solutions\/eau\/collecte-des-eaux-de-pluie-a-usage-domestique\/\" rel=\"noopener noreferrer\" target=\"_blank\">les usages domestiques<\/a>, ou <a href=\"https:\/\/www.geoplastglobal.com\/fr\/les-solutions\/eau\/reservoirs-de-stockage-pour-la-protection-contre-incendie\/\" rel=\"noopener noreferrer\" target=\"_blank\"> protection contre le  feu<\/a>.\r\n\r\n<h3>R\u00e9duire les \u00eelots de chaleur urbains avec des toits et des murs v\u00e9g\u00e9talis\u00e9s<\/h3>\r\n\r\nMurs et toits v\u00e9g\u00e9talis\u00e9s agissent comme un bouclier thermique naturel capable de r\u00e9duire les besoins \u00e9nerg\u00e9tiques du  b\u00e2timent de <a href=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/drainroof-43-deconomie-denergie\/\" rel=\"noopener noreferrer\" target=\"_blank\">43 %<\/a>. Si appliqu\u00e9s \u00e0 chaque nouveau projet, ils peuvent \u00e9galement abaisser la temp\u00e9rature des quartiers  locaux, r\u00e9duisant l&rsquo;effet de l&rsquo;\u00eelot de chaleur urbain. \r\n\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/vert\/wall-y\/\" rel=\"noopener noreferrer\" target=\"_blank\">Wall-Y<\/a> est con\u00e7u pour cr\u00e9er des <a href=\"https:\/\/www.geoplastglobal.com\/fr\/les-solutions\/vert\/mur-vegetalise-exterieur\/\" rel=\"noopener noreferrer\" target=\"_blank\">murs v\u00e9g\u00e9talis\u00e9s<\/a>, tandis que <a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/vert\/drainroof\/\" rel=\"noopener noreferrer\" target=\"_blank\">Drainroof<\/a> et <a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/vert\/completa\/\" rel=\"noopener noreferrer\" target=\"_blank\">Completa<\/a> sont utilis\u00e9s pour la culture de  jardins sur toit <a href=\"https:\/\/www.geoplastglobal.com\/fr\/les-solutions\/vert\/jardins-suspendus-pre-vegetalises\/\" rel=\"noopener noreferrer\" target=\"_blank\">extensifs<\/a> ou <a href=\"https:\/\/www.geoplastglobal.com\/fr\/les-solutions\/vert\/jardin-suspendus-intensifs\/\" rel=\"noopener noreferrer\" target=\"_blank\">intensifs<\/a>. Chacun est bien adapt\u00e9 aux conditions de la ville en termes d&rsquo;exigences techniques, d&rsquo;entretien et esth\u00e9tiques, permettant une gestion de l&rsquo;\u00e9nergie et de la temp\u00e9rature plus r\u00e9siliente. \r\n\r\n<font size=\"+2\"><a href=\"https:\/\/www.geoplastglobal.com\/en\/contacts\/\" rel=\"noopener noreferrer\" target=\"_blank\">Contactez-nous<\/a> pour savoir comment am\u00e9liorer la r\u00e9silience urbaine avec votre prochain projet.<\/font>\r\n","protected":false},"excerpt":{"rendered":"<p>Les ph\u00e9nom\u00e8nes m\u00e9t\u00e9orologiques extr\u00eames provoqu\u00e9s par le r\u00e9chauffement climatique augmentent en fr\u00e9quence et en intensit\u00e9, ce qui rend urgente l&rsquo;am\u00e9lioration de la r\u00e9silience dans les zones urbaines. Entre les d\u00e9fis nets z\u00e9ro et le secteur de la construction inerte, les architectes sont sur le point de trouver des solutions efficaces [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":159112,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[2952,1917,727,1667,2824,2137,1173,2002,1891,353,2153,1896,1897,2140,1671,1007],"class_list":["post-159163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eau","tag-aquabox-fr","tag-completa-fr","tag-drainpanel-fr","tag-drainroof-fr","tag-drening","tag-geocell-it-fr","tag-geoflor-fr","tag-geograss-fr","tag-geogravel-fr","tag-nouveau-elevetor-tank","tag-resilience-urbaine","tag-runfloor-fr","tag-salvaverde-fr","tag-solutions-deau","tag-solutions-vertes","tag-wall-y-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment les architectes peuvent-ils am\u00e9liorer la r\u00e9silience urbaine dans la crise climatique? &#8211; Geoplast<\/title>\n<meta name=\"description\" content=\"La crise climatique fait de la r\u00e9silience urbaine une question urgente. Nous avons con\u00e7u une vaste gamme de solutions pour aider les architectes \u00e0 construire des villes plus r\u00e9silientes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment les architectes peuvent-ils am\u00e9liorer la r\u00e9silience urbaine dans la crise climatique? &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"La crise climatique fait de la r\u00e9silience urbaine une question urgente. Nous avons con\u00e7u une vaste gamme de solutions pour aider les architectes \u00e0 construire des villes plus r\u00e9silientes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-08T09:19:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-22T11:44:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/09\/Geoplast-blog-How-can-architects-improve-urban-resilience.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jelena Zivancevic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jelena Zivancevic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\\\/\"},\"author\":{\"name\":\"Jelena Zivancevic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\"},\"headline\":\"Comment les architectes peuvent-ils am\u00e9liorer la r\u00e9silience urbaine dans la crise climatique?\",\"datePublished\":\"2021-09-08T09:19:02+00:00\",\"dateModified\":\"2022-11-22T11:44:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\\\/\"},\"wordCount\":524,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Geoplast-blog-How-can-architects-improve-urban-resilience.jpg\",\"keywords\":[\"Aquabox\",\"Completa\",\"Drainpanel\",\"Drainroof\",\"Drening\",\"Geocell\",\"Geoflor\",\"Geograss\",\"Geogravel\",\"Nouveau Elevetor Tank\",\"R\u00e9silience urbaine\",\"Runfloor\",\"Salvaverde\",\"Solutions d'eau\",\"Solutions vertes\",\"Wall-Y\"],\"articleSection\":[\"Eau\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\\\/\",\"name\":\"Comment les architectes peuvent-ils am\u00e9liorer la r\u00e9silience urbaine dans la crise climatique? &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Geoplast-blog-How-can-architects-improve-urban-resilience.jpg\",\"datePublished\":\"2021-09-08T09:19:02+00:00\",\"dateModified\":\"2022-11-22T11:44:03+00:00\",\"description\":\"La crise climatique fait de la r\u00e9silience urbaine une question urgente. Nous avons con\u00e7u une vaste gamme de solutions pour aider les architectes \u00e0 construire des villes plus r\u00e9silientes.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Geoplast-blog-How-can-architects-improve-urban-resilience.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Geoplast-blog-How-can-architects-improve-urban-resilience.jpg\",\"width\":1240,\"height\":500,\"caption\":\"Comment les architectes peuvent-ils am\u00e9liorer la r\u00e9silience urbaine dans la crise climatique?\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\",\"name\":\"Jelena Zivancevic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"caption\":\"Jelena Zivancevic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment les architectes peuvent-ils am\u00e9liorer la r\u00e9silience urbaine dans la crise climatique? &#8211; Geoplast","description":"La crise climatique fait de la r\u00e9silience urbaine une question urgente. Nous avons con\u00e7u une vaste gamme de solutions pour aider les architectes \u00e0 construire des villes plus r\u00e9silientes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/fr\/blog\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment les architectes peuvent-ils am\u00e9liorer la r\u00e9silience urbaine dans la crise climatique? &#8211; Geoplast","og_description":"La crise climatique fait de la r\u00e9silience urbaine une question urgente. Nous avons con\u00e7u une vaste gamme de solutions pour aider les architectes \u00e0 construire des villes plus r\u00e9silientes.","og_url":"https:\/\/www.geoplastglobal.com\/fr\/blog\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2021-09-08T09:19:02+00:00","article_modified_time":"2022-11-22T11:44:03+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/09\/Geoplast-blog-How-can-architects-improve-urban-resilience.jpg","type":"image\/jpeg"}],"author":"Jelena Zivancevic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Jelena Zivancevic","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\/"},"author":{"name":"Jelena Zivancevic","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad"},"headline":"Comment les architectes peuvent-ils am\u00e9liorer la r\u00e9silience urbaine dans la crise climatique?","datePublished":"2021-09-08T09:19:02+00:00","dateModified":"2022-11-22T11:44:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\/"},"wordCount":524,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/09\/Geoplast-blog-How-can-architects-improve-urban-resilience.jpg","keywords":["Aquabox","Completa","Drainpanel","Drainroof","Drening","Geocell","Geoflor","Geograss","Geogravel","Nouveau Elevetor Tank","R\u00e9silience urbaine","Runfloor","Salvaverde","Solutions d'eau","Solutions vertes","Wall-Y"],"articleSection":["Eau"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\/","url":"https:\/\/www.geoplastglobal.com\/fr\/blog\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\/","name":"Comment les architectes peuvent-ils am\u00e9liorer la r\u00e9silience urbaine dans la crise climatique? &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/09\/Geoplast-blog-How-can-architects-improve-urban-resilience.jpg","datePublished":"2021-09-08T09:19:02+00:00","dateModified":"2022-11-22T11:44:03+00:00","description":"La crise climatique fait de la r\u00e9silience urbaine une question urgente. Nous avons con\u00e7u une vaste gamme de solutions pour aider les architectes \u00e0 construire des villes plus r\u00e9silientes.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/fr\/blog\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/comment-les-architectes-peuvent-ils-ameliorer-la-resilience-urbaine-dans-la-crise-climatique\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/09\/Geoplast-blog-How-can-architects-improve-urban-resilience.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/09\/Geoplast-blog-How-can-architects-improve-urban-resilience.jpg","width":1240,"height":500,"caption":"Comment les architectes peuvent-ils am\u00e9liorer la r\u00e9silience urbaine dans la crise climatique?"},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/fr\/#website","url":"https:\/\/www.geoplastglobal.com\/fr\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad","name":"Jelena Zivancevic","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","caption":"Jelena Zivancevic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/159163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/comments?post=159163"}],"version-history":[{"count":6,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/159163\/revisions"}],"predecessor-version":[{"id":159994,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/159163\/revisions\/159994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/media\/159112"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/media?parent=159163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/categories?post=159163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/tags?post=159163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}