
{"id":156743,"date":"2021-07-21T05:29:07","date_gmt":"2021-07-21T05:29:07","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/?p=156743"},"modified":"2021-07-21T13:02:44","modified_gmt":"2021-07-21T13:02:44","slug":"conseils-aux-architectes-sur-la-durabilite","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/fr\/blog\/conseils-aux-architectes-sur-la-durabilite\/","title":{"rendered":"Conseils aux architectes sur la durabilit\u00e9"},"content":{"rendered":"<style> .single-post .body h2 { margin-top: 0 !important; font-size: 24px; } .single-post article.post .body p { padding-top: 6px; } <\/style>\r\n<a href=\"\/fr\/sustainability\/\" rel=\"noopener noreferrer\" target=\"_blank\">La durabilit\u00e9<\/a> est une tendance irr\u00e9sistible et imparable qui doit \u00eatre adopt\u00e9e par tous les architectes. Je travaille avec des architectes sur l&rsquo;am\u00e9lioration de la durabilit\u00e9, de la rentabilit\u00e9 et de la qualit\u00e9 des projets de construction depuis des d\u00e9cennies. Sur la base de mon exp\u00e9rience, je vous offre quelques conseils essentiels que tous les architectes pourraient trouver utiles \u00e0 suivre:\r\n&nbsp;\r\n<h2>Remplacez les mati\u00e8res vierges par les mati\u00e8res recycl\u00e9es<\/h2>\r\nL&rsquo;usage des mati\u00e8res vierges repr\u00e9sente dans la plupart des cas un probl\u00e8me pour la durabilit\u00e9. Votre objectif devrait \u00eatre d&rsquo;utiliser autant de mati\u00e8res recycl\u00e9es que possible et de r\u00e9duire les mati\u00e8res vierges. Un petit e-mail \u00e0 vos fournisseurs et fabricants suffira pour comprendre si vous utilisez des mat\u00e9riaux et des produits qui utilisent des mati\u00e8res recycl\u00e9es ou non. \r\n&nbsp;\r\n<h2>Utilisez des solutions disponibles dans le monde entier, produites en s\u00e9rie et abordables<\/h2>\r\nTrop souvent, les architectes choisissent des solutions tr\u00e8s populaires mais qui ne peuvent pas am\u00e9liorer la construction  \u00e0 l&rsquo;\u00e9chelle mondiale en raison de limitations de production, d&rsquo;un manque de distribution ou d&rsquo;un prix \u00e9lev\u00e9. Il est pr\u00e9f\u00e9rable d&rsquo;investir dans des innovations disponibles dans le monde entier, qui peuvent facilement \u00e9lever la production  et sont abordables pour une grande partie du march\u00e9.\r\n&nbsp;\r\n<h2>Utilisez des solutions \u00e9prouv\u00e9es \u00e0 long terme<\/h2>\r\nLes projets de construction vont \u00eatre utilis\u00e9s pendant des d\u00e9cennies, voire des si\u00e8cles. Lors de la conception et de la construction, vous devez vous assurer de choisir des solutions qui ont la plus grande probabilit\u00e9 de rester pertinentes et d&rsquo;\u00eatre respect\u00e9es \u00e0 long terme. Ceci est r\u00e9alis\u00e9 en choisissant des solutions qui ont d\u00e9j\u00e0 fait leurs preuves et qui ont une  vision \u00e0 long terme.\r\n\r\n<p style=\"padding-top: 22px;\">En tant que cr\u00e9ateur et fabricant de produits, je vous sugg\u00e8re de nous appeler et de vous renseigner en d\u00e9tail sur les conseils ci-dessus avant de prendre une d\u00e9cision sur la mati\u00e8re et les produits \u00e0 utiliser. Nous partageons un objectif commun pour am\u00e9liorer la durabilit\u00e9 dans la construction, et tout architecte et fabricant devrait \u00eatre pr\u00eat \u00e0 travailler ensemble afin d\u2019y arriver.<\/p>","protected":false},"excerpt":{"rendered":"<p>La durabilit\u00e9 est une tendance irr\u00e9sistible et imparable qui doit \u00eatre adopt\u00e9e par tous les architectes. Je travaille avec des architectes sur l&rsquo;am\u00e9lioration de la durabilit\u00e9, de la rentabilit\u00e9 et de la qualit\u00e9 des projets de construction depuis des d\u00e9cennies. Sur la base de mon exp\u00e9rience, je vous offre quelques [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":156625,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2872],"tags":[3231,1739,1585,1676,3287,4239,2756],"class_list":["post-156743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rentabilite-durable","tag-architecture-fr","tag-sustainable-architecture","tag-sustainable-building-fr","tag-durabilite","tag-plastiques-recycles","tag-recycled-plastic-fr","tag-rentabilite-durable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conseils aux architectes sur la durabilit\u00e9 &#8211; Geoplast<\/title>\n<meta name=\"description\" content=\"Je travaille sur l&#039;am\u00e9lioration de la durabilit\u00e9 et de la rentabilit\u00e9 des projets de construction depuis des d\u00e9cennies. Voici quelques conseils de ma part pour les architectes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/conseils-aux-architectes-sur-la-durabilite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conseils aux architectes sur la durabilit\u00e9 &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Je travaille sur l&#039;am\u00e9lioration de la durabilit\u00e9 et de la rentabilit\u00e9 des projets de construction depuis des d\u00e9cennies. Voici quelques conseils de ma part pour les architectes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/conseils-aux-architectes-sur-la-durabilite\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-21T05:29:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-21T13:02:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/07\/Mirco-Pegoraro-SEO-Geoplast.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mirco Pegoraro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mirco Pegoraro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/conseils-aux-architectes-sur-la-durabilite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/conseils-aux-architectes-sur-la-durabilite\\\/\"},\"author\":{\"name\":\"Mirco Pegoraro\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/person\\\/429475bf4037f4574c7647a775e57105\"},\"headline\":\"Conseils aux architectes sur la durabilit\u00e9\",\"datePublished\":\"2021-07-21T05:29:07+00:00\",\"dateModified\":\"2021-07-21T13:02:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/conseils-aux-architectes-sur-la-durabilite\\\/\"},\"wordCount\":383,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/conseils-aux-architectes-sur-la-durabilite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Mirco-Pegoraro-SEO-Geoplast.jpg\",\"keywords\":[\"Architecture\",\"Architecture durable\",\"Construction durable\",\"Durabilit\u00e9\",\"plastiques recycl\u00e9s\",\"Recycled plastic\",\"Rentabilit\u00e9 Durable\"],\"articleSection\":[\"Rentabilit\u00e9 Durable\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/conseils-aux-architectes-sur-la-durabilite\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/conseils-aux-architectes-sur-la-durabilite\\\/\",\"name\":\"Conseils aux architectes sur la durabilit\u00e9 &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/conseils-aux-architectes-sur-la-durabilite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/conseils-aux-architectes-sur-la-durabilite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Mirco-Pegoraro-SEO-Geoplast.jpg\",\"datePublished\":\"2021-07-21T05:29:07+00:00\",\"dateModified\":\"2021-07-21T13:02:44+00:00\",\"description\":\"Je travaille sur l'am\u00e9lioration de la durabilit\u00e9 et de la rentabilit\u00e9 des projets de construction depuis des d\u00e9cennies. Voici quelques conseils de ma part pour les architectes.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/conseils-aux-architectes-sur-la-durabilite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/conseils-aux-architectes-sur-la-durabilite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Mirco-Pegoraro-SEO-Geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Mirco-Pegoraro-SEO-Geoplast.jpg\",\"width\":1240,\"height\":500,\"caption\":\"Mirco Pegoraro SEO Geoplast\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/person\\\/429475bf4037f4574c7647a775e57105\",\"name\":\"Mirco Pegoraro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e47c9a1476a827613d869ba6315c33b9a90a00c66085309c002bf7db53d49b9e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e47c9a1476a827613d869ba6315c33b9a90a00c66085309c002bf7db53d49b9e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e47c9a1476a827613d869ba6315c33b9a90a00c66085309c002bf7db53d49b9e?s=96&d=mm&r=g\",\"caption\":\"Mirco Pegoraro\"},\"sameAs\":[\"https:\\\/\\\/www.geoplastglobal.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conseils aux architectes sur la durabilit\u00e9 &#8211; Geoplast","description":"Je travaille sur l'am\u00e9lioration de la durabilit\u00e9 et de la rentabilit\u00e9 des projets de construction depuis des d\u00e9cennies. Voici quelques conseils de ma part pour les architectes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/fr\/blog\/conseils-aux-architectes-sur-la-durabilite\/","og_locale":"fr_FR","og_type":"article","og_title":"Conseils aux architectes sur la durabilit\u00e9 &#8211; Geoplast","og_description":"Je travaille sur l'am\u00e9lioration de la durabilit\u00e9 et de la rentabilit\u00e9 des projets de construction depuis des d\u00e9cennies. Voici quelques conseils de ma part pour les architectes.","og_url":"https:\/\/www.geoplastglobal.com\/fr\/blog\/conseils-aux-architectes-sur-la-durabilite\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2021-07-21T05:29:07+00:00","article_modified_time":"2021-07-21T13:02:44+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/07\/Mirco-Pegoraro-SEO-Geoplast.jpg","type":"image\/jpeg"}],"author":"Mirco Pegoraro","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Mirco Pegoraro","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/conseils-aux-architectes-sur-la-durabilite\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/conseils-aux-architectes-sur-la-durabilite\/"},"author":{"name":"Mirco Pegoraro","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/person\/429475bf4037f4574c7647a775e57105"},"headline":"Conseils aux architectes sur la durabilit\u00e9","datePublished":"2021-07-21T05:29:07+00:00","dateModified":"2021-07-21T13:02:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/conseils-aux-architectes-sur-la-durabilite\/"},"wordCount":383,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/conseils-aux-architectes-sur-la-durabilite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/07\/Mirco-Pegoraro-SEO-Geoplast.jpg","keywords":["Architecture","Architecture durable","Construction durable","Durabilit\u00e9","plastiques recycl\u00e9s","Recycled plastic","Rentabilit\u00e9 Durable"],"articleSection":["Rentabilit\u00e9 Durable"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/conseils-aux-architectes-sur-la-durabilite\/","url":"https:\/\/www.geoplastglobal.com\/fr\/blog\/conseils-aux-architectes-sur-la-durabilite\/","name":"Conseils aux architectes sur la durabilit\u00e9 &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/conseils-aux-architectes-sur-la-durabilite\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/conseils-aux-architectes-sur-la-durabilite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/07\/Mirco-Pegoraro-SEO-Geoplast.jpg","datePublished":"2021-07-21T05:29:07+00:00","dateModified":"2021-07-21T13:02:44+00:00","description":"Je travaille sur l'am\u00e9lioration de la durabilit\u00e9 et de la rentabilit\u00e9 des projets de construction depuis des d\u00e9cennies. Voici quelques conseils de ma part pour les architectes.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/fr\/blog\/conseils-aux-architectes-sur-la-durabilite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/conseils-aux-architectes-sur-la-durabilite\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/07\/Mirco-Pegoraro-SEO-Geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/07\/Mirco-Pegoraro-SEO-Geoplast.jpg","width":1240,"height":500,"caption":"Mirco Pegoraro SEO Geoplast"},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/fr\/#website","url":"https:\/\/www.geoplastglobal.com\/fr\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/person\/429475bf4037f4574c7647a775e57105","name":"Mirco Pegoraro","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e47c9a1476a827613d869ba6315c33b9a90a00c66085309c002bf7db53d49b9e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e47c9a1476a827613d869ba6315c33b9a90a00c66085309c002bf7db53d49b9e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e47c9a1476a827613d869ba6315c33b9a90a00c66085309c002bf7db53d49b9e?s=96&d=mm&r=g","caption":"Mirco Pegoraro"},"sameAs":["https:\/\/www.geoplastglobal.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/156743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/comments?post=156743"}],"version-history":[{"count":6,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/156743\/revisions"}],"predecessor-version":[{"id":156806,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/156743\/revisions\/156806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/media\/156625"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/media?parent=156743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/categories?post=156743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/tags?post=156743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}