
{"id":148551,"date":"2021-03-30T08:03:00","date_gmt":"2021-03-30T08:03:00","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/blog\/new-elevetor-is-over-12-times-less-expensive-to-transport-than-eps-or-gravel\/"},"modified":"2021-03-30T09:44:50","modified_gmt":"2021-03-30T09:44:50","slug":"new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/fr\/blog\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\/","title":{"rendered":"Nouveau Elevetor est plus de 12 fois moins cher \u00e0  transporter le que le PSE ou le gravier"},"content":{"rendered":"<a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/fondations\/nouveau-elevetor\/\" rel=\"noopener noreferrer\" target=\"_blank\">Nouveau Elevetor<\/a> est compos\u00e9 d&rsquo;\u00e9l\u00e9ments en plastique recyclables l\u00e9gers qui s&#8217;embo\u00eetent parfaitement. Cela le rend  beaucoup plus compact que les mat\u00e9riaux de remblayage traditionnels comme le polystyr\u00e8ne expans\u00e9 (PSE), le gravier  ou le sol. Pour faire une comparaison:\r\n\r\n<h2>1 camion peut transporter:<\/h2>\r\n\r\n<style>\r\n.green-background {\r\n    background-color: #e6e4e3;\r\n}\r\n.red-background {\r\n    background-color: #f5dbc9;\r\n}\r\n.estimate-mobile { display: none; }\r\n.estimate {\r\n    width: 100%;\r\n    margin: 20px auto 0 0;\r\n    border-collapse: separate;\r\n    border-spacing: 5px;\r\n}\r\n.estimate td {\r\n    width: 33%;\r\n    text-align: left;\r\n    padding: 20px;\r\n}\r\n#geoplastPost .estimate td p.header {\r\n    font-size: 20px;\r\n    font-weight: 700;\r\n    padding-top: 5px;\r\n}\r\n#geoplastPost .estimate td p {\r\n    font-size: 37px;\r\n    line-height: 1;\r\n    font-weight: 700;\r\n}\r\n.estimate tr {\r\n    padding-top: 5px;\r\n}\r\n.estimate tr td:nth-child(1) {\r\n    background-color: #f5dbc9; \r\n}\r\n.estimate tr td:nth-child(2), .estimate tr td:nth-child(3) {\r\n    background-color: #e6e4e3;\r\n}\r\n@media (max-width: 768px) {\r\n    .estimate {\r\n        display: none;\r\n    }\r\n    .estimate-mobile {\r\n        display: block;\r\n    }\r\n    #geoplastPost .estimate-mobile p {\r\n        line-height: 1;\r\n        font-size: 18px;\r\n    }\r\n}\r\n<\/style>\r\n<table class=\"estimate\">\r\n    <tr>\r\n        <td><p class=\"header\">Nouveau Elevetor<\/p><p>1,100m3<\/p><\/td>\r\n        <td><p class=\"header\">EPS<\/p><p>85m3<\/p><\/td>\r\n        <td><p class=\"header\">Sol de gravier ou de remblai<\/p><p>20-25m3<\/p><\/td>\r\n    <\/tr>\r\n<\/table>\r\n<div class=\"estimate-mobile\">\r\n    <p class=\"green-background\" style=\"padding-left: 10px; padding-right: 10px;\">Nouveau Elevetor<\/p>\r\n    <p class=\"green-background\" style=\"padding: 10px; margin-bottom: 10px;\">1,100m3<\/span><\/p>\r\n    <p class=\"red-background\" style=\"padding-left: 10px; padding-right: 10px;\">EPS<\/p>\r\n    <p class=\"red-background\" style=\"padding: 10px; margin-bottom: 10px;\">85m3<\/span><\/p>\r\n    <p class=\"red-background\" style=\"padding-left: 10px; padding-right: 10px;\">Sol de gravier ou de remblai<\/p>\r\n    <p class=\"red-background\" style=\"padding: 10px; margin-bottom: 10px;\">20-25m3<\/span><\/p>\r\n<\/div>\r\n\r\n&nbsp;\r\nEn raison de la grande capacit\u00e9 d&#8217;empilage et de la l\u00e9g\u00e8ret\u00e9 de Nouveau Elevetor, le volume de mat\u00e9riau \u00e0 transporter est  r\u00e9duit de 12 \u00e0 44 fois, ce qui r\u00e9duit consid\u00e9rablement les co\u00fbts de transport et de manutention. Par rapport aux solutions  traditionnelles, il offre \u00e9galement de nombreux autres avantages:\r\n&nbsp;\r\n<ul>\r\n<li>N\u00e9cessite moins d&rsquo;espace de stockage sur le chantier,<\/li>\r\n\r\n<li> Aucune grue ou machinerie lourde n&rsquo;est n\u00e9cessaire pour son installation,<\/li>\r\n\r\n<li>Acc\u00e9l\u00e8re le processus de construction,<\/li>\r\n\r\n<li> Fusionne 3 \u00e9tapes de coulage du b\u00e9ton : poutres de fondation, remblayage et coul\u00e9e de dalles,<\/li>\r\n\r\n<li>Cr\u00e9e des vides sanitaires inspectables, adapt\u00e9s au MEP et \u00e0 l&rsquo;att\u00e9nuation de la vapeur,<\/li>\r\n\r\n<li>Il est modulaire, r\u00e9glable en hauteur et peut \u00eatre utilis\u00e9 pour les rampes d&rsquo;acc\u00e8s, les escaliers ou diff\u00e9rentes  surfaces nivel\u00e9es,<\/li>\r\n\r\n<li>En raison de sa capacit\u00e9 de charge \u00e9lev\u00e9e, il est adapt\u00e9 aux fondations, \u00e0 l&rsquo;am\u00e9nagement paysager urbain et aux  surfaces pav\u00e9es r\u00e9sistantes,<\/li>\r\n\r\n<li>Il est fait de mat\u00e9riaux recycl\u00e9s qui sont plus durables que les autres solutions.<\/li>\r\n<\/ul>\r\n\r\n<h3>En savoir plus sur Nouveau Elevetor<\/h3>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/produits\/fondations\/nouveau-elevetor\/telechargement\/\" rel=\"noopener noreferrer\" target=\"_blank\">Documentation Nouveau Elevetor<\/a>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/en\/products\/foundations\/new-elevetor\/research-papers\/\" rel=\"noopener noreferrer\" target=\"_blank\">Documents de recherche Nouveau Elevetor<\/a>\r\n\r\n<h3>Projets Nouveau Elevetor<\/h3>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/projects\/expo-2020-quartier-thmatique--duba-\/\" rel=\"noopener noreferrer\" target=\"_blank\">EXPO 2020 Quartier Th\u00e9matique \u00e0 Duba\u00ef, EAU<\/a>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/projects\/agrandissement-dun-entrept-frigorifique-teolo-padoue\/\" rel=\"noopener noreferrer\" target=\"_blank\">Entrep\u00f4t frigorifique \u00e0 Teolo, Padoue, Italie<\/a>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/projects\/rnovation-de-la-piscine-municipale-de-bazas-france\/\" rel=\"noopener noreferrer\" target=\"_blank\">R\u00e9novation de la piscine municipale de Bazas, France<\/a>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/fr\/projects\/solutions-pour-les-fondations-rehaussement-de-la-place-en-face-du-nouveau-quartier-daffaires-symbiosis--milan\/\" rel=\"noopener noreferrer\" target=\"_blank\">Nouveau quartier d\u2019affaires Symbiosis \u00e0 Milan, Italie<\/a>\r\n","protected":false},"excerpt":{"rendered":"<p>Nouveau Elevetor est compos\u00e9 d&rsquo;\u00e9l\u00e9ments en plastique recyclables l\u00e9gers qui s&#8217;embo\u00eetent parfaitement. Cela le rend beaucoup plus compact que les mat\u00e9riaux de remblayage traditionnels comme le polystyr\u00e8ne expans\u00e9 (PSE), le gravier ou le sol. Pour faire une comparaison: 1 camion peut transporter: Nouveau Elevetor1,100m3 EPS85m3 Sol de gravier ou de [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":148552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2500,76,52],"tags":[291,1793,1977,1670],"class_list":["post-148551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construction","category-fondations","category-foundations","tag-construction-solutions","tag-nouveau-elevetor","tag-reduction-des-couts","tag-solutions-de-fondations"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouveau Elevetor est plus de 12 fois moins cher \u00e0 transporter le que le PSE ou le gravier &#8211; Geoplast<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouveau Elevetor est plus de 12 fois moins cher \u00e0 transporter le que le PSE ou le gravier &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Nouveau Elevetor est compos\u00e9 d&rsquo;\u00e9l\u00e9ments en plastique recyclables l\u00e9gers qui s&#8217;embo\u00eetent parfaitement. Cela le rend beaucoup plus compact que les mat\u00e9riaux de remblayage traditionnels comme le polystyr\u00e8ne expans\u00e9 (PSE), le gravier ou le sol. Pour faire une comparaison: 1 camion peut transporter: Nouveau Elevetor1,100m3 EPS85m3 Sol de gravier ou de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/fr\/blog\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-30T08:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-30T09:44:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/03\/New-Elevetor-Load-FR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jelena Zivancevic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jelena Zivancevic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\\\/\"},\"author\":{\"name\":\"Jelena Zivancevic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\"},\"headline\":\"Nouveau Elevetor est plus de 12 fois moins cher \u00e0 transporter le que le PSE ou le gravier\",\"datePublished\":\"2021-03-30T08:03:00+00:00\",\"dateModified\":\"2021-03-30T09:44:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\\\/\"},\"wordCount\":320,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/New-Elevetor-Load-FR.jpg\",\"keywords\":[\"Construction solutions\",\"Nouveau Elevetor\",\"R\u00e9duction des couts\",\"Solutions de fondations\"],\"articleSection\":[\"Construction\",\"Fondations\",\"Foundations\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\\\/\",\"name\":\"Nouveau Elevetor est plus de 12 fois moins cher \u00e0 transporter le que le PSE ou le gravier &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/New-Elevetor-Load-FR.jpg\",\"datePublished\":\"2021-03-30T08:03:00+00:00\",\"dateModified\":\"2021-03-30T09:44:50+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/blog\\\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/New-Elevetor-Load-FR.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/New-Elevetor-Load-FR.jpg\",\"width\":1240,\"height\":500},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/fr\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\",\"name\":\"Jelena Zivancevic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"caption\":\"Jelena Zivancevic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouveau Elevetor est plus de 12 fois moins cher \u00e0 transporter le que le PSE ou le gravier &#8211; Geoplast","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/fr\/blog\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouveau Elevetor est plus de 12 fois moins cher \u00e0 transporter le que le PSE ou le gravier &#8211; Geoplast","og_description":"Nouveau Elevetor est compos\u00e9 d&rsquo;\u00e9l\u00e9ments en plastique recyclables l\u00e9gers qui s&#8217;embo\u00eetent parfaitement. Cela le rend beaucoup plus compact que les mat\u00e9riaux de remblayage traditionnels comme le polystyr\u00e8ne expans\u00e9 (PSE), le gravier ou le sol. Pour faire une comparaison: 1 camion peut transporter: Nouveau Elevetor1,100m3 EPS85m3 Sol de gravier ou de [&hellip;]","og_url":"https:\/\/www.geoplastglobal.com\/fr\/blog\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2021-03-30T08:03:00+00:00","article_modified_time":"2021-03-30T09:44:50+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/03\/New-Elevetor-Load-FR.jpg","type":"image\/jpeg"}],"author":"Jelena Zivancevic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Jelena Zivancevic","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\/"},"author":{"name":"Jelena Zivancevic","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad"},"headline":"Nouveau Elevetor est plus de 12 fois moins cher \u00e0 transporter le que le PSE ou le gravier","datePublished":"2021-03-30T08:03:00+00:00","dateModified":"2021-03-30T09:44:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\/"},"wordCount":320,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/03\/New-Elevetor-Load-FR.jpg","keywords":["Construction solutions","Nouveau Elevetor","R\u00e9duction des couts","Solutions de fondations"],"articleSection":["Construction","Fondations","Foundations"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\/","url":"https:\/\/www.geoplastglobal.com\/fr\/blog\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\/","name":"Nouveau Elevetor est plus de 12 fois moins cher \u00e0 transporter le que le PSE ou le gravier &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/03\/New-Elevetor-Load-FR.jpg","datePublished":"2021-03-30T08:03:00+00:00","dateModified":"2021-03-30T09:44:50+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/fr\/blog\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.geoplastglobal.com\/fr\/blog\/new-elevetor-est-plus-de-12-fois-moins-cher-a-transporter-le-que-le-pse-ou-le-gravier\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/03\/New-Elevetor-Load-FR.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/03\/New-Elevetor-Load-FR.jpg","width":1240,"height":500},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/fr\/#website","url":"https:\/\/www.geoplastglobal.com\/fr\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/fr\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/fr\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad","name":"Jelena Zivancevic","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","caption":"Jelena Zivancevic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/148551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/comments?post=148551"}],"version-history":[{"count":4,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/148551\/revisions"}],"predecessor-version":[{"id":148573,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/posts\/148551\/revisions\/148573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/media\/148552"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/media?parent=148551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/categories?post=148551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/fr\/wp-json\/wp\/v2\/tags?post=148551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}