
{"id":52099,"date":"2017-11-28T10:22:01","date_gmt":"2017-11-28T10:22:01","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/?p=52099"},"modified":"2022-04-15T10:05:51","modified_gmt":"2022-04-15T10:05:51","slug":"caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/es\/blog\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\/","title":{"rendered":"Caso de estudio Completa: un nuevo tejado verde extensivo en Bolonia"},"content":{"rendered":"<a href=\"https:\/\/www.geoplastglobal.com\/it\/prodotti\/verde\/completa\/\" target=\"_blank\" rel=\"noopener\">Completa<\/a> de Geoplast es la \u00faltima generaci\u00f3n de sedum pre-cultivado para tejados verdes extensivos, que se pueden f\u00e1cilmente instalar tanto sobre superficies planas, como sobre techos inclinados , porque son extremamente ligeros (<strong>60 kg\/metro cuadrado<\/strong> en condiciones de saturaci\u00f3n de agua). El producto no requiere un mantenimiento particular y se puede quitar f\u00e1cilmente para cualquier inspecci\u00f3n del techo despu\u00e9s de la instalaci\u00f3n.\r\n\r\nGracias a estas peculiaridades, <a href=\"https:\/\/www.geoplastglobal.com\/it\/prodotti\/verde\/completa\/\" target=\"_blank\" rel=\"noopener\">Completa<\/a>\u00a0fue recientemente elegido por una famosa cadena de supermercados para crear un <strong>tejado verde extensivo<\/strong> en Bolonia: en el proyecto se utilizaron <strong>11.040 piezas,<\/strong> cubriendo una superficie total de unos <strong>3.200 m2.<\/strong>\r\n\r\nEl amplio techo verde realizado con nuestra cubeta para tejados verdes pre-cultivados permite <strong>ahorros en costes y mantenimiento.<\/strong> El sistema no requiere cortes de c\u00e9sped ni tratamientos con pesticidas. Adem\u00e1s de <strong>una fertilizaci\u00f3n semestral\/anual,<\/strong> no se necesita ninguna otra intervenci\u00f3n. En caso de largos per\u00edodos de sequ\u00eda durante el verano, se recomienda el riego de emergencia, para mantener un aspecto floreciente en el techo.\r\n\r\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-67121 size-full\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2017\/11\/Completa_-088.jpg\" alt=\"\" width=\"1240\" height=\"500\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2017\/11\/Completa_-088.jpg 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2017\/11\/Completa_-088-300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2017\/11\/Completa_-088-768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2017\/11\/Completa_-088-1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2017\/11\/Completa_-088-224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2017\/11\/Completa_-088-124x50.jpg 124w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n\r\n<a href=\"https:\/\/www.geoplastglobal.com\/it\/prodotti\/verde\/completa\/\" target=\"_blank\" rel=\"noopener\">Completa<\/a> es tambi\u00e9n muy f\u00e1cil de instalar: los m\u00f3dulos se colocan y conectan entre s\u00ed a trav\u00e9s del sistema de acoplamiento doblemente solapado. Una vez finalizada la instalaci\u00f3n en obra, es necesario regar abundantemente toda la superficie hasta alcanzar la saturaci\u00f3n del suelo.\r\n\r\nLos beneficios garantizados por un amplio techo verde son varios: absorbe la mayor parte de las precipitaciones, protege la cobertura y a\u00edsla t\u00e9rmicamente el edificio. Manteniendo una temperatura estable, tambi\u00e9n puede mejorar el rendimiento de los paneles fotovoltaicos.","protected":false},"excerpt":{"rendered":"<p>Completa de Geoplast es la \u00faltima generaci\u00f3n de sedum pre-cultivado para tejados verdes extensivos, que se pueden f\u00e1cilmente instalar tanto sobre superficies planas, como sobre techos inclinados , porque son extremamente ligeros (60 kg\/metro cuadrado en condiciones de saturaci\u00f3n de agua). El producto no requiere un mantenimiento particular y se [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":67114,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[108],"tags":[501,500,952,493,498,422],"class_list":["post-52099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-verde-es","tag-bolonia","tag-supermercado","tag-techos-jardines","tag-tejado-verde","tag-tejado-verde-extensivo","tag-verde"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caso de estudio Completa: un nuevo tejado verde extensivo en Bolonia &#8211; Geoplast<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/es\/blog\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caso de estudio Completa: un nuevo tejado verde extensivo en Bolonia &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Completa de Geoplast es la \u00faltima generaci\u00f3n de sedum pre-cultivado para tejados verdes extensivos, que se pueden f\u00e1cilmente instalar tanto sobre superficies planas, como sobre techos inclinados , porque son extremamente ligeros (60 kg\/metro cuadrado en condiciones de saturaci\u00f3n de agua). El producto no requiere un mantenimiento particular y se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/es\/blog\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-28T10:22:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-15T10:05:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2017\/11\/Completa_-083.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nikola Tosic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nikola Tosic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\\\/\"},\"author\":{\"name\":\"Nikola Tosic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/0feabc79985006722a394123a98c8065\"},\"headline\":\"Caso de estudio Completa: un nuevo tejado verde extensivo en Bolonia\",\"datePublished\":\"2017-11-28T10:22:01+00:00\",\"dateModified\":\"2022-04-15T10:05:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\\\/\"},\"wordCount\":275,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Completa_-083.jpg\",\"keywords\":[\"Bolonia\",\"supermercado\",\"techos jardines\",\"tejado verde\",\"tejado verde extensivo\",\"verde\"],\"articleSection\":[\"Verde\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\\\/\",\"name\":\"Caso de estudio Completa: un nuevo tejado verde extensivo en Bolonia &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Completa_-083.jpg\",\"datePublished\":\"2017-11-28T10:22:01+00:00\",\"dateModified\":\"2022-04-15T10:05:51+00:00\",\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Completa_-083.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Completa_-083.jpg\",\"width\":1240,\"height\":500},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/0feabc79985006722a394123a98c8065\",\"name\":\"Nikola Tosic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g\",\"caption\":\"Nikola Tosic\"},\"sameAs\":[\"https:\\\/\\\/www.geoplastglobal.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caso de estudio Completa: un nuevo tejado verde extensivo en Bolonia &#8211; Geoplast","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/es\/blog\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\/","og_locale":"es_ES","og_type":"article","og_title":"Caso de estudio Completa: un nuevo tejado verde extensivo en Bolonia &#8211; Geoplast","og_description":"Completa de Geoplast es la \u00faltima generaci\u00f3n de sedum pre-cultivado para tejados verdes extensivos, que se pueden f\u00e1cilmente instalar tanto sobre superficies planas, como sobre techos inclinados , porque son extremamente ligeros (60 kg\/metro cuadrado en condiciones de saturaci\u00f3n de agua). El producto no requiere un mantenimiento particular y se [&hellip;]","og_url":"https:\/\/www.geoplastglobal.com\/es\/blog\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2017-11-28T10:22:01+00:00","article_modified_time":"2022-04-15T10:05:51+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2017\/11\/Completa_-083.jpg","type":"image\/jpeg"}],"author":"Nikola Tosic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Nikola Tosic","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\/"},"author":{"name":"Nikola Tosic","@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/person\/0feabc79985006722a394123a98c8065"},"headline":"Caso de estudio Completa: un nuevo tejado verde extensivo en Bolonia","datePublished":"2017-11-28T10:22:01+00:00","dateModified":"2022-04-15T10:05:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\/"},"wordCount":275,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2017\/11\/Completa_-083.jpg","keywords":["Bolonia","supermercado","techos jardines","tejado verde","tejado verde extensivo","verde"],"articleSection":["Verde"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\/","url":"https:\/\/www.geoplastglobal.com\/es\/blog\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\/","name":"Caso de estudio Completa: un nuevo tejado verde extensivo en Bolonia &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2017\/11\/Completa_-083.jpg","datePublished":"2017-11-28T10:22:01+00:00","dateModified":"2022-04-15T10:05:51+00:00","inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/es\/blog\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/caso-de-estudio-completa-un-nuevo-tejado-verde-extensivo-en-bolonia\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2017\/11\/Completa_-083.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2017\/11\/Completa_-083.jpg","width":1240,"height":500},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/es\/#website","url":"https:\/\/www.geoplastglobal.com\/es\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/es\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/person\/0feabc79985006722a394123a98c8065","name":"Nikola Tosic","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a93b5cb5354f871f2611710a7374ffac5d4dbadce7f9ff39f242a7e5040387d?s=96&d=mm&r=g","caption":"Nikola Tosic"},"sameAs":["https:\/\/www.geoplastglobal.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts\/52099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/comments?post=52099"}],"version-history":[{"count":7,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts\/52099\/revisions"}],"predecessor-version":[{"id":68489,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts\/52099\/revisions\/68489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/media\/67114"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/media?parent=52099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/categories?post=52099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/tags?post=52099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}