
{"id":221344,"date":"2026-04-23T10:23:55","date_gmt":"2026-04-23T10:23:55","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/?p=221344"},"modified":"2026-04-23T10:23:55","modified_gmt":"2026-04-23T10:23:55","slug":"nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/es\/blog\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\/","title":{"rendered":"Nuevo Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi"},"content":{"rendered":"<ul class=\"first-ul-intro\">\r\n \t<li style=\"list-style-type: none;\">\r\n<ul class=\"first-ul-intro\">\r\n \t<li style=\"list-style-type: none; text-align: left;\">\r\n<h2><b>Las zonas s\u00edsmicas aumentan el riesgo de da\u00f1os estructurales en los edificios causados por terremotos.<\/b><\/h2>\r\n<\/li>\r\n \t<li style=\"list-style-type: none; text-align: left;\">\r\n<h2>Studio <a href=\"https:\/\/www.giuseppepassaroarchitetto.com\/\">Giuseppe Passaro Architects<\/a> &amp; <a href=\"https:\/\/www.engineeringcostruzioni.it\/\">Engineering Costruzioni<\/a> implement\u00f3 una soluci\u00f3n de resistencia estructural en el edificio de oficinas de <a href=\"https:\/\/www.geoplastglobal.com\/es\/proyectos\/oficina-de-gruppo-grassi\/\">Gruppo Grassi<\/a>.<\/h2>\r\n<\/li>\r\n \t<li style=\"list-style-type: none; text-align: left;\">\r\n<h2><a href=\"https:\/\/www.geoplastglobal.com\/es\/productos\/forjados\/nuevo-nautilus-evo\/\"><b>Nuevo Nautilus Evo<\/b><\/a><b> redujo el uso de hormig\u00f3n, mejorando la resistencia s\u00edsmica y el rendimiento estructural general.<\/b><\/h2>\r\n<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<p style=\"text-align: center;\"><a class=\"btn\" href=\"https:\/\/www.geoplastglobal.com\/es\/proyectos\/oficina-de-gruppo-grassi\/\"><b>VER PROYECTO<\/b><\/a><\/p>\r\n&nbsp;\r\n&nbsp;\r\n<h3><b>Las zonas s\u00edsmicas aumentan las exigencias estructurales<\/b><\/h3>\r\n&nbsp;\r\n\r\n<span style=\"font-weight: 400;\">En zonas s\u00edsmicas como Montemurlo, Italia, los edificios est\u00e1n <strong>expuestos a un mayor riesgo de da\u00f1os estructurales durante los terremotos<\/strong>. <\/span>\r\n\r\n&nbsp;\r\n\r\n<span style=\"font-weight: 400;\">Estos eventos pueden provocar grietas y deformaciones en los elementos estructurales y, en casos graves, fallos parciales o totales. <strong>Garantizar la respuesta m\u00e1s segura del edificio ante fuerzas din\u00e1micas es<\/strong> <strong>esencial para prevenir da\u00f1os a largo plazo.<\/strong><\/span>\r\n\r\n&nbsp;\r\n\r\n&nbsp;\r\n<h3><b>Una soluci\u00f3n centrada en la resistencia para un proyecto complejo<\/b><\/h3>\r\n&nbsp;\r\n\r\n<span style=\"font-weight: 400;\">Para el <\/span><a href=\"https:\/\/www.geoplastglobal.com\/es\/proyectos\/oficina-de-gruppo-grassi\/\"><span style=\"font-weight: 400;\">Gruppo Grassi office<\/span><\/a><span style=\"font-weight: 400;\"> edificio, Studio <\/span><a href=\"https:\/\/www.giuseppepassaroarchitetto.com\/\"><span style=\"font-weight: 400;\">Giuseppe Passaro Architects<\/span><\/a><span style=\"font-weight: 400;\"> &amp; <\/span><a href=\"https:\/\/www.engineeringcostruzioni.it\/\"><span style=\"font-weight: 400;\">Engineering Costruzioni<\/span><\/a><span style=\"font-weight: 400;\"> seleccion\u00f3 <\/span><a href=\"https:\/\/www.geoplastglobal.com\/es\/productos\/forjados\/nuevo-nautilus-evo\/\"><span style=\"font-weight: 400;\">Nuevo Nautilus Evo<\/span><\/a><span style=\"font-weight: 400;\">, una soluci\u00f3n enfocada en el rendimiento estructural y la ejecuci\u00f3n pr\u00e1ctica en obra. <\/span>\r\n\r\n<span style=\"font-weight: 400;\">Los principales desaf\u00edos fueron: <\/span>\r\n<ul>\r\n \t<li><span style=\"font-weight: 400;\">ubicaci\u00f3n en zona s\u00edsmica,<\/span><\/li>\r\n \t<li><span style=\"font-weight: 400;\">geometr\u00eda irregular del edificio,<\/span><\/li>\r\n \t<li><span style=\"font-weight: 400;\">puntos de apoyo a diferentes alturas debido a la configuraci\u00f3n del terreno.<\/span><\/li>\r\n<\/ul>\r\n&nbsp;\r\n\r\n<strong>En este contexto, <a href=\"https:\/\/www.geoplastglobal.com\/es\/productos\/forjados\/nuevo-nautilus-evo\/\">Nuevo Nautilus Evo<\/a> contribuy\u00f3 a un rendimiento estructural m\u00e1s eficiente, adapt\u00e1ndose a la complejidad del proyecto.<\/strong>\r\n\r\n&nbsp;\r\n\r\n&nbsp;\r\n<h3><b>Reducci\u00f3n del hormig\u00f3n para mejorar el rendimiento estructural<\/b><\/h3>\r\n&nbsp;\r\n\r\n<a href=\"https:\/\/www.geoplastglobal.com\/es\/productos\/forjados\/nuevo-nautilus-evo\/\"><span style=\"font-weight: 400;\">Nuevo Nautilus Evo<\/span><\/a><span style=\"font-weight: 400;\"> se utiliz\u00f3 para <strong>reducir el volumen de hormig\u00f3n<\/strong> creando vac\u00edos donde el material no es estructuralmente necesario. <\/span>\r\n\r\n<span style=\"font-weight: 400;\"><strong>Reducir la masa es una estrategia eficaz para mejorar la resistencia s\u00edsmica<\/strong> al disminuir las fuerzas de inercia y las tensiones en los elementos estructurales clave. <\/span>\r\n\r\n<span style=\"font-weight: 400;\">De este modo, la soluci\u00f3n contribuy\u00f3 a mejorar el rendimiento estructural global bajo las condiciones s\u00edsmicas de esta zona.<\/span>\r\n\r\n&nbsp;\r\n\r\n&nbsp;\r\n<h3><a href=\"https:\/\/www.geoplastglobal.com\/es\/contactos\/\"><b>Contacte con Geoplast<\/b><\/a><b> para hablar de su pr\u00f3ximo proyecto.<\/b><\/h3>","protected":false},"excerpt":{"rendered":"<p>Las zonas s\u00edsmicas aumentan el riesgo de da\u00f1os estructurales en los edificios causados por terremotos. Studio Giuseppe Passaro Architects &amp; Engineering Costruzioni implement\u00f3 una soluci\u00f3n de resistencia estructural en el edificio de oficinas de Gruppo Grassi. Nuevo Nautilus Evo redujo el uso de hormig\u00f3n, mejorando la resistencia s\u00edsmica y el [&hellip;]<\/p>\n","protected":false},"author":54,"featured_media":221346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[105],"tags":[437,3406,3546],"class_list":["post-221344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectos-es","tag-forjados","tag-new-nautilus-evo-es","tag-reduccion-de-hormigon"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuevo Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi &#8211; Geoplast<\/title>\n<meta name=\"description\" content=\"Nuevo Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi al reducir la masa de hormig\u00f3n y mejorar el rendimiento estructural en la zona s\u00edsmica de Montemurlo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/es\/blog\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevo Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Nuevo Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi al reducir la masa de hormig\u00f3n y mejorar el rendimiento estructural en la zona s\u00edsmica de Montemurlo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/es\/blog\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-23T10:23:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2026\/04\/es-gruppo-grassi-office-new-nautilus-evo-helped-improve-seismic-resistance.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Natalija Jevtic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natalija Jevtic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\\\/\"},\"author\":{\"name\":\"Natalija Jevtic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/99b3780d7d45df95c951b1f8ae8da531\"},\"headline\":\"Nuevo Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi\",\"datePublished\":\"2026-04-23T10:23:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\\\/\"},\"wordCount\":342,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/es-gruppo-grassi-office-new-nautilus-evo-helped-improve-seismic-resistance.jpg\",\"keywords\":[\"forjados\",\"New Nautilus Evo\",\"Reducci\u00f3n de hormig\u00f3n\"],\"articleSection\":[\"Proyectos\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\\\/\",\"name\":\"Nuevo Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/es-gruppo-grassi-office-new-nautilus-evo-helped-improve-seismic-resistance.jpg\",\"datePublished\":\"2026-04-23T10:23:55+00:00\",\"description\":\"Nuevo Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi al reducir la masa de hormig\u00f3n y mejorar el rendimiento estructural en la zona s\u00edsmica de Montemurlo.\",\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/es-gruppo-grassi-office-new-nautilus-evo-helped-improve-seismic-resistance.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/es-gruppo-grassi-office-new-nautilus-evo-helped-improve-seismic-resistance.jpg\",\"width\":1240,\"height\":500,\"caption\":\"New Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/99b3780d7d45df95c951b1f8ae8da531\",\"name\":\"Natalija Jevtic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3a0686092447b5f3f6557ab1ed1afe0d0533ace526005b5ad70d9abf1a454c9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3a0686092447b5f3f6557ab1ed1afe0d0533ace526005b5ad70d9abf1a454c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3a0686092447b5f3f6557ab1ed1afe0d0533ace526005b5ad70d9abf1a454c9?s=96&d=mm&r=g\",\"caption\":\"Natalija Jevtic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevo Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi &#8211; Geoplast","description":"Nuevo Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi al reducir la masa de hormig\u00f3n y mejorar el rendimiento estructural en la zona s\u00edsmica de Montemurlo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/es\/blog\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\/","og_locale":"es_ES","og_type":"article","og_title":"Nuevo Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi &#8211; Geoplast","og_description":"Nuevo Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi al reducir la masa de hormig\u00f3n y mejorar el rendimiento estructural en la zona s\u00edsmica de Montemurlo.","og_url":"https:\/\/www.geoplastglobal.com\/es\/blog\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2026-04-23T10:23:55+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2026\/04\/es-gruppo-grassi-office-new-nautilus-evo-helped-improve-seismic-resistance.jpg","type":"image\/jpeg"}],"author":"Natalija Jevtic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Natalija Jevtic","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\/"},"author":{"name":"Natalija Jevtic","@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/person\/99b3780d7d45df95c951b1f8ae8da531"},"headline":"Nuevo Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi","datePublished":"2026-04-23T10:23:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\/"},"wordCount":342,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2026\/04\/es-gruppo-grassi-office-new-nautilus-evo-helped-improve-seismic-resistance.jpg","keywords":["forjados","New Nautilus Evo","Reducci\u00f3n de hormig\u00f3n"],"articleSection":["Proyectos"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\/","url":"https:\/\/www.geoplastglobal.com\/es\/blog\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\/","name":"Nuevo Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2026\/04\/es-gruppo-grassi-office-new-nautilus-evo-helped-improve-seismic-resistance.jpg","datePublished":"2026-04-23T10:23:55+00:00","description":"Nuevo Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi al reducir la masa de hormig\u00f3n y mejorar el rendimiento estructural en la zona s\u00edsmica de Montemurlo.","inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/es\/blog\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/nautilus-evo-mejora-la-resistencia-sismica-en-las-oficinas-de-gruppo-grassi\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2026\/04\/es-gruppo-grassi-office-new-nautilus-evo-helped-improve-seismic-resistance.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2026\/04\/es-gruppo-grassi-office-new-nautilus-evo-helped-improve-seismic-resistance.jpg","width":1240,"height":500,"caption":"New Nautilus Evo mejora la resistencia s\u00edsmica en las oficinas de Gruppo Grassi"},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/es\/#website","url":"https:\/\/www.geoplastglobal.com\/es\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/es\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/person\/99b3780d7d45df95c951b1f8ae8da531","name":"Natalija Jevtic","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/d3a0686092447b5f3f6557ab1ed1afe0d0533ace526005b5ad70d9abf1a454c9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d3a0686092447b5f3f6557ab1ed1afe0d0533ace526005b5ad70d9abf1a454c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d3a0686092447b5f3f6557ab1ed1afe0d0533ace526005b5ad70d9abf1a454c9?s=96&d=mm&r=g","caption":"Natalija Jevtic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts\/221344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/comments?post=221344"}],"version-history":[{"count":1,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts\/221344\/revisions"}],"predecessor-version":[{"id":221370,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts\/221344\/revisions\/221370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/media\/221346"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/media?parent=221344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/categories?post=221344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/tags?post=221344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}