
{"id":189069,"date":"2023-11-21T10:29:49","date_gmt":"2023-11-21T10:29:49","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/blog\/3-formwork-projects-in-inaccessible-locations\/"},"modified":"2023-11-23T09:34:06","modified_gmt":"2023-11-23T09:34:06","slug":"3-proyectos-con-encofrado-en-obras-de-dificil-acceso","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/es\/blog\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\/","title":{"rendered":"3 proyectos con encofrado en obras de dif\u00edcil acceso"},"content":{"rendered":"<style>\r\n.columns-wrapper-post {\r\n\tdisplay: flex;\r\n\tflex-flow: row wrap;\r\n\tjustify-content: space-between;\r\n\trow-gap: 100px;\r\n\tcolumn-gap: 30px;\r\n\tpadding-top: 90px;\r\n\tpadding-bottom: 60px;\r\n}\r\n.column-post {\r\n\tflex-basis: 1;\r\n\twidth: calc(50% - 20px);\r\n}\r\n.column-post h3 {\r\n\tmargin-top: 0px !important;\r\n}\r\n.post-title {\r\n        font-size:40px;\r\n}\r\n.post-text {\r\n        font-size:30px;\r\n}\r\n.single-post .body iframe {\r\n\theight:250px !important;\r\n}\r\n.columns-video-wrapper {\r\n\tposition: relative !important; \r\n\tpadding-bottom: 40.32% !important;\r\n\theight: 0 !important;\r\nmargin-top: 17px;\r\n}\r\n.column-post-text {margin-top: -22px;}\r\n.post-text-subtitle {line-height: 2;}\r\n.single-post .body iframe {\r\n\tposition: absolute !important; \r\n\ttop: 0 !important;\r\n\tleft: 0 !important;\r\n\twidth: 100% !important;\r\n\theight: 100% !important;\r\n}\r\n.single-post a.button--cat-l{\r\nmargin-top: 30px !important;\r\n    color: #f5842b;\r\n    text-decoration: none;\r\n    text-transform: uppercase;\r\n    text-decoration: none;\r\n    display: grid;\r\n    place-items: center;\r\n    background-color: #f5842b;\r\n    color: white !important;\r\n    padding: 10px 20px;\r\n    width: max-content;\r\n    margin-top: 8px;\r\n    font-size: large;\r\n    max-width: 100%;\r\n    text-align: center;\r\n    min-height: 50px;\r\n}\r\n.single-post a.button--cat-l:hover{\r\nbackground-color: #16478b;\r\ncolor: white !important;\r\n}\r\n@media screen and (max-width: 1000px) {\r\n    .columns-wrapper-post {\r\n\t\trow-gap: 50px;\r\n\t\tcolumn-gap: 20px;\r\n\t\tpadding-top: 50px;\r\n\t\tpadding-bottom: 50px;\r\n\t}\r\n\t\t.single-post p {\r\n\t\tpadding-top: 10px !important;\r\n\t}\r\n}\r\n@media screen and (max-width: 800px) {\r\n    .columns-wrapper-post {\r\n\t\trow-gap: 30px;\r\n\t\tpadding-top: 40px;\r\n\t\tpadding-bottom: 40px;\r\n\t}\r\n    .column-post {\r\n\t\tflex-basis: 1;\r\n\t\twidth: 100%;\r\n\t}\r\n\t.single-post .body h3 {\r\n\t\tmargin-top: -15px !important;\r\n\t}\r\n}\r\n<\/style>\r\n\r\n<div class=\"post-text\">\r\nEn comparaci\u00f3n con las alternativas de madera y metal, el encofrado de pl\u00e1stico reciclado de Geoplast es ligero, compacto y f\u00e1cil de maniobrar en espacios reducidos y lo pueden hacer los obreros de manera individual. Estas  caracter\u00edsticas son cruciales cuando se trabaja en obras de dif\u00edcil acceso con espacio limitado y sin acceso a  maquinaria pesada. A continuaci\u00f3n pueden ver 3 proyectos mejorados con <a href=\"https:\/\/www.geoplastglobal.com\/es\/productos\/encofrados\/geotub\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geotub<\/a> y <a href=\"https:\/\/www.geoplastglobal.com\/es\/productos\/encofrados\/geopanel\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geopanel<\/a>.\r\n<\/div>\r\n\r\n<div class=\"columns-wrapper-post\">\r\n<div class=\"column-post\">\r\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/1-Muele-marino-Pozzuoli.jpg\" alt=\"1 Muele marino, Pozzuoli\" width=\"1080\" height=\"1080\" class=\"alignnone size-full wp-image-189079\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/1-Muele-marino-Pozzuoli.jpg 1080w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/1-Muele-marino-Pozzuoli-300x300.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/1-Muele-marino-Pozzuoli-1024x1024.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/1-Muele-marino-Pozzuoli-150x150.jpg 150w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/1-Muele-marino-Pozzuoli-768x768.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/1-Muele-marino-Pozzuoli-224x224.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/1-Muele-marino-Pozzuoli-50x50.jpg 50w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\r\n\t<\/div>\r\n\t<div class=\"column-post column-post-text\">\r\n\t\t<span class=\"post-title\"><strong><a href=\"https:\/\/www.geoplastglobal.com\/es\/proyectos\/reconstruccin-del-muelle-pozzuoli-italia\/\" rel=\"noopener noreferrer\" target=\"_blank\">Muele marino, Pozzuoli<\/a><\/strong><\/span>\r\n\t\t<span class=\"post-text post-text-subtitle\"><strong>Geotub<\/strong><\/span>\r\n\t\t<span class=\"post-text\">La obra en Pozzuoli consisti\u00f3 en reconstruir columnas redondas bajo el muelle marino que fueron sumergidas. Geotub permiti\u00f3 la colocaci\u00f3n lateral y fue resistente al agua, proporcionando una reconstrucci\u00f3n del muelle eficiente y dentro de los plazos previstos.<\/span> \r\n<a class=\"button--cat-l\" href=\"https:\/\/www.geoplastglobal.com\/es\/proyectos\/reconstruccin-del-muelle-pozzuoli-italia\/\" target=\"_blank\" rel=\"noopener\">M\u00c1S SOBRE ESTE PROYECTO<\/a>\r\n\t<\/div>\r\n\r\n<div class=\"column-post\">\r\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/2-Puerto-Quai-Napoles.jpg\" alt=\"2 Puerto Quai, N\u00e1poles\" width=\"1080\" height=\"1080\" class=\"alignnone size-full wp-image-189087\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/2-Puerto-Quai-Napoles.jpg 1080w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/2-Puerto-Quai-Napoles-300x300.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/2-Puerto-Quai-Napoles-1024x1024.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/2-Puerto-Quai-Napoles-150x150.jpg 150w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/2-Puerto-Quai-Napoles-768x768.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/2-Puerto-Quai-Napoles-224x224.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/2-Puerto-Quai-Napoles-50x50.jpg 50w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\r\n\t<\/div>\r\n\t<div class=\"column-post column-post-text\">\r\n\t\t<span class=\"post-title\"><strong><a href=\"https:\/\/www.geoplastglobal.com\/es\/proyectos\/puerto-de-npoles-quai-npoles-italia-\/\" rel=\"noopener noreferrer\" target=\"_blank\">Puerto Quai, N\u00e1poles<\/a><\/strong><\/span>\r\n\t\t<span class=\"post-text post-text-subtitle\"><strong>Geopanel<\/strong><\/span>\r\n\t\t<span class=\"post-text\">La obra en N\u00e1poles se encontraba en un estrecho muelle mar\u00edtimo delimitado por el espacio de almacenamiento a un  lado y el mar al otro. Los paneles de encofrado de Geopanel fueron livianos, por lo que resultaba seguro instalarlos en  un estrecho andamio sobre el agua.<\/span> \r\n<a class=\"button--cat-l\" href=\"https:\/\/www.geoplastglobal.com\/es\/proyectos\/puerto-de-npoles-quai-npoles-italia-\/\" target=\"_blank\" rel=\"noopener\">M\u00c1S SOBRE ESTE PROYECTO<\/a>\r\n\t<\/div>\r\n\r\n<div class=\"column-post\">\r\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/3-Autopista-de-peaje-Miami.jpg\" alt=\"3 Autopista de peaje, Miami\" width=\"1080\" height=\"1080\" class=\"alignnone size-full wp-image-189095\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/3-Autopista-de-peaje-Miami.jpg 1080w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/3-Autopista-de-peaje-Miami-300x300.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/3-Autopista-de-peaje-Miami-1024x1024.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/3-Autopista-de-peaje-Miami-150x150.jpg 150w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/3-Autopista-de-peaje-Miami-768x768.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/3-Autopista-de-peaje-Miami-224x224.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/3-Autopista-de-peaje-Miami-50x50.jpg 50w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\r\n\t<\/div>\r\n\t<div class=\"column-post column-post-text\">\r\n\t\t<span class=\"post-title\"><strong><a href=\"https:\/\/www.geoplastglobal.com\/es\/proyectos\/columnas-redondas-para-la-autopista-turnipike-con-geotub\/\" rel=\"noopener noreferrer\" target=\"_blank\">Autopista de peaje, Miami<\/a><\/strong><\/span>\r\n\t\t<span class=\"post-text post-text-subtitle\"><strong>Geotub<\/strong><\/span>\r\n\t\t<span class=\"post-text\">Geotub fue utilizado para la construcci\u00f3n de una serie de columnas redondas debajo del puente que cruzaba la  Autopista de Peaje en Florida. Geotub no requiri\u00f3 gr\u00faas ni equipos mec\u00e1nicos, dejando el tr\u00e1fico de la autopista  ininterrumpido durante la construcci\u00f3n.<\/span> \r\n<a class=\"button--cat-l\" href=\"https:\/\/www.geoplastglobal.com\/es\/proyectos\/columnas-redondas-para-la-autopista-turnipike-con-geotub\/\" target=\"_blank\" rel=\"noopener\">M\u00c1S SOBRE ESTE PROYECTO<\/a>\r\n\t<\/div>\r\n\r\n<\/div>\r\n\r\n","protected":false},"excerpt":{"rendered":"<p>En comparaci\u00f3n con las alternativas de madera y metal, el encofrado de pl\u00e1stico reciclado de Geoplast es ligero, compacto y f\u00e1cil de maniobrar en espacios reducidos y lo pueden hacer los obreros de manera individual. Estas caracter\u00edsticas son cruciales cuando se trabaja en obras de dif\u00edcil acceso con espacio limitado [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":189071,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[106],"tags":[4127,1082],"class_list":["post-189069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-encofrados-es","tag-encofrados-de-plastico-reciclado","tag-soluciones-de-encofrado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3 proyectos con encofrado en obras de dif\u00edcil acceso &#8211; Geoplast<\/title>\n<meta name=\"description\" content=\"El encofrado de pl\u00e1stico reciclado de Geoplast es ligero y compacto, por lo que es perfecto para obras de dif\u00edcil acceso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/es\/blog\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 proyectos con encofrado en obras de dif\u00edcil acceso &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"El encofrado de pl\u00e1stico reciclado de Geoplast es ligero y compacto, por lo que es perfecto para obras de dif\u00edcil acceso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/es\/blog\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-21T10:29:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-23T09:34:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jelena Zivancevic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jelena Zivancevic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\\\/\"},\"author\":{\"name\":\"Jelena Zivancevic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\"},\"headline\":\"3 proyectos con encofrado en obras de dif\u00edcil acceso\",\"datePublished\":\"2023-11-21T10:29:49+00:00\",\"dateModified\":\"2023-11-23T09:34:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\\\/\"},\"wordCount\":243,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso.jpg\",\"keywords\":[\"encofrados de pl\u00e1stico reciclado\",\"soluciones de encofrado\"],\"articleSection\":[\"Encofrados\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\\\/\",\"name\":\"3 proyectos con encofrado en obras de dif\u00edcil acceso &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso.jpg\",\"datePublished\":\"2023-11-21T10:29:49+00:00\",\"dateModified\":\"2023-11-23T09:34:06+00:00\",\"description\":\"El encofrado de pl\u00e1stico reciclado de Geoplast es ligero y compacto, por lo que es perfecto para obras de dif\u00edcil acceso.\",\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso.jpg\",\"width\":1240,\"height\":500,\"caption\":\"3 proyectos con encofrado en obras de dif\u00edcil acceso\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\",\"name\":\"Jelena Zivancevic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"caption\":\"Jelena Zivancevic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 proyectos con encofrado en obras de dif\u00edcil acceso &#8211; Geoplast","description":"El encofrado de pl\u00e1stico reciclado de Geoplast es ligero y compacto, por lo que es perfecto para obras de dif\u00edcil acceso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/es\/blog\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\/","og_locale":"es_ES","og_type":"article","og_title":"3 proyectos con encofrado en obras de dif\u00edcil acceso &#8211; Geoplast","og_description":"El encofrado de pl\u00e1stico reciclado de Geoplast es ligero y compacto, por lo que es perfecto para obras de dif\u00edcil acceso.","og_url":"https:\/\/www.geoplastglobal.com\/es\/blog\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2023-11-21T10:29:49+00:00","article_modified_time":"2023-11-23T09:34:06+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso.jpg","type":"image\/jpeg"}],"author":"Jelena Zivancevic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Jelena Zivancevic","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\/"},"author":{"name":"Jelena Zivancevic","@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad"},"headline":"3 proyectos con encofrado en obras de dif\u00edcil acceso","datePublished":"2023-11-21T10:29:49+00:00","dateModified":"2023-11-23T09:34:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\/"},"wordCount":243,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso.jpg","keywords":["encofrados de pl\u00e1stico reciclado","soluciones de encofrado"],"articleSection":["Encofrados"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\/","url":"https:\/\/www.geoplastglobal.com\/es\/blog\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\/","name":"3 proyectos con encofrado en obras de dif\u00edcil acceso &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso.jpg","datePublished":"2023-11-21T10:29:49+00:00","dateModified":"2023-11-23T09:34:06+00:00","description":"El encofrado de pl\u00e1stico reciclado de Geoplast es ligero y compacto, por lo que es perfecto para obras de dif\u00edcil acceso.","inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/es\/blog\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/11\/3-proyectos-con-encofrado-en-obras-de-dificil-acceso.jpg","width":1240,"height":500,"caption":"3 proyectos con encofrado en obras de dif\u00edcil acceso"},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/es\/#website","url":"https:\/\/www.geoplastglobal.com\/es\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/es\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad","name":"Jelena Zivancevic","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","caption":"Jelena Zivancevic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts\/189069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/comments?post=189069"}],"version-history":[{"count":2,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts\/189069\/revisions"}],"predecessor-version":[{"id":189103,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts\/189069\/revisions\/189103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/media\/189071"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/media?parent=189069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/categories?post=189069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/tags?post=189069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}