
{"id":180269,"date":"2023-03-01T13:58:54","date_gmt":"2023-03-01T13:58:54","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/blog\/increase-construction-circularity-with-geoplast\/"},"modified":"2023-03-02T11:14:49","modified_gmt":"2023-03-02T11:14:49","slug":"aumente-la-circularidad-en-la-construccion-con-geoplast","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/es\/blog\/aumente-la-circularidad-en-la-construccion-con-geoplast\/","title":{"rendered":"Aumente la circularidad en la construcci\u00f3n con Geoplast"},"content":{"rendered":"La circularidad implica utilizar los recursos el mayor tiempo posible, extraer su m\u00e1ximo valor y darles un nuevo uso al  final de su ciclo de vida. Los productos de Geoplast le permiten aplicar estas 3 estrategias fundamentales para  aumentar la circularidad en la construcci\u00f3n.  \r\n\r\n<span class=\"font-XL\">Renovar <\/span>\r\nLa renovaci\u00f3n prolonga la vida de los edificios existentes, reduciendo los residuos de demolici\u00f3n. Productos como <a href=\"https:\/\/www.geoplastglobal.com\/es\/productos\/encofrados\/geotub\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geotub<\/a> y <a href=\"https:\/\/www.geoplastglobal.com\/es\/productos\/encofrados\/geotub-panel\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geotub Panel<\/a> est\u00e1n hechos para renovaciones \u2013 son livianos y se fabrican en dimensiones manejables  adecuadas para la instalaci\u00f3n manual en espacios peque\u00f1os. \r\n\r\n<span class=\"font-XL\">Utilizar menos material <\/span>\r\nReducir el carbono incorporado es crucial para aumentar la circularidad en el sector de la construcci\u00f3n. Productos para <a href=\"https:\/\/www.geoplastglobal.com\/es\/productos\/cimientos\/\" rel=\"noopener noreferrer\" target=\"_blank\">cimientos<\/a> y <a href=\"https:\/\/www.geoplastglobal.com\/es\/productos\/forjados\/\" rel=\"noopener noreferrer\" target=\"_blank\">forjados<\/a> como <a href=\"https:\/\/www.geoplastglobal.com\/es\/productos\/cimientos\/modulo\/\" rel=\"noopener noreferrer\" target=\"_blank\">Modulo<\/a> y <a href=\"https:\/\/www.geoplastglobal.com\/es\/productos\/forjados\/skyrail\/\" rel=\"noopener noreferrer\" target=\"_blank\">Skyrail<\/a> sustituyen hormig\u00f3n con alto contenido de carbono y los rellenos con  espacios vac\u00edos, limitando su uso en los edificios nuevos.\r\n\r\n<span class=\"font-XL\">Utilizar soluciones recicladas<\/span>\r\nEl reciclaje reduce el abastecimiento y la extracci\u00f3n de materiales v\u00edrgenes no sostenibles. Los productos de Geoplast <a href=\"https:\/\/www.geoplastglobal.com\/es\/productos\/agua\/aquabox\/\" rel=\"noopener noreferrer\" target=\"_blank\">Aquabox<\/a> y <a href=\"https:\/\/www.geoplastglobal.com\/es\/productos\/cimientos\/multimodulo\/\" rel=\"noopener noreferrer\" target=\"_blank\">Multimodulo<\/a>  entre otros, est\u00e1n hechos de residuos pl\u00e1sticos reciclados para aumentar la circularidad en la  construcci\u00f3n.  \r\n\r\n&nbsp;\r\n<a class=\"button--cat-l\" href=\"https:\/\/www.geoplastglobal.com\/es\/contactos\/\" target=\"_blank\" rel=\"noopener\">Cont\u00e1ctenos para aumentar la circularidad en su pr\u00f3ximo proyecto<\/a>","protected":false},"excerpt":{"rendered":"<p>La circularidad implica utilizar los recursos el mayor tiempo posible, extraer su m\u00e1ximo valor y darles un nuevo uso al final de su ciclo de vida. Los productos de Geoplast le permiten aplicar estas 3 estrategias fundamentales para aumentar la circularidad en la construcci\u00f3n. Renovar La renovaci\u00f3n prolonga la vida [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":180245,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3386],"tags":[4151,4150,3517,4028,3612,3611,3425,4152,2050],"class_list":["post-180269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rentabilidad-sostenible","tag-circularidad","tag-circularity-es","tag-construction-industry-es","tag-industria-de-la-construccion","tag-reciclaje","tag-recycling-es","tag-refurbishment-es","tag-rehabilitacion","tag-sustainability-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aumente la circularidad en la construcci\u00f3n con Geoplast &#8211; Geoplast<\/title>\n<meta name=\"description\" content=\"Los productos de Geoplast le permiten aplicar 3 estrategias fundamentales para aumentar la circularidad en la construcci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/es\/blog\/aumente-la-circularidad-en-la-construccion-con-geoplast\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aumente la circularidad en la construcci\u00f3n con Geoplast &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Los productos de Geoplast le permiten aplicar 3 estrategias fundamentales para aumentar la circularidad en la construcci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/es\/blog\/aumente-la-circularidad-en-la-construccion-con-geoplast\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-01T13:58:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-02T11:14:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/Increase-circularity-in-construction-with-Geoplast.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jelena Zivancevic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jelena Zivancevic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/aumente-la-circularidad-en-la-construccion-con-geoplast\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/aumente-la-circularidad-en-la-construccion-con-geoplast\\\/\"},\"author\":{\"name\":\"Jelena Zivancevic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\"},\"headline\":\"Aumente la circularidad en la construcci\u00f3n con Geoplast\",\"datePublished\":\"2023-03-01T13:58:54+00:00\",\"dateModified\":\"2023-03-02T11:14:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/aumente-la-circularidad-en-la-construccion-con-geoplast\\\/\"},\"wordCount\":206,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/aumente-la-circularidad-en-la-construccion-con-geoplast\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Increase-circularity-in-construction-with-Geoplast.jpg\",\"keywords\":[\"circularidad\",\"Circularity\",\"Construction industry\",\"Industria de la construcci\u00f3n\",\"reciclaje\",\"Recycling\",\"Refurbishment\",\"rehabilitaci\u00f3n\",\"Sostenibilidad\"],\"articleSection\":[\"Rentabilidad Sostenible\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/aumente-la-circularidad-en-la-construccion-con-geoplast\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/aumente-la-circularidad-en-la-construccion-con-geoplast\\\/\",\"name\":\"Aumente la circularidad en la construcci\u00f3n con Geoplast &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/aumente-la-circularidad-en-la-construccion-con-geoplast\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/aumente-la-circularidad-en-la-construccion-con-geoplast\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Increase-circularity-in-construction-with-Geoplast.jpg\",\"datePublished\":\"2023-03-01T13:58:54+00:00\",\"dateModified\":\"2023-03-02T11:14:49+00:00\",\"description\":\"Los productos de Geoplast le permiten aplicar 3 estrategias fundamentales para aumentar la circularidad en la construcci\u00f3n.\",\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/aumente-la-circularidad-en-la-construccion-con-geoplast\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/aumente-la-circularidad-en-la-construccion-con-geoplast\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Increase-circularity-in-construction-with-Geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Increase-circularity-in-construction-with-Geoplast.jpg\",\"width\":1240,\"height\":500,\"caption\":\"Increase circularity in construction with Geoplast\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\",\"name\":\"Jelena Zivancevic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"caption\":\"Jelena Zivancevic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aumente la circularidad en la construcci\u00f3n con Geoplast &#8211; Geoplast","description":"Los productos de Geoplast le permiten aplicar 3 estrategias fundamentales para aumentar la circularidad en la construcci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/es\/blog\/aumente-la-circularidad-en-la-construccion-con-geoplast\/","og_locale":"es_ES","og_type":"article","og_title":"Aumente la circularidad en la construcci\u00f3n con Geoplast &#8211; Geoplast","og_description":"Los productos de Geoplast le permiten aplicar 3 estrategias fundamentales para aumentar la circularidad en la construcci\u00f3n.","og_url":"https:\/\/www.geoplastglobal.com\/es\/blog\/aumente-la-circularidad-en-la-construccion-con-geoplast\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2023-03-01T13:58:54+00:00","article_modified_time":"2023-03-02T11:14:49+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/Increase-circularity-in-construction-with-Geoplast.jpg","type":"image\/jpeg"}],"author":"Jelena Zivancevic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Jelena Zivancevic","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/aumente-la-circularidad-en-la-construccion-con-geoplast\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/aumente-la-circularidad-en-la-construccion-con-geoplast\/"},"author":{"name":"Jelena Zivancevic","@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad"},"headline":"Aumente la circularidad en la construcci\u00f3n con Geoplast","datePublished":"2023-03-01T13:58:54+00:00","dateModified":"2023-03-02T11:14:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/aumente-la-circularidad-en-la-construccion-con-geoplast\/"},"wordCount":206,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/aumente-la-circularidad-en-la-construccion-con-geoplast\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/Increase-circularity-in-construction-with-Geoplast.jpg","keywords":["circularidad","Circularity","Construction industry","Industria de la construcci\u00f3n","reciclaje","Recycling","Refurbishment","rehabilitaci\u00f3n","Sostenibilidad"],"articleSection":["Rentabilidad Sostenible"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/aumente-la-circularidad-en-la-construccion-con-geoplast\/","url":"https:\/\/www.geoplastglobal.com\/es\/blog\/aumente-la-circularidad-en-la-construccion-con-geoplast\/","name":"Aumente la circularidad en la construcci\u00f3n con Geoplast &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/aumente-la-circularidad-en-la-construccion-con-geoplast\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/aumente-la-circularidad-en-la-construccion-con-geoplast\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/Increase-circularity-in-construction-with-Geoplast.jpg","datePublished":"2023-03-01T13:58:54+00:00","dateModified":"2023-03-02T11:14:49+00:00","description":"Los productos de Geoplast le permiten aplicar 3 estrategias fundamentales para aumentar la circularidad en la construcci\u00f3n.","inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/es\/blog\/aumente-la-circularidad-en-la-construccion-con-geoplast\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/aumente-la-circularidad-en-la-construccion-con-geoplast\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/Increase-circularity-in-construction-with-Geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/02\/Increase-circularity-in-construction-with-Geoplast.jpg","width":1240,"height":500,"caption":"Increase circularity in construction with Geoplast"},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/es\/#website","url":"https:\/\/www.geoplastglobal.com\/es\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/es\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad","name":"Jelena Zivancevic","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","caption":"Jelena Zivancevic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts\/180269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/comments?post=180269"}],"version-history":[{"count":3,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts\/180269\/revisions"}],"predecessor-version":[{"id":180272,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts\/180269\/revisions\/180272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/media\/180245"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/media?parent=180269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/categories?post=180269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/tags?post=180269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}