
{"id":163355,"date":"2021-06-16T08:03:22","date_gmt":"2021-06-16T08:03:22","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/blog\/sustainability-can-be-profitable-immediately\/"},"modified":"2021-12-09T15:22:38","modified_gmt":"2021-12-09T15:22:38","slug":"la-sostenibilidad-puede-ser-rentable-inmediatamente","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/es\/blog\/la-sostenibilidad-puede-ser-rentable-inmediatamente\/","title":{"rendered":"La sostenibilidad puede ser rentable   inmediatamente"},"content":{"rendered":"La mayor oportunidad en la industria de la construcci\u00f3n hoy en d\u00eda es rentabilizar la sostenibilidad inmediatamente  durante la fase de construcci\u00f3n. \r\n\r\nInversores, arquitectos, ingenieros y empresas de construcci\u00f3n tienen que invertir ahora, pero no pueden esperar  muchos a\u00f1os para obtener el ROI (Retorno de la Inversi\u00f3n). Nuestras soluciones garantizan un aumento de  sostenibilidad junto con un aumento de la rentabilidad en la fase de la construcci\u00f3n. \r\n\r\nHemos previsto este problema y hemos dise\u00f1ado m\u00e1s de 40 productos que se centran en rentabilizar la sostenibilidad. Esto se consigue con nuestros productos de pl\u00e1stico reciclado, probados y f\u00e1ciles de usar.  \r\n\r\nNuestros productos se pueden agregar a todos tipos de proyectos de construcci\u00f3n para reducir el tiempo de  construcci\u00f3n, para reducir el uso de los materiales y la maquinar\u00eda. Juntos, estos tres cambios en el proceso de  construcci\u00f3n aumentan la rentabilidad y mejoran de inmediato la sostenibilidad.  \r\n\r\nUna vez que el proyecto est\u00e1 terminado, nuestros productos tambi\u00e9n reducen el uso de energ\u00eda y aumentan la  resiliencia, haciendo que los proyectos de construcci\u00f3n sean a\u00fan m\u00e1s sostenibles y rentables. \r\n\r\nVemos la necesidad de la construcci\u00f3n sostenible como una de las mayores oportunidades de nuestra generaci\u00f3n. Es  una oportunidad para la salud de nuestro ecosistema, pero tambi\u00e9n para nuestro negocio.  \r\n\r\n<a href=\"mailto:mirco.pegoraro@geoplastglobal.com\">Hable conmigo<\/a> sobre c\u00f3mo hacer su proyecto m\u00e1s <a href=\"https:\/\/www.geoplastglobal.com\/es\/blog\/rentabilidad-sostenible-es-nuestro-enfoque\/\" rel=\"noopener noreferrer\" target=\"_blank\">sostenible Y rentable<\/a>.\r\n","protected":false},"excerpt":{"rendered":"<p>La mayor oportunidad en la industria de la construcci\u00f3n hoy en d\u00eda es rentabilizar la sostenibilidad inmediatamente durante la fase de construcci\u00f3n. Inversores, arquitectos, ingenieros y empresas de construcci\u00f3n tienen que invertir ahora, pero no pueden esperar muchos a\u00f1os para obtener el ROI (Retorno de la Inversi\u00f3n). Nuestras soluciones garantizan [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":153886,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3386],"tags":[3411,3393,2932],"class_list":["post-163355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rentabilidad-sostenible","tag-innovacion","tag-rentabilidad-sostenible","tag-roi-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La sostenibilidad puede ser rentable  inmediatamente &#8211; Geoplast<\/title>\n<meta name=\"description\" content=\"La industria de la construcci\u00f3n tiene hoy la oportunidad de rentabilizar la sostenibilidad inmediatamente durante la fase de construcci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/es\/blog\/la-sostenibilidad-puede-ser-rentable-inmediatamente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La sostenibilidad puede ser rentable  inmediatamente &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"La industria de la construcci\u00f3n tiene hoy la oportunidad de rentabilizar la sostenibilidad inmediatamente durante la fase de construcci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/es\/blog\/la-sostenibilidad-puede-ser-rentable-inmediatamente\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-16T08:03:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-09T15:22:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/06\/Mirco-Pegoraro-CEO-Geoplast-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mirco Pegoraro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mirco Pegoraro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/la-sostenibilidad-puede-ser-rentable-inmediatamente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/la-sostenibilidad-puede-ser-rentable-inmediatamente\\\/\"},\"author\":{\"name\":\"Mirco Pegoraro\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/429475bf4037f4574c7647a775e57105\"},\"headline\":\"La sostenibilidad puede ser rentable inmediatamente\",\"datePublished\":\"2021-06-16T08:03:22+00:00\",\"dateModified\":\"2021-12-09T15:22:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/la-sostenibilidad-puede-ser-rentable-inmediatamente\\\/\"},\"wordCount\":247,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/la-sostenibilidad-puede-ser-rentable-inmediatamente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Mirco-Pegoraro-CEO-Geoplast-1.jpg\",\"keywords\":[\"innovaci\u00f3n\",\"rentabilidad sostenible\",\"ROI\"],\"articleSection\":[\"Rentabilidad Sostenible\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/la-sostenibilidad-puede-ser-rentable-inmediatamente\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/la-sostenibilidad-puede-ser-rentable-inmediatamente\\\/\",\"name\":\"La sostenibilidad puede ser rentable inmediatamente &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/la-sostenibilidad-puede-ser-rentable-inmediatamente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/la-sostenibilidad-puede-ser-rentable-inmediatamente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Mirco-Pegoraro-CEO-Geoplast-1.jpg\",\"datePublished\":\"2021-06-16T08:03:22+00:00\",\"dateModified\":\"2021-12-09T15:22:38+00:00\",\"description\":\"La industria de la construcci\u00f3n tiene hoy la oportunidad de rentabilizar la sostenibilidad inmediatamente durante la fase de construcci\u00f3n.\",\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/la-sostenibilidad-puede-ser-rentable-inmediatamente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/blog\\\/la-sostenibilidad-puede-ser-rentable-inmediatamente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Mirco-Pegoraro-CEO-Geoplast-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Mirco-Pegoraro-CEO-Geoplast-1.jpg\",\"width\":1240,\"height\":500,\"caption\":\"Mirco Pegoraro CEO Geoplast\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/429475bf4037f4574c7647a775e57105\",\"name\":\"Mirco Pegoraro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e47c9a1476a827613d869ba6315c33b9a90a00c66085309c002bf7db53d49b9e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e47c9a1476a827613d869ba6315c33b9a90a00c66085309c002bf7db53d49b9e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e47c9a1476a827613d869ba6315c33b9a90a00c66085309c002bf7db53d49b9e?s=96&d=mm&r=g\",\"caption\":\"Mirco Pegoraro\"},\"sameAs\":[\"https:\\\/\\\/www.geoplastglobal.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La sostenibilidad puede ser rentable  inmediatamente &#8211; Geoplast","description":"La industria de la construcci\u00f3n tiene hoy la oportunidad de rentabilizar la sostenibilidad inmediatamente durante la fase de construcci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/es\/blog\/la-sostenibilidad-puede-ser-rentable-inmediatamente\/","og_locale":"es_ES","og_type":"article","og_title":"La sostenibilidad puede ser rentable  inmediatamente &#8211; Geoplast","og_description":"La industria de la construcci\u00f3n tiene hoy la oportunidad de rentabilizar la sostenibilidad inmediatamente durante la fase de construcci\u00f3n.","og_url":"https:\/\/www.geoplastglobal.com\/es\/blog\/la-sostenibilidad-puede-ser-rentable-inmediatamente\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2021-06-16T08:03:22+00:00","article_modified_time":"2021-12-09T15:22:38+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/06\/Mirco-Pegoraro-CEO-Geoplast-1.jpg","type":"image\/jpeg"}],"author":"Mirco Pegoraro","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Mirco Pegoraro","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/la-sostenibilidad-puede-ser-rentable-inmediatamente\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/la-sostenibilidad-puede-ser-rentable-inmediatamente\/"},"author":{"name":"Mirco Pegoraro","@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/person\/429475bf4037f4574c7647a775e57105"},"headline":"La sostenibilidad puede ser rentable inmediatamente","datePublished":"2021-06-16T08:03:22+00:00","dateModified":"2021-12-09T15:22:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/la-sostenibilidad-puede-ser-rentable-inmediatamente\/"},"wordCount":247,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/la-sostenibilidad-puede-ser-rentable-inmediatamente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/06\/Mirco-Pegoraro-CEO-Geoplast-1.jpg","keywords":["innovaci\u00f3n","rentabilidad sostenible","ROI"],"articleSection":["Rentabilidad Sostenible"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/la-sostenibilidad-puede-ser-rentable-inmediatamente\/","url":"https:\/\/www.geoplastglobal.com\/es\/blog\/la-sostenibilidad-puede-ser-rentable-inmediatamente\/","name":"La sostenibilidad puede ser rentable inmediatamente &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/la-sostenibilidad-puede-ser-rentable-inmediatamente\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/la-sostenibilidad-puede-ser-rentable-inmediatamente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/06\/Mirco-Pegoraro-CEO-Geoplast-1.jpg","datePublished":"2021-06-16T08:03:22+00:00","dateModified":"2021-12-09T15:22:38+00:00","description":"La industria de la construcci\u00f3n tiene hoy la oportunidad de rentabilizar la sostenibilidad inmediatamente durante la fase de construcci\u00f3n.","inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/es\/blog\/la-sostenibilidad-puede-ser-rentable-inmediatamente\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.geoplastglobal.com\/es\/blog\/la-sostenibilidad-puede-ser-rentable-inmediatamente\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/06\/Mirco-Pegoraro-CEO-Geoplast-1.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/06\/Mirco-Pegoraro-CEO-Geoplast-1.jpg","width":1240,"height":500,"caption":"Mirco Pegoraro CEO Geoplast"},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/es\/#website","url":"https:\/\/www.geoplastglobal.com\/es\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/es\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/es\/#\/schema\/person\/429475bf4037f4574c7647a775e57105","name":"Mirco Pegoraro","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/e47c9a1476a827613d869ba6315c33b9a90a00c66085309c002bf7db53d49b9e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e47c9a1476a827613d869ba6315c33b9a90a00c66085309c002bf7db53d49b9e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e47c9a1476a827613d869ba6315c33b9a90a00c66085309c002bf7db53d49b9e?s=96&d=mm&r=g","caption":"Mirco Pegoraro"},"sameAs":["https:\/\/www.geoplastglobal.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts\/163355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/comments?post=163355"}],"version-history":[{"count":2,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts\/163355\/revisions"}],"predecessor-version":[{"id":163357,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/posts\/163355\/revisions\/163357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/media\/153886"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/media?parent=163355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/categories?post=163355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/es\/wp-json\/wp\/v2\/tags?post=163355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}