
{"id":194310,"date":"2024-04-17T07:28:42","date_gmt":"2024-04-17T07:28:42","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/blog\/geoplast-for-sustainable-urban-water-management\/"},"modified":"2024-04-17T12:15:15","modified_gmt":"2024-04-17T12:15:15","slug":"geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\/","title":{"rendered":"Geoplast f\u00fcr ein nachhaltiges st\u00e4dtisches Wassermanagement"},"content":{"rendered":"<style>\r\n.columns-wrapper-post {\r\n\tdisplay: flex;\r\n\tflex-flow: row wrap;\r\n\tjustify-content: space-between;\r\n\trow-gap: 100px;\r\n\tcolumn-gap: 30px;\r\n\tpadding-top: 90px;\r\n\tpadding-bottom: 60px;\r\n}\r\n.column-post {\r\n\tflex-basis: 1;\r\n\twidth: calc(50% - 20px);\r\n}\r\n.column-post h3 {\r\n\tmargin-top: 0px !important;\r\n}\r\n.post-title {\r\n        font-size:35px;\r\nline-height: 1.2;\r\n}\r\n.post-text {\r\n        font-size:22px !important;\r\npadding-top: 30px;\r\n}\r\n.single-post .body iframe {\r\n\theight:250px !important;\r\n}\r\n.columns-video-wrapper {\r\n\tposition: relative !important; \r\n\tpadding-bottom: 40.32% !important;\r\n\theight: 0 !important;\r\nmargin-top: 17px;\r\n}\r\n.column-post-text {margin-top: -8px;}\r\n.post-text-subtitlec{line-height: 2;}\r\n.single-post .body iframe {\r\n\tposition: absolute !important; \r\n\ttop: 0 !important;\r\n\tleft: 0 !important;\r\n\twidth: 100% !important;\r\n\theight: 100% !important;\r\n}\r\n.single-post a.button--cat-l{\r\nmargin-top: 30px !important;\r\n    color: #f5842b;\r\n    text-decoration: none;\r\n    text-transform: uppercase;\r\n    text-decoration: none;\r\n    display: grid;\r\n    place-items: center;\r\n    background-color: #f5842b;\r\n    color: white !important;\r\n    padding: 10px 20px;\r\n    width: max-content;\r\n    margin-top: 8px;\r\n    font-size: large;\r\n    max-width: 100%;\r\n    text-align: center;\r\n    min-height: 50px;\r\n}\r\n.single-post a.button--cat-l:hover{\r\nbackground-color: #16478b;\r\ncolor: white !important;\r\n}\r\n.post-text-padding {padding-top:40px;}\r\n.post-title-one{\r\n font-size:50px;\r\n line-height:1.05 !important;\r\n}\r\n.post-title-second{\r\n line-height:1.5 !important;\r\n}\r\n@media screen and (max-width: 1000px) {\r\n    .columns-wrapper-post {\r\n\t\trow-gap: 50px;\r\n\t\tcolumn-gap: 20px;\r\n\t\tpadding-top: 50px;\r\n\t\tpadding-bottom: 50px;\r\n\t}\r\n\t\t.single-post p {\r\n\t\tpadding-top: 10px !important;\r\n\t}\r\n}\r\n@media screen and (max-width: 800px) {\r\n    .columns-wrapper-post {\r\n\t\trow-gap: 30px;\r\n\t\tpadding-top: 40px;\r\n\t\tpadding-bottom: 40px;\r\n\t}\r\n    .column-post {\r\n\t\tflex-basis: 1;\r\n\t\twidth: 100%;\r\n\t}\r\n\t.single-post .body h3 {\r\n\t\tmargin-top: -15px !important;\r\n\t}\r\n}\r\n<\/style>\r\n\r\n\r\n<div class=\"post-text\">\r\nDer st\u00e4dtische Wasserbedarf wird in den n\u00e4chsten drei Jahrzehnten voraussichtlich um <a href=\"https:\/\/www.nature.com\/articles\/s41467-021-25026-3\" rel=\"noopener noreferrer\" target=\"_blank\">50\u201380%<\/a> steigen, so dass ein  nachhaltiges Wassermanagement f\u00fcr die langfristige Belastbarkeit der St\u00e4dte von entscheidender Bedeutung ist.  Geoplast hat eine Reihe von <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/wasser\/\" rel=\"noopener noreferrer\" target=\"_blank\">Wasserprodukten<\/a> aus recyceltem Kunststoff entwickelt, die speziell f\u00fcr die Drainage,  Sammlung und Wiederverwendung von Wasser in dicht besiedelten st\u00e4dtischen Gebieten geeignet sind. Hier sind die  wichtigsten Merkmale und die besten Einsatzm\u00f6glichkeiten f\u00fcr Ihr n\u00e4chstes Projekt. \r\n<\/div>\r\n\r\n<div class=\"columns-wrapper-post\">\r\n<div class=\"column-post\">\r\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/1-Aquabox.jpg\" alt=\"1 Aquabox\" width=\"1080\" height=\"1080\" class=\"alignnone size-full wp-image-194196\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/1-Aquabox.jpg 1080w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/1-Aquabox-300x300.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/1-Aquabox-1024x1024.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/1-Aquabox-150x150.jpg 150w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/1-Aquabox-768x768.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/1-Aquabox-224x224.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/1-Aquabox-50x50.jpg 50w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\r\n\t<\/div>\r\n\t<div class=\"column-post column-post-text\">\r\n\t\t<span class=\"post-title post-title-one\"><strong>Aquabox<\/strong><\/span>\r\n\t\t<p class=\"post-text\"><a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/wasser\/aquabox\/\" rel=\"noopener noreferrer\" target=\"_blank\">Aquabox<\/a> ist unser w\u00fcrfelf\u00f6rmiges Modul f\u00fcr den <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\/\" rel=\"noopener noreferrer\" target=\"_blank\">schnellen und einfachen Aufbau<\/a> von Becken jeder Gr\u00f6\u00dfe. Mit einer Wasserr\u00fcckhaltekapazit\u00e4t von 96% und einer Einbautiefe von bis zu 6,3 Metern ist es f\u00fcr gro\u00dffl\u00e4chige Anwendungen wie  \u00f6ffentliche Parkpl\u00e4tze, Industrie- und Gewerbegebiete unerl\u00e4sslich.<\/p> \r\n\t<\/div>\r\n\r\n\r\n<div class=\"columns-wrapper-post\">\r\n<div class=\"column-post\">\r\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/2-Drainpanel.jpg\" alt=\"2 Drainpanel\" width=\"1080\" height=\"1080\" class=\"alignnone size-full wp-image-194236\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/2-Drainpanel.jpg 1080w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/2-Drainpanel-300x300.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/2-Drainpanel-1024x1024.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/2-Drainpanel-150x150.jpg 150w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/2-Drainpanel-768x768.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/2-Drainpanel-224x224.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/2-Drainpanel-50x50.jpg 50w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\r\n\t<\/div>\r\n\t<div class=\"column-post column-post-text\">\r\n\t\t<span class=\"post-title post-title-one\"><strong>Drainpanel<\/strong><\/span>\r\n\t\t<p class=\"post-text\"><a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/wasser\/drainpanel\/\" rel=\"noopener noreferrer\" target=\"_blank\">Drainpanel<\/a> ist ein paneelf\u00f6rmiges Modul zur Herstellung von Laminierbecken mit variablen H\u00f6hen. Mit einer H\u00f6he von  nur <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/wasser\/drainpanel\/daten\/\" rel=\"noopener noreferrer\" target=\"_blank\">23 cm<\/a> passt es sich leicht an geringe Tiefen an und ist damit ideal f\u00fcr Stra\u00dfenbauarbeiten und st\u00e4dtische Gebiete  mit begrenzten Aushubvoraussetzungen.<\/p> \r\n\t<\/div>\r\n\r\n\r\n<div class=\"columns-wrapper-post\">\r\n<div class=\"column-post\">\r\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/3-Drening.jpg\" alt=\"3 Drening\" width=\"1080\" height=\"1080\" class=\"alignnone size-full wp-image-194228\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/3-Drening.jpg 1080w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/3-Drening-300x300.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/3-Drening-1024x1024.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/3-Drening-150x150.jpg 150w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/3-Drening-768x768.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/3-Drening-224x224.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/3-Drening-50x50.jpg 50w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\r\n\t<\/div>\r\n\t<div class=\"column-post column-post-text\">\r\n\t\t<span class=\"post-title post-title-one\"><strong>Drening<\/strong><\/span>\r\n\t\t<p class=\"post-text\"><a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/wasser\/drening\/\" rel=\"noopener noreferrer\" target=\"_blank\">Drening<\/a>  ist unser tunnelf\u00f6rmiges Modul, das so viel Wasser speichern kann wie <a href=\"https:\/\/youtu.be\/6BlJBKJHtt4\" rel=\"noopener noreferrer\" target=\"_blank\">36 PVC-Rohre<\/a>. Es eignet sich perfekt  f\u00fcr Projekte mit Platzmangel, wie z.B. Stra\u00dfeninfrastruktur, Parkpl\u00e4tze, D\u00e4cher oder Abfl\u00fcsse bestehender Abwassersysteme. <\/p> \r\n\t<\/div>\r\n\r\n<div class=\"columns-wrapper-post\">\r\n<div class=\"column-post\">\r\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/4-Drening-Reflue.jpg\" alt=\"4 Drening Reflue\" width=\"1080\" height=\"1080\" class=\"alignnone size-full wp-image-194220\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/4-Drening-Reflue.jpg 1080w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/4-Drening-Reflue-300x300.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/4-Drening-Reflue-1024x1024.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/4-Drening-Reflue-150x150.jpg 150w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/4-Drening-Reflue-768x768.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/4-Drening-Reflue-224x224.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/4-Drening-Reflue-50x50.jpg 50w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\r\n\t<\/div>\r\n\t<div class=\"column-post column-post-text\">\r\n\t\t<span class=\"post-title post-title-one\"><strong>Drening Reflue<\/strong><\/span>\r\n\t\t<p class=\"post-text\"><a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/wasser\/drening-reflue\/\" rel=\"noopener noreferrer\" target=\"_blank\">Drening Reflue<\/a> ist unser Tunnelmodul, das speziell f\u00fcr die Versickerung von Haushaltsabwasser entwickelt wurde. Es  leitet das Wasser nach der Kl\u00e4rung in das \u00d6kosystem und hilft so bei der Wiederherstellung der nat\u00fcrlichen  mikrobiologischen Umgebung.<\/p> \r\n\t<\/div>\r\n\r\n\r\n<div class=\"columns-wrapper-post\">\r\n<div class=\"column-post\">\r\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/5-Neu-Elevetor-Tank.jpg\" alt=\"5 Neu Elevetor Tank\" width=\"1080\" height=\"1080\" class=\"alignnone size-full wp-image-194321\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/5-Neu-Elevetor-Tank.jpg 1080w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/5-Neu-Elevetor-Tank-300x300.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/5-Neu-Elevetor-Tank-1024x1024.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/5-Neu-Elevetor-Tank-150x150.jpg 150w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/5-Neu-Elevetor-Tank-768x768.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/5-Neu-Elevetor-Tank-224x224.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/5-Neu-Elevetor-Tank-50x50.jpg 50w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\r\n\t<\/div>\r\n\t<div class=\"column-post column-post-text\">\r\n\t\t<span class=\"post-title post-title-one\"><strong>Neu Elevetor Tank<\/strong><\/span>\r\n\t\t<p class=\"post-text\"><a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/wasser\/neu-elevetor-tank\/\" rel=\"noopener noreferrer\" target=\"_blank\">Neu Elevetor Tank<\/a> ist unsere permanente Schalung f\u00fcr den Bau von Regenwassertanks aus Beton, die vor Ort  gegossen werden. Ihre hohe Lastkapazit\u00e4t macht sie unverzichtbar f\u00fcr das Wassermanagement und die  Wiederverwendung unter <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/wasser\/neu-elevetor-tank\/projekte\/\" rel=\"noopener noreferrer\" target=\"_blank\">Wohn- oder Gesch\u00e4ftsgeb\u00e4uden<\/a>, sowie in Bereichen mit hohem Verkehrsaufkommen.<\/p> \r\n\t<\/div>\r\n\r\n\r\n<div class=\"columns-wrapper-post\">\r\n<div class=\"column-post\">\r\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/6-Geocell.jpg\" alt=\"6 Geocell\" width=\"1080\" height=\"1080\" class=\"alignnone size-full wp-image-194204\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/6-Geocell.jpg 1080w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/6-Geocell-300x300.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/6-Geocell-1024x1024.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/6-Geocell-150x150.jpg 150w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/6-Geocell-768x768.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/6-Geocell-224x224.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/6-Geocell-50x50.jpg 50w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\r\n\t<\/div>\r\n\t<div class=\"column-post column-post-text\">\r\n\t\t<span class=\"post-title post-title-one\"><strong>Geocell<\/strong><\/span>\r\n\t\t<p class=\"post-text\"><a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/wasser\/geocell\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geocell<\/a>, unsere nur 3 cm hohe Oberfl\u00e4chenplatte, bietet sowohl einen horizontalen als auch einen vertikalen  Wasserfluss, was sie von Alternativen wie Kies unterscheidet. Das macht sie zur bevorzugten L\u00f6sung f\u00fcr die schnelle  und effiziente Drainage von <a href=\"https:\/\/www.geoplastglobal.com\/de\/projekte\/auenterrasse-fr-fugnger-beim-observatorium-in-marana-di-krespadoro\/\" rel=\"noopener noreferrer\" target=\"_blank\">gepflasterten Fl\u00e4chen<\/a>, Sportpl\u00e4tzen und st\u00e4dtischen Gr\u00fcnfl\u00e4chen.<\/p> \r\n\t<\/div>\r\n\r\n<font size=\"+2,5\">Wenn Sie unsere Wasserprodukte kaufen oder mehr dar\u00fcber erfahren m\u00f6chten, wenden Sie sich  an Roberto Cecchinato unter <a href=\"mailto: roberto.cecchinato@geoplastglobal.com\">roberto.cecchinato@geoplastglobal.com<\/a> oder kontaktieren Sie uns auf <a href=\"https:\/\/www.linkedin.com\/in\/roberto-cecchinato-2a82574\/\" rel=\"noopener noreferrer\" target=\"_blank\">Linkedin<\/a>.<\/font>\r\n","protected":false},"excerpt":{"rendered":"<p>Der st\u00e4dtische Wasserbedarf wird in den n\u00e4chsten drei Jahrzehnten voraussichtlich um 50\u201380% steigen, so dass ein nachhaltiges Wassermanagement f\u00fcr die langfristige Belastbarkeit der St\u00e4dte von entscheidender Bedeutung ist. Geoplast hat eine Reihe von Wasserprodukten aus recyceltem Kunststoff entwickelt, die speziell f\u00fcr die Drainage, Sammlung und Wiederverwendung von Wasser in dicht [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":194312,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[85],"tags":[4622,1705,3709,841,3595],"class_list":["post-194310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wasser","tag-hochwasserresistenz","tag-nachhaltigkeit","tag-regenwasserbecken","tag-regenwassermanagement","tag-staedtische-resilienz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geoplast f\u00fcr ein nachhaltiges st\u00e4dtisches Wassermanagement &#8211; Geoplast<\/title>\n<meta name=\"description\" content=\"Geoplast hat eine Reihe von Wasserprodukten aus recyceltem Kunststoff entwickelt, die speziell f\u00fcr die Drainage, Sammlung und Wiederverwendung von Wasser in dicht besiedelten st\u00e4dtischen Gebieten geeignet sind.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geoplast f\u00fcr ein nachhaltiges st\u00e4dtisches Wassermanagement &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Geoplast hat eine Reihe von Wasserprodukten aus recyceltem Kunststoff entwickelt, die speziell f\u00fcr die Drainage, Sammlung und Wiederverwendung von Wasser in dicht besiedelten st\u00e4dtischen Gebieten geeignet sind.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-17T07:28:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-17T12:15:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/Geoplast-fur-ein-nachhaltiges-stadtisches-Wassermanagement-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jelena Zivancevic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jelena Zivancevic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\\\/\"},\"author\":{\"name\":\"Jelena Zivancevic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\"},\"headline\":\"Geoplast f\u00fcr ein nachhaltiges st\u00e4dtisches Wassermanagement\",\"datePublished\":\"2024-04-17T07:28:42+00:00\",\"dateModified\":\"2024-04-17T12:15:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\\\/\"},\"wordCount\":384,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Geoplast-fur-ein-nachhaltiges-stadtisches-Wassermanagement-.jpg\",\"keywords\":[\"Hochwasserresistenz\",\"Nachhaltigkeit\",\"Regenwasserbecken\",\"Regenwassermanagement\",\"St\u00e4dtische Resilienz\"],\"articleSection\":[\"Wasser\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\\\/\",\"name\":\"Geoplast f\u00fcr ein nachhaltiges st\u00e4dtisches Wassermanagement &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Geoplast-fur-ein-nachhaltiges-stadtisches-Wassermanagement-.jpg\",\"datePublished\":\"2024-04-17T07:28:42+00:00\",\"dateModified\":\"2024-04-17T12:15:15+00:00\",\"description\":\"Geoplast hat eine Reihe von Wasserprodukten aus recyceltem Kunststoff entwickelt, die speziell f\u00fcr die Drainage, Sammlung und Wiederverwendung von Wasser in dicht besiedelten st\u00e4dtischen Gebieten geeignet sind.\",\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Geoplast-fur-ein-nachhaltiges-stadtisches-Wassermanagement-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Geoplast-fur-ein-nachhaltiges-stadtisches-Wassermanagement-.jpg\",\"width\":1240,\"height\":500,\"caption\":\"Geoplast f\u00fcr ein nachhaltiges st\u00e4dtisches Wassermanagement\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\",\"name\":\"Jelena Zivancevic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"caption\":\"Jelena Zivancevic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geoplast f\u00fcr ein nachhaltiges st\u00e4dtisches Wassermanagement &#8211; Geoplast","description":"Geoplast hat eine Reihe von Wasserprodukten aus recyceltem Kunststoff entwickelt, die speziell f\u00fcr die Drainage, Sammlung und Wiederverwendung von Wasser in dicht besiedelten st\u00e4dtischen Gebieten geeignet sind.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\/","og_locale":"de_DE","og_type":"article","og_title":"Geoplast f\u00fcr ein nachhaltiges st\u00e4dtisches Wassermanagement &#8211; Geoplast","og_description":"Geoplast hat eine Reihe von Wasserprodukten aus recyceltem Kunststoff entwickelt, die speziell f\u00fcr die Drainage, Sammlung und Wiederverwendung von Wasser in dicht besiedelten st\u00e4dtischen Gebieten geeignet sind.","og_url":"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2024-04-17T07:28:42+00:00","article_modified_time":"2024-04-17T12:15:15+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/Geoplast-fur-ein-nachhaltiges-stadtisches-Wassermanagement-.jpg","type":"image\/jpeg"}],"author":"Jelena Zivancevic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Jelena Zivancevic","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\/"},"author":{"name":"Jelena Zivancevic","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad"},"headline":"Geoplast f\u00fcr ein nachhaltiges st\u00e4dtisches Wassermanagement","datePublished":"2024-04-17T07:28:42+00:00","dateModified":"2024-04-17T12:15:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\/"},"wordCount":384,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/Geoplast-fur-ein-nachhaltiges-stadtisches-Wassermanagement-.jpg","keywords":["Hochwasserresistenz","Nachhaltigkeit","Regenwasserbecken","Regenwassermanagement","St\u00e4dtische Resilienz"],"articleSection":["Wasser"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\/","url":"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\/","name":"Geoplast f\u00fcr ein nachhaltiges st\u00e4dtisches Wassermanagement &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/Geoplast-fur-ein-nachhaltiges-stadtisches-Wassermanagement-.jpg","datePublished":"2024-04-17T07:28:42+00:00","dateModified":"2024-04-17T12:15:15+00:00","description":"Geoplast hat eine Reihe von Wasserprodukten aus recyceltem Kunststoff entwickelt, die speziell f\u00fcr die Drainage, Sammlung und Wiederverwendung von Wasser in dicht besiedelten st\u00e4dtischen Gebieten geeignet sind.","inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-fuer-ein-nachhaltiges-staedtisches-wassermanagement\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/Geoplast-fur-ein-nachhaltiges-stadtisches-Wassermanagement-.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2024\/04\/Geoplast-fur-ein-nachhaltiges-stadtisches-Wassermanagement-.jpg","width":1240,"height":500,"caption":"Geoplast f\u00fcr ein nachhaltiges st\u00e4dtisches Wassermanagement"},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/de\/#website","url":"https:\/\/www.geoplastglobal.com\/de\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/de\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad","name":"Jelena Zivancevic","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","caption":"Jelena Zivancevic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/194310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/comments?post=194310"}],"version-history":[{"count":3,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/194310\/revisions"}],"predecessor-version":[{"id":194320,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/194310\/revisions\/194320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/media\/194312"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/media?parent=194310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/categories?post=194310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/tags?post=194310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}