
{"id":183989,"date":"2023-06-14T09:10:10","date_gmt":"2023-06-14T09:10:10","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/blog\/how-to-build-an-aquabox-basin-in-7-easy-steps\/"},"modified":"2023-06-14T10:41:18","modified_gmt":"2023-06-14T10:41:18","slug":"wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\/","title":{"rendered":"Wie man ein Aquabox-Becken in 7 einfachen Schritten  aufbaut"},"content":{"rendered":"<style>\r\n.font-XL {\r\n\tfont-family: Arial, sans-serif !important;\r\n\tfont-weight: 400;\r\n}\r\n\t.columns-wrapper-post {\r\n\t\tdisplay: flex;\r\n\t\tflex-flow: row wrap;\r\n\t\tjustify-content: space-between;\r\n\t\trow-gap: 100px;\r\n\t\tcolumn-gap: 30px;\r\n\t\tpadding-top: 90px;\r\n\t\tpadding-bottom: 60px;\r\n\t}\r\n\t.column-post {\r\n\t\tflex-basis: 1;\r\n\t\twidth: calc(50% - 20px);\r\n\t}\r\n.column-post-text {\r\nmargin-top: -10px !important;\r\n}\r\n\t.column-post .font-L {\r\n\t\tmargin-top: 0px !important;\r\n\t}\r\n\t.single-post .body .font-L {\r\n\t\tmargin-top: 0px !important;\r\n\t}\r\n.single-post .body h2 {\r\nmargin-top: 30px !important;\r\n}\r\n\t@media screen and (max-width: 1000px) {\r\n\t    .columns-wrapper-post {\r\n\t\t\trow-gap: 50px;\r\n\t\t\tcolumn-gap: 20px;\r\n\t\t\tpadding-top: 50px;\r\n\t\t\tpadding-bottom: 50px;\r\n\t\t}\r\n\t\t\t.single-post p {\r\n\t\t\tpadding-top: 10px !important;\r\n\t\t}\r\n.single-post .body h2 {\r\nmargin-top: 0px !important;\r\n}\r\n\t}\r\n\t@media screen and (max-width: 800px) {\r\n\t    .columns-wrapper-post {\r\n\t\t\trow-gap: 30px;\r\n\t\t\tpadding-top: 50px;\r\n\t\t\tpadding-bottom: 40px;\r\n\t\t}\r\n\t    .column-post {\r\n\t\t\tflex-basis: 1;\r\n\t\t\twidth: 100%;\r\n\t\t}\r\n\t}\r\n<\/style>\r\n\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/wasser\/aquabox\/\" rel=\"noopener noreferrer\" target=\"_blank\">Aquabox<\/a> wurde f\u00fcr einen <strong>schnellen und einfachen<\/strong> manuellen Aufbau entwickelt. Dank des Schnappverschlusssystems  und eines Gewichts von 10 kg kann Aquabox auch von unerfahrenen Arbeitern installiert werden. Hier finden Sie eine  Anleitung f\u00fcr Anf\u00e4nger zum Bau eines Aquabox-Regenwasserbeckens in 7 einfachen Schritten, basierend auf unserem  j\u00fcngsten Projekt in der K\u00fcstenstadt Punta Ala, Italien. \r\n\r\n<div class=\"columns-wrapper-post\">\r\n<div class=\"column-post\">\r\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-1-Machen-Sie-die-Bettungsschicht-.jpg\" alt=\"Schritt 1 - Machen Sie die Bettungsschicht\" width=\"1240\" height=\"500\" class=\"alignnone size-full wp-image-183999\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-1-Machen-Sie-die-Bettungsschicht-.jpg 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-1-Machen-Sie-die-Bettungsschicht--300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-1-Machen-Sie-die-Bettungsschicht--1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-1-Machen-Sie-die-Bettungsschicht--768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-1-Machen-Sie-die-Bettungsschicht--224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-1-Machen-Sie-die-Bettungsschicht--124x50.jpg 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-1-Machen-Sie-die-Bettungsschicht--570x230.jpg 570w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n\t<\/div>\r\n\t<div class=\"column-post column-post-text\">\r\n\t\t<span class=\"font-L\"><strong>Schritt 1 &#8211; Machen Sie die Bettungsschicht <\/strong><\/span>\r\n\t\tHeben Sie einen Graben aus und ebnen Sie den Boden. Legen Sie ihn mit Geotextil aus (f\u00fcr ein Versickerungsbecken)  und, falls erforderlich, mit Geomembran und einer zweiten Lage Geotextil (f\u00fcr R\u00fcckhaltung und Wiederverwendung). \r\n\t<\/div>\r\n\r\n<div class=\"column-post\">\r\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-2-Entladen-Sie-die-Paletten.jpg\" alt=\"Schritt 2 - Entladen Sie die Paletten\" width=\"1240\" height=\"500\" class=\"alignnone size-full wp-image-184007\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-2-Entladen-Sie-die-Paletten.jpg 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-2-Entladen-Sie-die-Paletten-300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-2-Entladen-Sie-die-Paletten-1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-2-Entladen-Sie-die-Paletten-768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-2-Entladen-Sie-die-Paletten-224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-2-Entladen-Sie-die-Paletten-124x50.jpg 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-2-Entladen-Sie-die-Paletten-570x230.jpg 570w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n\t<\/div>\r\n\t<div class=\"column-post column-post-text\">\r\n\t\t<span class=\"font-L\"><strong>Schritt 2 &#8211; Entladen Sie die Paletten<\/strong><\/span>\r\n\t\tAquabox wird f\u00fcr einen leichteren Transport gestapelt geliefert. Jede Palette enth\u00e4lt 80 Halbelemente oder 40 Module.\r\n\t<\/div>\r\n\r\n<div class=\"column-post\">\r\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-3-Erstellen-Sie-die-Module.jpg\" alt=\"Schritt 3 - Erstellen Sie die Module\" width=\"1240\" height=\"500\" class=\"alignnone size-full wp-image-184015\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-3-Erstellen-Sie-die-Module.jpg 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-3-Erstellen-Sie-die-Module-300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-3-Erstellen-Sie-die-Module-1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-3-Erstellen-Sie-die-Module-768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-3-Erstellen-Sie-die-Module-224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-3-Erstellen-Sie-die-Module-124x50.jpg 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-3-Erstellen-Sie-die-Module-570x230.jpg 570w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n\t<\/div>\r\n\t<div class=\"column-post column-post-text\">\r\n\t\t<span class=\"font-L\"><strong>Schritt 3 &#8211; Erstellen Sie die Module<\/strong><\/span>\r\n\t\tPacken Sie die Paletten aus und f\u00fcgen Sie die Halbelemente zu Aquabox-Modulen zusammen.  \r\n\t<\/div>\r\n\r\n<div class=\"column-post\">\r\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-4-Platzieren-Sie-die-Module.jpg\" alt=\"Schritt 4 - Platzieren Sie die Module\" width=\"1240\" height=\"500\" class=\"alignnone size-full wp-image-184023\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-4-Platzieren-Sie-die-Module.jpg 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-4-Platzieren-Sie-die-Module-300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-4-Platzieren-Sie-die-Module-1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-4-Platzieren-Sie-die-Module-768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-4-Platzieren-Sie-die-Module-224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-4-Platzieren-Sie-die-Module-124x50.jpg 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-4-Platzieren-Sie-die-Module-570x230.jpg 570w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n\t<\/div>\r\n\t<div class=\"column-post column-post-text\">\r\n\t\t<span class=\"font-L\"><strong>Schritt 4 &#8211; Platzieren Sie die Module<\/strong><\/span>\r\n\t\tSetzen Sie das Becken zusammen, indem Sie die Module platzieren und mit den roten Verbindungsst\u00fccken  zusammenschlie\u00dfen. \r\n\t<\/div>\r\n\r\n<div class=\"column-post\">\r\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-5-Platzieren-Sie-das-Gitter.jpg\" alt=\"Schritt 5 - Platzieren Sie das Gitter\" width=\"1240\" height=\"500\" class=\"alignnone size-full wp-image-184031\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-5-Platzieren-Sie-das-Gitter.jpg 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-5-Platzieren-Sie-das-Gitter-300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-5-Platzieren-Sie-das-Gitter-1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-5-Platzieren-Sie-das-Gitter-768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-5-Platzieren-Sie-das-Gitter-224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-5-Platzieren-Sie-das-Gitter-124x50.jpg 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-5-Platzieren-Sie-das-Gitter-570x230.jpg 570w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n\t<\/div>\r\n\t<div class=\"column-post column-post-text\">\r\n\t\t<span class=\"font-L\"><strong>Schritt 5 &#8211; Platzieren Sie das Gitter<\/strong><\/span>\r\n\t\tSchlie\u00dfen Sie das Becken, indem Sie die Seitenw\u00e4nde und das Abdeckgitter anbringen.  \r\n\t<\/div>\r\n\r\n<div class=\"column-post\">\r\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-6-Decken-Sie-das-Becken-ab.jpg\" alt=\"Schritt 6 - Decken Sie das Becken ab\" width=\"1240\" height=\"500\" class=\"alignnone size-full wp-image-184039\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-6-Decken-Sie-das-Becken-ab.jpg 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-6-Decken-Sie-das-Becken-ab-300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-6-Decken-Sie-das-Becken-ab-1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-6-Decken-Sie-das-Becken-ab-768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-6-Decken-Sie-das-Becken-ab-224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-6-Decken-Sie-das-Becken-ab-124x50.jpg 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-6-Decken-Sie-das-Becken-ab-570x230.jpg 570w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n\t<\/div>\r\n\t<div class=\"column-post column-post-text\">\r\n\t\t<span class=\"font-L\"><strong>Schritt 6 &#8211; Decken Sie das Becken ab<\/strong><\/span>\r\n\t\tDecken Sie das Becken mit dem Geotextil ab. Dichten Sie es mit einer Geomembran und einer zweiten Lage Geotextil  ab, falls n\u00f6tig. Bedecken Sie es mit Erde. \r\n\t<\/div>\r\n\r\n<div class=\"column-post\">\r\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-7-Erfreuen-Sie-sich.jpg\" alt=\"Schritt 7 - Erfreuen Sie sich\" width=\"1240\" height=\"500\" class=\"alignnone size-full wp-image-184047\" srcset=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-7-Erfreuen-Sie-sich.jpg 1240w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-7-Erfreuen-Sie-sich-300x121.jpg 300w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-7-Erfreuen-Sie-sich-1024x413.jpg 1024w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-7-Erfreuen-Sie-sich-768x310.jpg 768w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-7-Erfreuen-Sie-sich-224x90.jpg 224w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-7-Erfreuen-Sie-sich-124x50.jpg 124w, https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Schritt-7-Erfreuen-Sie-sich-570x230.jpg 570w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/>\r\n\t<\/div>\r\n\t<div class=\"column-post column-post-text\">\r\n\t\t<span class=\"font-L\"><strong>Schritt 7 &#8211; Erfreuen Sie sich<\/strong><\/span>\r\n\t\tFreuen Sie sich \u00fcber das gro\u00dfartige Regenwassermanagement Ihres neuen Aquabox-Beckens.\r\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n<a class=\"button--cat-l\" href=\"https:\/\/www.geoplastglobal.com\/de\/kontakte\/\" target=\"_blank\" rel=\"noopener\">BAUEN SIE JETZT EIN AQUABOX-BECKEN<\/a>\r\n","protected":false},"excerpt":{"rendered":"<p>Aquabox wurde f\u00fcr einen schnellen und einfachen manuellen Aufbau entwickelt. Dank des Schnappverschlusssystems und eines Gewichts von 10 kg kann Aquabox auch von unerfahrenen Arbeitern installiert werden. Hier finden Sie eine Anleitung f\u00fcr Anf\u00e4nger zum Bau eines Aquabox-Regenwasserbeckens in 7 einfachen Schritten, basierend auf unserem j\u00fcngsten Projekt in der K\u00fcstenstadt [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":183991,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[85],"tags":[2964,2967,841,4244,2968,844,3708],"class_list":["post-183989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wasser","tag-aquabox-de","tag-rainwater-reuse-de","tag-regenwassermanagement","tag-regenwasserwiederverwendung","tag-stormwater-management-de","tag-wasserloesungen","tag-water-solutions-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wie man ein Aquabox-Becken in 7 einfachen Schritten aufbaut &#8211; Geoplast<\/title>\n<meta name=\"description\" content=\"Hier ist eine Anleitung f\u00fcr Anf\u00e4nger, wie man ein Aquabox-Regenwasserbecken baut, basierend auf unserem j\u00fcngsten Projekt in Punta Ala, Italien.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie man ein Aquabox-Becken in 7 einfachen Schritten aufbaut &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Hier ist eine Anleitung f\u00fcr Anf\u00e4nger, wie man ein Aquabox-Regenwasserbecken baut, basierend auf unserem j\u00fcngsten Projekt in Punta Ala, Italien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-14T09:10:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-14T10:41:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Wie-man-ein-Aquabox-Becken-in-7-einfachen-Schritten-aufbaut.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jelena Zivancevic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jelena Zivancevic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\\\/\"},\"author\":{\"name\":\"Jelena Zivancevic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\"},\"headline\":\"Wie man ein Aquabox-Becken in 7 einfachen Schritten aufbaut\",\"datePublished\":\"2023-06-14T09:10:10+00:00\",\"dateModified\":\"2023-06-14T10:41:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\\\/\"},\"wordCount\":248,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Wie-man-ein-Aquabox-Becken-in-7-einfachen-Schritten-aufbaut.jpg\",\"keywords\":[\"Aquabox\",\"Rainwater reuse\",\"Regenwassermanagement\",\"Regenwasserwiederverwendung\",\"Stormwater management\",\"Wasserl\u00f6sungen\",\"Water solutions\"],\"articleSection\":[\"Wasser\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\\\/\",\"name\":\"Wie man ein Aquabox-Becken in 7 einfachen Schritten aufbaut &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Wie-man-ein-Aquabox-Becken-in-7-einfachen-Schritten-aufbaut.jpg\",\"datePublished\":\"2023-06-14T09:10:10+00:00\",\"dateModified\":\"2023-06-14T10:41:18+00:00\",\"description\":\"Hier ist eine Anleitung f\u00fcr Anf\u00e4nger, wie man ein Aquabox-Regenwasserbecken baut, basierend auf unserem j\u00fcngsten Projekt in Punta Ala, Italien.\",\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Wie-man-ein-Aquabox-Becken-in-7-einfachen-Schritten-aufbaut.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Wie-man-ein-Aquabox-Becken-in-7-einfachen-Schritten-aufbaut.jpg\",\"width\":1240,\"height\":500,\"caption\":\"Wie man ein Aquabox-Becken in 7 einfachen Schritten aufbaut\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\",\"name\":\"Jelena Zivancevic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"caption\":\"Jelena Zivancevic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie man ein Aquabox-Becken in 7 einfachen Schritten aufbaut &#8211; Geoplast","description":"Hier ist eine Anleitung f\u00fcr Anf\u00e4nger, wie man ein Aquabox-Regenwasserbecken baut, basierend auf unserem j\u00fcngsten Projekt in Punta Ala, Italien.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\/","og_locale":"de_DE","og_type":"article","og_title":"Wie man ein Aquabox-Becken in 7 einfachen Schritten aufbaut &#8211; Geoplast","og_description":"Hier ist eine Anleitung f\u00fcr Anf\u00e4nger, wie man ein Aquabox-Regenwasserbecken baut, basierend auf unserem j\u00fcngsten Projekt in Punta Ala, Italien.","og_url":"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2023-06-14T09:10:10+00:00","article_modified_time":"2023-06-14T10:41:18+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Wie-man-ein-Aquabox-Becken-in-7-einfachen-Schritten-aufbaut.jpg","type":"image\/jpeg"}],"author":"Jelena Zivancevic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Jelena Zivancevic","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\/"},"author":{"name":"Jelena Zivancevic","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad"},"headline":"Wie man ein Aquabox-Becken in 7 einfachen Schritten aufbaut","datePublished":"2023-06-14T09:10:10+00:00","dateModified":"2023-06-14T10:41:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\/"},"wordCount":248,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Wie-man-ein-Aquabox-Becken-in-7-einfachen-Schritten-aufbaut.jpg","keywords":["Aquabox","Rainwater reuse","Regenwassermanagement","Regenwasserwiederverwendung","Stormwater management","Wasserl\u00f6sungen","Water solutions"],"articleSection":["Wasser"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\/","url":"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\/","name":"Wie man ein Aquabox-Becken in 7 einfachen Schritten aufbaut &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Wie-man-ein-Aquabox-Becken-in-7-einfachen-Schritten-aufbaut.jpg","datePublished":"2023-06-14T09:10:10+00:00","dateModified":"2023-06-14T10:41:18+00:00","description":"Hier ist eine Anleitung f\u00fcr Anf\u00e4nger, wie man ein Aquabox-Regenwasserbecken baut, basierend auf unserem j\u00fcngsten Projekt in Punta Ala, Italien.","inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-ein-aquabox-becken-in-7-einfachen-schritten-aufbaut\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Wie-man-ein-Aquabox-Becken-in-7-einfachen-Schritten-aufbaut.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2023\/06\/Wie-man-ein-Aquabox-Becken-in-7-einfachen-Schritten-aufbaut.jpg","width":1240,"height":500,"caption":"Wie man ein Aquabox-Becken in 7 einfachen Schritten aufbaut"},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/de\/#website","url":"https:\/\/www.geoplastglobal.com\/de\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/de\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad","name":"Jelena Zivancevic","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","caption":"Jelena Zivancevic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/183989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/comments?post=183989"}],"version-history":[{"count":3,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/183989\/revisions"}],"predecessor-version":[{"id":184068,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/183989\/revisions\/184068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/media\/183991"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/media?parent=183989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/categories?post=183989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/tags?post=183989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}