
{"id":177347,"date":"2022-12-06T13:45:54","date_gmt":"2022-12-06T13:45:54","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/blog\/myth-vs-fact-about-sustainable-construction\/"},"modified":"2022-12-07T10:01:32","modified_gmt":"2022-12-07T10:01:32","slug":"mythen-versus-fakten-ueber-nachhaltiges-bauen","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/de\/blog\/mythen-versus-fakten-ueber-nachhaltiges-bauen\/","title":{"rendered":"Mythen versus Fakten \u00fcber nachhaltiges Bauen"},"content":{"rendered":"Lassen Sie uns die am weitesten verbreiteten Mythen \u00fcber nachhaltiges Bauen aufgreifen und erkl\u00e4ren, warum Sie sie  ausr\u00e4umen sollten.  \r\n\r\n<h3>Mythos Nr. 1: Nachhaltiges Bauen verursacht h\u00f6here Kosten<\/h3> \r\n\r\nDies ist der am weitesten verbreitete Mythos von allen. Tats\u00e4chlich k\u00f6nnen nachhaltige L\u00f6sungen die Logistik und die  Baugeschwindigkeit verbessern und den Materialverbrauch reduzieren, was den Bauprozess profitabler macht.  Energieeffizienz und Regenwassermanagement senken auch die zuk\u00fcnftigen Kosten und erh\u00f6hen den  Wiederverkaufswert.  \r\n\r\nSiehe: <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/ein-mythos-wird-entlarvt-nachhaltigkeit-erhoeht-die-baukosten\/\" rel=\"noopener noreferrer\" target=\"_blank\">Ein Mythos wird entlarvt: Nachhaltigkeit erh\u00f6ht die Baukosten<\/a>\r\n\r\n<h3>Mythos Nr. 2: Nachhaltige Produkte sind nicht verf\u00fcgbar<\/h3>\r\n\r\nJa, wir sind daran gew\u00f6hnt, Beton, Metall und EPS zu verwenden, aber bedeutet das, dass nachhaltige Alternativen  schwer zu beschaffen sind? Die Produkte von Geoplast sind jederzeit weltweit zum Kauf oder zur Miete erh\u00e4ltlich &#8211; kontaktieren Sie unser Beratungsteam f\u00fcr ausf\u00fchrlichere Informationen.   \r\n\r\nSiehe: <a href=\"https:\/\/www.geoplastglobal.com\/de\/kontakte\/\" rel=\"noopener noreferrer\" target=\"_blank\">Kontakte<\/a>, <a href=\"https:\/\/www.geoplastglobal.com\/en\/rent-formwork\/\" rel=\"noopener noreferrer\" target=\"_blank\">Schalung mieten<\/a>\r\n\r\n<h3>Mythos Nr. 3: Nachhaltige Produkte sind nicht f\u00fcr jedes Projekt geeignet <\/h3> \r\n\r\nEntlegene H\u00fctten m\u00f6gen einmal der Archetyp des nachhaltigen Bauens gewesen sein, aber die Dinge haben sich  seitdem stark ver\u00e4ndert. Heute gibt es L\u00f6sungen f\u00fcr die Verbesserung der Nachhaltigkeit verschiedener Geb\u00e4udeteile  und Projektarten, vom Fundament bis zum Dach, ob gro\u00df oder klein.  \r\n\r\nSiehe: <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/neu-elevetor-ist-fuer-jede-art-von-projekt-geeignet\/\" rel=\"noopener noreferrer\" target=\"_blank\">Neu Elevetor ist f\u00fcr jede Art von Projekt geeignet <\/a>\r\n\r\n<h3>Mythos Nr. 4: Nachhaltigkeit hat mit Solarmodulen zu tun<\/h3>\r\n\r\nEs ist ein weit verbreiteter Irrglaube, dass man nachhaltiges Bauen nach Fertigstellung des Geb\u00e4udes mit ein paar  Solarmodulen auf dem Dach erreichen kann. Im Gegenteil, wir haben und sollten L\u00f6sungen nutzen, die sich mit  verschiedenen Aspekten des Bauens befassen: Materialeinsparung, Produktivit\u00e4t auf der Baustelle, Transport,  Installation, Abfallreduzierung usw.  \r\n\r\nSiehe: <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-produktvielseitigkeit-mehr-nutzen-aus-jedem-produkt\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geoplast Produktvielseitigkeit \u2013 mehr Nutzen aus jedem Produkt<\/a>\r\n\r\n<h3>Mythos Nr. 5: Nachhaltige Geb\u00e4ude zu bauen dauert l\u00e4nger<\/h3>\r\n\r\nDie Leute denken oft, dass nachhaltiges Bauen komplizierter ist und l\u00e4nger dauert. Die Wahrheit ist genau das  Gegenteil. Aufgrund ihrer Leichtigkeit und Stapelbarkeit ben\u00f6tigen unsere nachhaltigen L\u00f6sungen weniger Transport und Lagerfl\u00e4che und weniger Maschinen auf der Baustelle, wodurch der Bauprozess beschleunigt wird. \r\n\r\nSiehe: <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/geotub-runde-saeulen-44-schneller-bauen\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geotub: runde S\u00e4ulen 44 % schneller bauen<\/a>\r\n\r\n<h3>Mythos Nr. 6: Nachhaltiges Bauen erfordert von den Arbeitern spezielle F\u00e4higkeiten<\/h3>\r\nEin weiterer Mythos ist, dass nachhaltige L\u00f6sungen besondere oder fachm\u00e4nnische F\u00e4higkeiten f\u00fcr die Installation  erfordern. Tats\u00e4chlich k\u00f6nnen sie dank ihres innovativen Designs und ihres geringen Gewichts von jedem, auch von  unerfahrenen Arbeitern, ohne jegliche Anleitung installiert werde.  \r\n\r\nSiehe: <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/schauen-sie-sich-an-wie-einfach-es-zu-installieren-ist-aquabox-becken-in-punta-ala\/\" rel=\"noopener noreferrer\" target=\"_blank\"> Schauen Sie, wie einfach die Installation ist: Aquabox Becken in Punta Ala<\/a> \r\n\r\n<h3>Mythos Nr. 7: Bewertungssysteme sind schwer zu erreichen<\/h3>\r\n\r\nGanz und gar nicht. Die Teilnahme am LEED-Bewertungssystem ist einfach. F\u00fcr jedes nachhaltige Produkt gibt es eine  bestimmte Anzahl von Punkten f\u00fcr die Ber\u00fccksichtigung von Umweltaspekten. Sie sammeln die Punkte, um eine bestimmte Zertifizierungsstufe zu erhalten: Zertifiziert (40-49 Punkte), Silber (50-59), Gold (60-79) oder Platin (80+).   \r\n\r\nSiehe: <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/schalungen\/geopanel\/leed\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geopanel LEED<\/a>, <a href=\"https:\/\/www.usgbc.org\/leed\" rel=\"noopener noreferrer\" target=\"_blank\">LEED-Bewertungssystem<\/a> \r\n\r\n<h3>Mythos Nr. 8: Es ist ein vor\u00fcbergehender Trend<\/h3>\r\n\r\nDieser Mythos ist der am wenigsten zutreffende von allen. An der Klimakrise f\u00fchrt kein Weg vorbei, und das Gleiche gilt  f\u00fcr nachhaltiges Bauen &#8211; es wird sich durchsetzen und bald die EINZIGE Art zu bauen sein.  \r\n\r\n\r\n&nbsp; \r\n<font size=\"+2\"><a href=\"https:\/\/www.geoplastglobal.com\/de\/kontakte\/\" rel=\"noopener noreferrer\" target=\"_blank\">Kontaktieren Sie uns, um Ihre Projekte nachhaltiger zu gestalten.<\/a><\/font>\r\n\r\n","protected":false},"excerpt":{"rendered":"<p>Lassen Sie uns die am weitesten verbreiteten Mythen \u00fcber nachhaltiges Bauen aufgreifen und erkl\u00e4ren, warum Sie sie ausr\u00e4umen sollten. Mythos Nr. 1: Nachhaltiges Bauen verursacht h\u00f6here Kosten Dies ist der am weitesten verbreitete Mythos von allen. Tats\u00e4chlich k\u00f6nnen nachhaltige L\u00f6sungen die Logistik und die Baugeschwindigkeit verbessern und den Materialverbrauch reduzieren, [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":177349,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2873],"tags":[3375,1830,1705,4911,3225,3355],"class_list":["post-177347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachhaltigen-profitabilitaet","tag-nachhaltige-konstruktion","tag-nachhaltiges-gebaeude","tag-nachhaltigkeit","tag-sostenibilidad-de","tag-sustainable-building-de","tag-sustainable-construction-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mythen versus Fakten \u00fcber nachhaltiges Bauen &#8211; Geoplast<\/title>\n<meta name=\"description\" content=\"Lassen Sie uns die am weitesten verbreiteten Mythen \u00fcber nachhaltiges Bauen aufgreifen und erkl\u00e4ren, warum Sie sie ausr\u00e4umen sollten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/mythen-versus-fakten-ueber-nachhaltiges-bauen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mythen versus Fakten \u00fcber nachhaltiges Bauen &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Lassen Sie uns die am weitesten verbreiteten Mythen \u00fcber nachhaltiges Bauen aufgreifen und erkl\u00e4ren, warum Sie sie ausr\u00e4umen sollten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/de\/blog\/mythen-versus-fakten-ueber-nachhaltiges-bauen\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-06T13:45:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-07T10:01:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/12\/Richtig-oder-falsch.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jelena Zivancevic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jelena Zivancevic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/mythen-versus-fakten-ueber-nachhaltiges-bauen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/mythen-versus-fakten-ueber-nachhaltiges-bauen\\\/\"},\"author\":{\"name\":\"Jelena Zivancevic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\"},\"headline\":\"Mythen versus Fakten \u00fcber nachhaltiges Bauen\",\"datePublished\":\"2022-12-06T13:45:54+00:00\",\"dateModified\":\"2022-12-07T10:01:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/mythen-versus-fakten-ueber-nachhaltiges-bauen\\\/\"},\"wordCount\":529,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/mythen-versus-fakten-ueber-nachhaltiges-bauen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Richtig-oder-falsch.jpg\",\"keywords\":[\"Nachhaltige Konstruktion\",\"nachhaltiges Geb\u00e4ude\",\"Nachhaltigkeit\",\"Sostenibilidad\",\"Sustainable Building\",\"Sustainable construction\"],\"articleSection\":[\"Nachhaltigen Profitabilit\u00e4t\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/mythen-versus-fakten-ueber-nachhaltiges-bauen\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/mythen-versus-fakten-ueber-nachhaltiges-bauen\\\/\",\"name\":\"Mythen versus Fakten \u00fcber nachhaltiges Bauen &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/mythen-versus-fakten-ueber-nachhaltiges-bauen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/mythen-versus-fakten-ueber-nachhaltiges-bauen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Richtig-oder-falsch.jpg\",\"datePublished\":\"2022-12-06T13:45:54+00:00\",\"dateModified\":\"2022-12-07T10:01:32+00:00\",\"description\":\"Lassen Sie uns die am weitesten verbreiteten Mythen \u00fcber nachhaltiges Bauen aufgreifen und erkl\u00e4ren, warum Sie sie ausr\u00e4umen sollten.\",\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/mythen-versus-fakten-ueber-nachhaltiges-bauen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/mythen-versus-fakten-ueber-nachhaltiges-bauen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Richtig-oder-falsch.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Richtig-oder-falsch.jpg\",\"width\":1240,\"height\":500,\"caption\":\"Mythen versus Fakten \u00fcber nachhaltiges Bauen\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\",\"name\":\"Jelena Zivancevic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"caption\":\"Jelena Zivancevic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mythen versus Fakten \u00fcber nachhaltiges Bauen &#8211; Geoplast","description":"Lassen Sie uns die am weitesten verbreiteten Mythen \u00fcber nachhaltiges Bauen aufgreifen und erkl\u00e4ren, warum Sie sie ausr\u00e4umen sollten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/de\/blog\/mythen-versus-fakten-ueber-nachhaltiges-bauen\/","og_locale":"de_DE","og_type":"article","og_title":"Mythen versus Fakten \u00fcber nachhaltiges Bauen &#8211; Geoplast","og_description":"Lassen Sie uns die am weitesten verbreiteten Mythen \u00fcber nachhaltiges Bauen aufgreifen und erkl\u00e4ren, warum Sie sie ausr\u00e4umen sollten.","og_url":"https:\/\/www.geoplastglobal.com\/de\/blog\/mythen-versus-fakten-ueber-nachhaltiges-bauen\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2022-12-06T13:45:54+00:00","article_modified_time":"2022-12-07T10:01:32+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/12\/Richtig-oder-falsch.jpg","type":"image\/jpeg"}],"author":"Jelena Zivancevic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Jelena Zivancevic","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/mythen-versus-fakten-ueber-nachhaltiges-bauen\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/mythen-versus-fakten-ueber-nachhaltiges-bauen\/"},"author":{"name":"Jelena Zivancevic","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad"},"headline":"Mythen versus Fakten \u00fcber nachhaltiges Bauen","datePublished":"2022-12-06T13:45:54+00:00","dateModified":"2022-12-07T10:01:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/mythen-versus-fakten-ueber-nachhaltiges-bauen\/"},"wordCount":529,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/mythen-versus-fakten-ueber-nachhaltiges-bauen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/12\/Richtig-oder-falsch.jpg","keywords":["Nachhaltige Konstruktion","nachhaltiges Geb\u00e4ude","Nachhaltigkeit","Sostenibilidad","Sustainable Building","Sustainable construction"],"articleSection":["Nachhaltigen Profitabilit\u00e4t"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/mythen-versus-fakten-ueber-nachhaltiges-bauen\/","url":"https:\/\/www.geoplastglobal.com\/de\/blog\/mythen-versus-fakten-ueber-nachhaltiges-bauen\/","name":"Mythen versus Fakten \u00fcber nachhaltiges Bauen &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/mythen-versus-fakten-ueber-nachhaltiges-bauen\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/mythen-versus-fakten-ueber-nachhaltiges-bauen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/12\/Richtig-oder-falsch.jpg","datePublished":"2022-12-06T13:45:54+00:00","dateModified":"2022-12-07T10:01:32+00:00","description":"Lassen Sie uns die am weitesten verbreiteten Mythen \u00fcber nachhaltiges Bauen aufgreifen und erkl\u00e4ren, warum Sie sie ausr\u00e4umen sollten.","inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/de\/blog\/mythen-versus-fakten-ueber-nachhaltiges-bauen\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/mythen-versus-fakten-ueber-nachhaltiges-bauen\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/12\/Richtig-oder-falsch.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/12\/Richtig-oder-falsch.jpg","width":1240,"height":500,"caption":"Mythen versus Fakten \u00fcber nachhaltiges Bauen"},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/de\/#website","url":"https:\/\/www.geoplastglobal.com\/de\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/de\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad","name":"Jelena Zivancevic","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","caption":"Jelena Zivancevic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/177347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/comments?post=177347"}],"version-history":[{"count":3,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/177347\/revisions"}],"predecessor-version":[{"id":177358,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/177347\/revisions\/177358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/media\/177349"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/media?parent=177347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/categories?post=177347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/tags?post=177347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}