
{"id":169417,"date":"2022-05-05T08:06:15","date_gmt":"2022-05-05T08:06:15","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/?p=169417"},"modified":"2022-05-05T09:21:58","modified_gmt":"2022-05-05T09:21:58","slug":"die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/de\/blog\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\/","title":{"rendered":"Die 5 wichtigsten Vorteile von Matrix gegen\u00fcber Metalldoppelb\u00f6den"},"content":{"rendered":"Doppelb\u00f6den mit Metallsockeln wurden entwickelt, um einen bequemen Zugang zu MEP-Systemen zu erm\u00f6glichen. Im  Laufe der Jahre wurden die Metallb\u00f6den f\u00fcr moderne Innenraumstandards wie Tragf\u00e4higkeit, Sicherheit, Akustik und  \u00c4sthetik \u00fcberfl\u00fcssig. \r\n \r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/fundamente\/matrix\/\" target=\"_blank\" rel=\"noopener\">Matrix<\/a> wurde f\u00fcr eine einfache MEP-Installation entwickelt, mit Verbesserungen im Vergleich zu Platten auf Sockeln, die  sich in 5 Vorteilen zusammenfassen lassen: \r\n\r\n<strong style=\"font-size:18px;\">Maximaler Zugangsraum<\/strong> \r\nTrotz der hohen Tragf\u00e4higkeit hat Matrix nur eine Gesamth\u00f6he von 15 cm und eine Zugangsfl\u00e4che f\u00fcr MEP-Systeme  von 10-12 cm H\u00f6he und 30-40 cm Breite.\r\n\r\n<strong style=\"font-size:18px;\">Hohe Tragf\u00e4higkeit<\/strong>\r\nDie Tragf\u00e4higkeit von Metallzugangsb\u00f6den betr\u00e4gt weniger als 1 t\/m2. Matrix bildet eine Betonkonstruktion, die mehr als  15 t\/m2 aush\u00e4lt und damit f\u00fcr die Belastung durch schweres Ger\u00e4t, Fahrzeuge und einen regen Fu\u00dfg\u00e4ngerverkehr  geeignet ist. Das System ist auch vor dem Betonieren begehbar. \r\n\r\n<strong style=\"font-size:18px;\">Akustische Leistung<\/strong>\r\nDoppelb\u00f6den aus Metall sind f\u00fcr ihre schlechten akustischen Eigenschaften bekannt. Matrix schafft eine monolithische  Betonoberfl\u00e4che, die den Nachhall von Schritten und M\u00f6beln verhindert und damit die akustische Leistung des Bodens  verbessert.   \r\n\r\n<strong style=\"font-size:18px;\">Geeignet f\u00fcr jede Art von Bodenbelag<\/strong>\r\nMetallb\u00f6den sind aufgrund ihres strukturellen Rasters nicht f\u00fcr jede Art von Bodenbelag geeignet. Matrix schafft eine  stabile, ebene Oberfl\u00e4che, die sich f\u00fcr jede Art von Belag eignet, einschlie\u00dflich Parkett, Mosaik, Keramikfliesen oder  moderne Epoxid- und Betonbeschichtungen. \r\n\r\n<strong style=\"font-size:18px;\">Schnelle und einfache Installation<\/strong>\r\nMetallbodensysteme haben viele kleine Teile, z. B. Sockel, F\u00fc\u00dfe und Schrauben, die verschiedene Zubeh\u00f6rteile und  Werkzeuge erfordern. Matrix besteht aus nur 2 Elementen, die durch einfaches Einhaken mit Druck befestigt werden:  das Basisgitter und die obere Schalung. \r\n\r\n&nbsp;\r\n<font size=\"+2\"><a href=\"https:\/\/www.geoplastglobal.com\/de\/kontakte\/\" rel=\"noopener noreferrer\" target=\"_blank\">Kontaktieren Sie uns<\/a>, um Matrix in Ihrem n\u00e4chsten Projekt einzusetzen.<\/font>","protected":false},"excerpt":{"rendered":"<p>Doppelb\u00f6den mit Metallsockeln wurden entwickelt, um einen bequemen Zugang zu MEP-Systemen zu erm\u00f6glichen. Im Laufe der Jahre wurden die Metallb\u00f6den f\u00fcr moderne Innenraumstandards wie Tragf\u00e4higkeit, Sicherheit, Akustik und \u00c4sthetik \u00fcberfl\u00fcssig. Matrix wurde f\u00fcr eine einfache MEP-Installation entwickelt, mit Verbesserungen im Vergleich zu Platten auf Sockeln, die sich in 5 Vorteilen [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":169433,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[52,81],"tags":[3676,3633,771,3629,3634],"class_list":["post-169417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-foundations","category-fundamente","tag-access-floors","tag-doppelboeden","tag-fundamentloesungen","tag-matrix-de","tag-mep-systemen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die 5 wichtigsten Vorteile von Matrix gegen\u00fcber Metalldoppelb\u00f6den &#8211; Geoplast<\/title>\n<meta name=\"description\" content=\"Matrix wurde f\u00fcr eine einfache MEP-Installation mit vielen Verbesserungen im Vergleich zu Metallsockelb\u00f6den entwickelt. Hier ist eine Liste der 5 wichtigsten Vorteile.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die 5 wichtigsten Vorteile von Matrix gegen\u00fcber Metalldoppelb\u00f6den &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Matrix wurde f\u00fcr eine einfache MEP-Installation mit vielen Verbesserungen im Vergleich zu Metallsockelb\u00f6den entwickelt. Hier ist eine Liste der 5 wichtigsten Vorteile.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/de\/blog\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-05T08:06:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-05T09:21:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/05\/Matrix-vs-metal-floors-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jelena Zivancevic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jelena Zivancevic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\\\/\"},\"author\":{\"name\":\"Jelena Zivancevic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\"},\"headline\":\"Die 5 wichtigsten Vorteile von Matrix gegen\u00fcber Metalldoppelb\u00f6den\",\"datePublished\":\"2022-05-05T08:06:15+00:00\",\"dateModified\":\"2022-05-05T09:21:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\\\/\"},\"wordCount\":290,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Matrix-vs-metal-floors-2.jpg\",\"keywords\":[\"Access floors\",\"Doppelb\u00f6den\",\"Fundamentl\u00f6sungen\",\"Matrix\",\"MEP-Systemen\"],\"articleSection\":[\"Foundations\",\"Fundamente\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\\\/\",\"name\":\"Die 5 wichtigsten Vorteile von Matrix gegen\u00fcber Metalldoppelb\u00f6den &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Matrix-vs-metal-floors-2.jpg\",\"datePublished\":\"2022-05-05T08:06:15+00:00\",\"dateModified\":\"2022-05-05T09:21:58+00:00\",\"description\":\"Matrix wurde f\u00fcr eine einfache MEP-Installation mit vielen Verbesserungen im Vergleich zu Metallsockelb\u00f6den entwickelt. Hier ist eine Liste der 5 wichtigsten Vorteile.\",\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Matrix-vs-metal-floors-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Matrix-vs-metal-floors-2.jpg\",\"width\":1240,\"height\":500,\"caption\":\"Die 5 wichtigsten Vorteile von Matrix gegen\u00fcber Metalldoppelb\u00f6den\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\",\"name\":\"Jelena Zivancevic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"caption\":\"Jelena Zivancevic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die 5 wichtigsten Vorteile von Matrix gegen\u00fcber Metalldoppelb\u00f6den &#8211; Geoplast","description":"Matrix wurde f\u00fcr eine einfache MEP-Installation mit vielen Verbesserungen im Vergleich zu Metallsockelb\u00f6den entwickelt. Hier ist eine Liste der 5 wichtigsten Vorteile.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/de\/blog\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\/","og_locale":"de_DE","og_type":"article","og_title":"Die 5 wichtigsten Vorteile von Matrix gegen\u00fcber Metalldoppelb\u00f6den &#8211; Geoplast","og_description":"Matrix wurde f\u00fcr eine einfache MEP-Installation mit vielen Verbesserungen im Vergleich zu Metallsockelb\u00f6den entwickelt. Hier ist eine Liste der 5 wichtigsten Vorteile.","og_url":"https:\/\/www.geoplastglobal.com\/de\/blog\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2022-05-05T08:06:15+00:00","article_modified_time":"2022-05-05T09:21:58+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/05\/Matrix-vs-metal-floors-2.jpg","type":"image\/jpeg"}],"author":"Jelena Zivancevic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Jelena Zivancevic","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\/"},"author":{"name":"Jelena Zivancevic","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad"},"headline":"Die 5 wichtigsten Vorteile von Matrix gegen\u00fcber Metalldoppelb\u00f6den","datePublished":"2022-05-05T08:06:15+00:00","dateModified":"2022-05-05T09:21:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\/"},"wordCount":290,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/05\/Matrix-vs-metal-floors-2.jpg","keywords":["Access floors","Doppelb\u00f6den","Fundamentl\u00f6sungen","Matrix","MEP-Systemen"],"articleSection":["Foundations","Fundamente"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\/","url":"https:\/\/www.geoplastglobal.com\/de\/blog\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\/","name":"Die 5 wichtigsten Vorteile von Matrix gegen\u00fcber Metalldoppelb\u00f6den &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/05\/Matrix-vs-metal-floors-2.jpg","datePublished":"2022-05-05T08:06:15+00:00","dateModified":"2022-05-05T09:21:58+00:00","description":"Matrix wurde f\u00fcr eine einfache MEP-Installation mit vielen Verbesserungen im Vergleich zu Metallsockelb\u00f6den entwickelt. Hier ist eine Liste der 5 wichtigsten Vorteile.","inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/de\/blog\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/die-5-wichtigsten-vorteile-von-matrix-gegenueber-metalldoppelboeden\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/05\/Matrix-vs-metal-floors-2.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2022\/05\/Matrix-vs-metal-floors-2.jpg","width":1240,"height":500,"caption":"Die 5 wichtigsten Vorteile von Matrix gegen\u00fcber Metalldoppelb\u00f6den"},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/de\/#website","url":"https:\/\/www.geoplastglobal.com\/de\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/de\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad","name":"Jelena Zivancevic","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","caption":"Jelena Zivancevic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/169417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/comments?post=169417"}],"version-history":[{"count":2,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/169417\/revisions"}],"predecessor-version":[{"id":169419,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/169417\/revisions\/169419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/media\/169433"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/media?parent=169417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/categories?post=169417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/tags?post=169417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}