
{"id":143514,"date":"2021-01-06T14:19:43","date_gmt":"2021-01-06T14:19:43","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/blog\/our-2020-favorite-posts\/"},"modified":"2021-08-19T14:16:15","modified_gmt":"2021-08-19T14:16:15","slug":"unsere-lieblingsbeitraege-2020-monat-fuer-monat","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\/","title":{"rendered":"Unsere Lieblingsbeitr\u00e4ge 2020 Monat f\u00fcr Monat"},"content":{"rendered":"2020 war ein anderes Jahr, in dem wir unser Bestes gegeben haben, um unserer Vision und unseren Kunden treu zu bleiben. Unsere Lieblingsartikel erz\u00e4hlen unsere 2020 Geschichte Monat f\u00fcr Monat:\r\n\r\n<h2>Januar 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/5-beispiele-fuer-nachhaltig-profitable-projekte\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" style=\"max-width: 50%;\" src=\"\/wp-content\/uploads\/2020\/01\/Marmara.jpg\" alt=\"\" \/><p style=\"font-size: 1.2em;\">5 Beispiele f\u00fcr nachhaltig profitable Projekte<\/p><\/a>\r\n\r\n<h2>Februar 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/neueste-kenntnisse-in-konstruktion-ingenieurwesen-und-architektur-mit-geoplastglobal-com-ressourcen\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" style=\"max-width: 50%;\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/01\/Resources-DE.jpg\" alt=\"\" \/><p style=\"font-size: 1.2em;\">Neueste Kenntnisse in Konstruktion, Ingenieurwesen und Architektur mit GeoplastGlobal.com Ressourcen<\/p><\/a>\r\n\r\n<h2>M\u00e4rz 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/bauprojekte-sind-mit-geoplast-fundamenten-rentabler\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" style=\"max-width: 50%;\" src=\"\/wp-content\/uploads\/2020\/03\/Modulo-construction-site-Symbiosis-Milan.jpg\" alt=\"\" \/><p style=\"font-size: 1.2em;\">Bauprojekte sind mit Geoplast-Fundamenten rentabler<\/p><\/a>\r\n\r\n<h2>April 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/kostenersparnis-und-profitabilitaet-im-bau-werden-nach-der-coronavirus-krise-wichtiger-sein\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" style=\"max-width: 50%;\" src=\"\/wp-content\/uploads\/2020\/01\/Completa-Despar.jpg\" alt=\"\" \/><p style=\"font-size: 1.2em;\">Kostenersparnis und Profitabilit\u00e4t im Bau werden nach der Coronavirus-Krise wichtiger sein<\/p><\/a>\r\n\r\n<h2>Mai 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/5-neue-schlanke-profitable-und-nachhaltige-geoplast-projekte\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" style=\"max-width: 50%;\" src=\"\/wp-content\/uploads\/2020\/05\/all-5-us-projects-2.jpg\" alt=\"\" \/><p style=\"font-size: 1.2em;\">5 neue schlanke, profitable und nachhaltige Geoplast Projekte<\/p><\/a>\r\n\r\n<h2>Juni 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-neuesten-schalungs-und-fundamentprojekte\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" style=\"max-width: 50%;\" src=\"\/wp-content\/uploads\/2020\/06\/Legoland-1.jpg\" alt=\"\" \/><p style=\"font-size: 1.2em;\">Unsere neuesten Schalungs- und Fundamentprojekte<\/p><\/a>\r\n\r\n<h2>Juli 2020<\/h2>\r\n<a href=\"\/en\/blog\/aquabox-geoplast-new-product-for-rainwater-management-better-roi-and-resilience\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" style=\"max-width: 50%;\" src=\"\/wp-content\/uploads\/2020\/07\/Aquabox-Cover.jpg\" alt=\"\" \/><p style=\"font-size: 1.2em;\">Aquabox &#8211; neues Produkt f\u00fcr Regenwassermanagement, besseren ROI und Widerstandsf\u00e4higkei\r\n<\/p><\/a>\r\n\r\n<h2>August 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/aquabox-ist-3-mal-besser-als-kies\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" style=\"max-width: 50%;\" src=\"\/wp-content\/uploads\/2020\/07\/Aquabox-vs-Gravel-cover.jpg\" alt=\"\" \/><p style=\"font-size: 1.2em;\">Aquabox ist 3 Mal besser als Kies<\/p><\/a>\r\n\r\n<h2>September 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/100-moeglichkeiten-bauprojekte-besser-zu-machen\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" style=\"max-width: 50%;\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/01\/100-WAYS-4-DE.jpg\" alt=\"\" \/><p style=\"font-size: 1.2em;\">100 M\u00f6glichkeiten Bauprojekte besser zu machen<\/p><\/a>\r\n\r\n<h2>Oktober 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/top-3-methoden-zur-nachhaltigen-nachruestung-bestehender-gebaeude\/\" target=\"_blank\" rel=\"noopener\"><img style=\"max-width: 50%;\"src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/01\/craighouse-1.png\" alt=\"\" \/><p style=\"font-size: 1.2em;\">Top 3 Methoden zur nachhaltigen Nachr\u00fcstung bestehender Geb\u00e4ude<\/p><\/a>\r\n\r\n<h2>November 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/geopanel-geotub-geopanel-star-schalung-einfache-installationsvideos\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" style=\"max-width: 50%;\" src=\"\/wp-content\/uploads\/2020\/11\/FORMWORK-VIDEOS.jpg\" alt=\"\" \/><p style=\"font-size: 1.2em;\">Geopanel, Geotub, Geopanel Star Schalung einfache Installationsvideos<\/p><\/a>\r\n\r\n<h2>Dezember 2020<\/h2>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-vorhersagen-fuer-2021\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" style=\"max-width: 50%;\" src=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/01\/Geoplast-2021-Blog-Post-DE.jpg\" alt=\"\" \/><p style=\"font-size: 1.2em;\">Unsere Vorhersagen f\u00fcr 2021<\/p><\/a>\r\n","protected":false},"excerpt":{"rendered":"<p>2020 war ein anderes Jahr, in dem wir unser Bestes gegeben haben, um unserer Vision und unseren Kunden treu zu bleiben. Unsere Lieblingsartikel erz\u00e4hlen unsere 2020 Geschichte Monat f\u00fcr Monat: Januar 2020 5 Beispiele f\u00fcr nachhaltig profitable Projekte Februar 2020 Neueste Kenntnisse in Konstruktion, Ingenieurwesen und Architektur mit GeoplastGlobal.com Ressourcen [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":143518,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[39,4862],"tags":[3107,3108],"class_list":["post-143514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten","category-ueber-uns","tag-2020-de","tag-vision-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unsere Lieblingsbeitr\u00e4ge 2020 Monat f\u00fcr Monat &#8211; Geoplast<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unsere Lieblingsbeitr\u00e4ge 2020 Monat f\u00fcr Monat &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"2020 war ein anderes Jahr, in dem wir unser Bestes gegeben haben, um unserer Vision und unseren Kunden treu zu bleiben. Unsere Lieblingsartikel erz\u00e4hlen unsere 2020 Geschichte Monat f\u00fcr Monat: Januar 2020 5 Beispiele f\u00fcr nachhaltig profitable Projekte Februar 2020 Neueste Kenntnisse in Konstruktion, Ingenieurwesen und Architektur mit GeoplastGlobal.com Ressourcen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-06T14:19:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-19T14:16:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/01\/2020-geoplast-german.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jelena Zivancevic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jelena Zivancevic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\\\/\"},\"author\":{\"name\":\"Jelena Zivancevic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\"},\"headline\":\"Unsere Lieblingsbeitr\u00e4ge 2020 Monat f\u00fcr Monat\",\"datePublished\":\"2021-01-06T14:19:43+00:00\",\"dateModified\":\"2021-08-19T14:16:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\\\/\"},\"wordCount\":140,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/2020-geoplast-german.jpg\",\"keywords\":[\"2020\",\"vision\"],\"articleSection\":[\"Nachrichten\",\"\u00dcber uns\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\\\/\",\"name\":\"Unsere Lieblingsbeitr\u00e4ge 2020 Monat f\u00fcr Monat &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/2020-geoplast-german.jpg\",\"datePublished\":\"2021-01-06T14:19:43+00:00\",\"dateModified\":\"2021-08-19T14:16:15+00:00\",\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/2020-geoplast-german.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/2020-geoplast-german.jpg\",\"width\":1240,\"height\":500},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/person\\\/6dea230320a3206d0db634600e4a37ad\",\"name\":\"Jelena Zivancevic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g\",\"caption\":\"Jelena Zivancevic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unsere Lieblingsbeitr\u00e4ge 2020 Monat f\u00fcr Monat &#8211; Geoplast","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\/","og_locale":"de_DE","og_type":"article","og_title":"Unsere Lieblingsbeitr\u00e4ge 2020 Monat f\u00fcr Monat &#8211; Geoplast","og_description":"2020 war ein anderes Jahr, in dem wir unser Bestes gegeben haben, um unserer Vision und unseren Kunden treu zu bleiben. Unsere Lieblingsartikel erz\u00e4hlen unsere 2020 Geschichte Monat f\u00fcr Monat: Januar 2020 5 Beispiele f\u00fcr nachhaltig profitable Projekte Februar 2020 Neueste Kenntnisse in Konstruktion, Ingenieurwesen und Architektur mit GeoplastGlobal.com Ressourcen [&hellip;]","og_url":"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2021-01-06T14:19:43+00:00","article_modified_time":"2021-08-19T14:16:15+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/01\/2020-geoplast-german.jpg","type":"image\/jpeg"}],"author":"Jelena Zivancevic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Jelena Zivancevic","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\/"},"author":{"name":"Jelena Zivancevic","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad"},"headline":"Unsere Lieblingsbeitr\u00e4ge 2020 Monat f\u00fcr Monat","datePublished":"2021-01-06T14:19:43+00:00","dateModified":"2021-08-19T14:16:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\/"},"wordCount":140,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/01\/2020-geoplast-german.jpg","keywords":["2020","vision"],"articleSection":["Nachrichten","\u00dcber uns"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\/","url":"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\/","name":"Unsere Lieblingsbeitr\u00e4ge 2020 Monat f\u00fcr Monat &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/01\/2020-geoplast-german.jpg","datePublished":"2021-01-06T14:19:43+00:00","dateModified":"2021-08-19T14:16:15+00:00","inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-lieblingsbeitraege-2020-monat-fuer-monat\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/01\/2020-geoplast-german.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2021\/01\/2020-geoplast-german.jpg","width":1240,"height":500},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/de\/#website","url":"https:\/\/www.geoplastglobal.com\/de\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/de\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/person\/6dea230320a3206d0db634600e4a37ad","name":"Jelena Zivancevic","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f1f981ef0b8e2ff05ea92e7eae53fa712ec639ac29ed4ba275f1c8b446650a8?s=96&d=mm&r=g","caption":"Jelena Zivancevic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/143514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/comments?post=143514"}],"version-history":[{"count":3,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/143514\/revisions"}],"predecessor-version":[{"id":143569,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/143514\/revisions\/143569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/media\/143518"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/media?parent=143514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/categories?post=143514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/tags?post=143514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}