
{"id":141740,"date":"2020-10-26T11:11:22","date_gmt":"2020-10-26T11:11:22","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/blog\/skyrail-contains-mep-in-commercial-buildings\/"},"modified":"2021-01-12T13:55:13","modified_gmt":"2021-01-12T13:55:13","slug":"skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/de\/blog\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\/","title":{"rendered":"Skyrail: enth\u00e4lt die Geb\u00e4udetechnik in   Gesch\u00e4ftsgeb\u00e4uden"},"content":{"rendered":"<a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/decke\/skyrail\/\" rel=\"noopener noreferrer\" target=\"_blank\">Skyrail<\/a> ist eine wiederverwendbare Schalung f\u00fcr den Bau von unidirektionalen gerippten  Betonplatten, die als Geb\u00e4udetechnikfach verwendet werden k\u00f6nnen. Der Abstand  zwischen den Betonrippen erm\u00f6glicht die Platzierung von hydraulischen und elektrischen  Systemen innerhalb des Plattenvolumens. Diese L\u00f6sung eignet sich besonders f\u00fcr  gewerbliche Geb\u00e4ude mit gro\u00dfen Spannweiten und komplexen Geb\u00e4udetechnikl\u00f6sungen.\r\n \r\nEin wichtiger Aspekt der gewerblichen Geb\u00e4udeplanung ist eine effiziente und funktionale  Raumnutzung. Skyrail ist eine <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/decke\/mehrwegschalung-fur-leichtbaudecken\/\" rel=\"noopener noreferrer\" target=\"_blank\">kosteng\u00fcnstige L\u00f6sung<\/a>, die leichte Platten f\u00fcr gro\u00dfe  Spannweiten bietet, einen einfachen Zugang zur Installation f\u00fcr Reparaturen erm\u00f6glicht und  maximale Bodenh\u00f6he gew\u00e4hrleistet. Daher spart unsere Betonplattenl\u00f6sung sowohl Kosten  als auch Platz und erm\u00f6glicht ein elegantes Deckendesign.\r\n \r\n<h3>\u00dcber Skyrail<\/h3>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/decke\/skyrail\/\" rel=\"noopener noreferrer\" target=\"_blank\">Skyrail<\/a>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/decke\/\" rel=\"noopener noreferrer\" target=\"_blank\">L\u00f6sungen F\u00fcr Platten<\/a>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/decke\/monodirektionale-decken-fur-burogebaude\/\" rel=\"noopener noreferrer\" target=\"_blank\">Monodirektionale Decken f\u00fcr B\u00fcrogeb\u00e4ude<\/a>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/decke\/mehrwegschalung-fur-leichtbaudecken\/\" rel=\"noopener noreferrer\" target=\"_blank\">Mehrwegschalung f\u00fcr Leichtbaudecken<\/a>\r\n \r\n<h3>\u00dcber Leichtbauplatten<\/h3>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-platten-reduzieren-baukosten\/\" rel=\"noopener noreferrer\" target=\"_blank\">Unsere Platten reduzieren Baukosten<\/a>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/leichtbauplatten-eignen-sich-hervorragend-fuer-familienhaeuser\/\" rel=\"noopener noreferrer\" target=\"_blank\">Leichtbauplatten eignen sich hervorragend f\u00fcr Familienh\u00e4user<\/a>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-den-co2-ausstoss-von-zement-reduziert\/\" rel=\"noopener noreferrer\" target=\"_blank\">Wie man den CO2-Aussto\u00df von Zement reduziert<\/a>\r\n<a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/gebaeude-die-wiederverwendet-werden-koennen-sind-nachhaltiger-und-eine-bessere-investition\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geb\u00e4ude, die wiederverwendet werden k\u00f6nnen, sind nachhaltiger und eine bessere Investition<\/a>\r\n","protected":false},"excerpt":{"rendered":"<p>Skyrail ist eine wiederverwendbare Schalung f\u00fcr den Bau von unidirektionalen gerippten Betonplatten, die als Geb\u00e4udetechnikfach verwendet werden k\u00f6nnen. Der Abstand zwischen den Betonrippen erm\u00f6glicht die Platzierung von hydraulischen und elektrischen Systemen innerhalb des Plattenvolumens. Diese L\u00f6sung eignet sich besonders f\u00fcr gewerbliche Geb\u00e4ude mit gro\u00dfen Spannweiten und komplexen Geb\u00e4udetechnikl\u00f6sungen. Ein wichtiger [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":141742,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[83,2980],"tags":[1105,651,2745,2328,2762,1944],"class_list":["post-141740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-decke-de","category-quick-fact-de","tag-leichtbauplatten","tag-leichtbeton-platte","tag-loesungen-fuer-platten","tag-monodirectional-slabs","tag-nachhaltigen-profitabilitaet","tag-skyrail-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Skyrail: enth\u00e4lt die Geb\u00e4udetechnik in  Gesch\u00e4ftsgeb\u00e4uden &#8211; Geoplast<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Skyrail: enth\u00e4lt die Geb\u00e4udetechnik in  Gesch\u00e4ftsgeb\u00e4uden &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Skyrail ist eine wiederverwendbare Schalung f\u00fcr den Bau von unidirektionalen gerippten Betonplatten, die als Geb\u00e4udetechnikfach verwendet werden k\u00f6nnen. Der Abstand zwischen den Betonrippen erm\u00f6glicht die Platzierung von hydraulischen und elektrischen Systemen innerhalb des Plattenvolumens. Diese L\u00f6sung eignet sich besonders f\u00fcr gewerbliche Geb\u00e4ude mit gro\u00dfen Spannweiten und komplexen Geb\u00e4udetechnikl\u00f6sungen. Ein wichtiger [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/de\/blog\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-26T11:11:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-12T13:55:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2020\/10\/QUICK-FACT-SKYRAIL-DE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marija Martinovic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marija Martinovic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\\\/\"},\"author\":{\"name\":\"Marija Martinovic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/person\\\/020c9bd0060fa2a0b3130cd37b971cbc\"},\"headline\":\"Skyrail: enth\u00e4lt die Geb\u00e4udetechnik in Gesch\u00e4ftsgeb\u00e4uden\",\"datePublished\":\"2020-10-26T11:11:22+00:00\",\"dateModified\":\"2021-01-12T13:55:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\\\/\"},\"wordCount\":183,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/QUICK-FACT-SKYRAIL-DE.jpg\",\"keywords\":[\"Leichtbauplatten\",\"Leichtbeton Platte\",\"L\u00f6sungen F\u00fcr Platten\",\"Monodirectional slabs\",\"Nachhaltigen Profitabilit\u00e4t\",\"Skyrail\"],\"articleSection\":[\"Decke\",\"Quick Fact\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\\\/\",\"name\":\"Skyrail: enth\u00e4lt die Geb\u00e4udetechnik in Gesch\u00e4ftsgeb\u00e4uden &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/QUICK-FACT-SKYRAIL-DE.jpg\",\"datePublished\":\"2020-10-26T11:11:22+00:00\",\"dateModified\":\"2021-01-12T13:55:13+00:00\",\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/QUICK-FACT-SKYRAIL-DE.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/QUICK-FACT-SKYRAIL-DE.jpg\",\"width\":1240,\"height\":500},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/person\\\/020c9bd0060fa2a0b3130cd37b971cbc\",\"name\":\"Marija Martinovic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f926bf327fd40f703774793ef896f698790e258141e48dc50352732cc2c9def3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f926bf327fd40f703774793ef896f698790e258141e48dc50352732cc2c9def3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f926bf327fd40f703774793ef896f698790e258141e48dc50352732cc2c9def3?s=96&d=mm&r=g\",\"caption\":\"Marija Martinovic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Skyrail: enth\u00e4lt die Geb\u00e4udetechnik in  Gesch\u00e4ftsgeb\u00e4uden &#8211; Geoplast","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/de\/blog\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\/","og_locale":"de_DE","og_type":"article","og_title":"Skyrail: enth\u00e4lt die Geb\u00e4udetechnik in  Gesch\u00e4ftsgeb\u00e4uden &#8211; Geoplast","og_description":"Skyrail ist eine wiederverwendbare Schalung f\u00fcr den Bau von unidirektionalen gerippten Betonplatten, die als Geb\u00e4udetechnikfach verwendet werden k\u00f6nnen. Der Abstand zwischen den Betonrippen erm\u00f6glicht die Platzierung von hydraulischen und elektrischen Systemen innerhalb des Plattenvolumens. Diese L\u00f6sung eignet sich besonders f\u00fcr gewerbliche Geb\u00e4ude mit gro\u00dfen Spannweiten und komplexen Geb\u00e4udetechnikl\u00f6sungen. Ein wichtiger [&hellip;]","og_url":"https:\/\/www.geoplastglobal.com\/de\/blog\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2020-10-26T11:11:22+00:00","article_modified_time":"2021-01-12T13:55:13+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2020\/10\/QUICK-FACT-SKYRAIL-DE.jpg","type":"image\/jpeg"}],"author":"Marija Martinovic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Marija Martinovic","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\/"},"author":{"name":"Marija Martinovic","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/person\/020c9bd0060fa2a0b3130cd37b971cbc"},"headline":"Skyrail: enth\u00e4lt die Geb\u00e4udetechnik in Gesch\u00e4ftsgeb\u00e4uden","datePublished":"2020-10-26T11:11:22+00:00","dateModified":"2021-01-12T13:55:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\/"},"wordCount":183,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2020\/10\/QUICK-FACT-SKYRAIL-DE.jpg","keywords":["Leichtbauplatten","Leichtbeton Platte","L\u00f6sungen F\u00fcr Platten","Monodirectional slabs","Nachhaltigen Profitabilit\u00e4t","Skyrail"],"articleSection":["Decke","Quick Fact"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\/","url":"https:\/\/www.geoplastglobal.com\/de\/blog\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\/","name":"Skyrail: enth\u00e4lt die Geb\u00e4udetechnik in Gesch\u00e4ftsgeb\u00e4uden &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2020\/10\/QUICK-FACT-SKYRAIL-DE.jpg","datePublished":"2020-10-26T11:11:22+00:00","dateModified":"2021-01-12T13:55:13+00:00","inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/de\/blog\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/skyrail-enthaelt-die-gebaeudetechnik-in-geschaeftsgebaeuden\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2020\/10\/QUICK-FACT-SKYRAIL-DE.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2020\/10\/QUICK-FACT-SKYRAIL-DE.jpg","width":1240,"height":500},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/de\/#website","url":"https:\/\/www.geoplastglobal.com\/de\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/de\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/person\/020c9bd0060fa2a0b3130cd37b971cbc","name":"Marija Martinovic","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/f926bf327fd40f703774793ef896f698790e258141e48dc50352732cc2c9def3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f926bf327fd40f703774793ef896f698790e258141e48dc50352732cc2c9def3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f926bf327fd40f703774793ef896f698790e258141e48dc50352732cc2c9def3?s=96&d=mm&r=g","caption":"Marija Martinovic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/141740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/comments?post=141740"}],"version-history":[{"count":2,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/141740\/revisions"}],"predecessor-version":[{"id":141751,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/141740\/revisions\/141751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/media\/141742"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/media?parent=141740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/categories?post=141740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/tags?post=141740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}