
{"id":140955,"date":"2020-10-07T07:43:37","date_gmt":"2020-10-07T07:43:37","guid":{"rendered":"https:\/\/www.geoplastglobal.com\/blog\/100-ways-to-make-better-construction-projects\/"},"modified":"2022-04-15T12:03:00","modified_gmt":"2022-04-15T12:03:00","slug":"100-moeglichkeiten-bauprojekte-besser-zu-machen","status":"publish","type":"post","link":"https:\/\/www.geoplastglobal.com\/de\/blog\/100-moeglichkeiten-bauprojekte-besser-zu-machen\/","title":{"rendered":"100 M\u00f6glichkeiten Bauprojekte besser zu machen"},"content":{"rendered":"<p style=\"font-size: 22px;\">Unsere <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/\" rel=\"noopener noreferrer\" target=\"_blank\">Produkte<\/a> und <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/\" rel=\"noopener noreferrer\" target=\"_blank\">L\u00f6sungen<\/a> k\u00f6nnen auf viele innovative Arten kombiniert und genutzt  werden. Hier sind hundert Ideen, die Sie dazu inspirieren sollen, Ihr Konstruktionsdesign zu  verbessern:<\/p>\r\n<p style=\"line-height: 200%; font-size: 22px;\">\r\n1.\tSch\u00e4dliche D\u00e4mpfe an den Fundamenten ausl\u00fcften mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/fundamente\/modulo\/\" rel=\"noopener noreferrer\" target=\"_blank\">Modulo<\/a>\r\n2.\tErh\u00f6hen Sie den Geb\u00e4udeboden mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/fundamente\/multimodulo\/\" rel=\"noopener noreferrer\" target=\"_blank\">Multimodulo<\/a>\r\n3.\tVerbessern Sie die Schallisolierung von B\u00f6den mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/fundamente\/minimodulo\/\" rel=\"noopener noreferrer\" target=\"_blank\">Minimodulo<\/a>\r\n4.\tErh\u00f6hen Sie die Tragf\u00e4higkeit der Fundamente mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/fundamente\/neu-elevetor\/\" rel=\"noopener noreferrer\" target=\"_blank\">Neu Elevetor<\/a>\r\n5.\tKellerw\u00e4nde vor Wasser sch\u00fctzen mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/fundamente\/defender\/\" rel=\"noopener noreferrer\" target=\"_blank\">Defender<\/a>\r\n6.\tReduzieren Sie die Baukosten mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/schalungen\/geopanel\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geopanel<\/a>\r\n7.\tPassen Sie sich an unterschiedliche Konstruktionsanforderungen an mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/schalungen\/geopanel-star\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geopanel Star<\/a>\r\n8.\tBeschleunigen Sie den Bauprozess mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/schalungen\/geotub\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geotub<\/a>\r\n9.\tSparen Sie Platz auf der Baustelle mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/schalungen\/geotub-panel\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geotub Panel<\/a>\r\n10.\tMachen Sie die Platten leichter mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/decke\/neu-nautilus\/\" rel=\"noopener noreferrer\" target=\"_blank\">Neu Nautilus<\/a>\r\n11.\tErreichen Sie ein perfektes Finish der Platte mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/decke\/neu-nautilus-evo\/\" rel=\"noopener noreferrer\" target=\"_blank\">Neu Nautilus Evo<\/a>\r\n12.\tVerbessern Sie die seismische Widerstandsf\u00e4higkeit von Platten mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/decke\/skydome\/\" rel=\"noopener noreferrer\" target=\"_blank\">Skydome<\/a>\r\n13.\tNutzen Sie den Platz in den Platten f\u00fcr technische Installationen mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/decke\/skyrail\/\" rel=\"noopener noreferrer\" target=\"_blank\">Skyrail<\/a>\r\n14.\tVereinfachen Sie die Installation mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/decke\/airplast\/\" rel=\"noopener noreferrer\" target=\"_blank\">Airplast<\/a>\r\n15.\tVerwenden Sie die Schalung zur Plattenkonstruktion wieder mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/decke\/geosky\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geosky<\/a>\r\n16.\tErm\u00f6glichen Sie die Regenwasserpermeabilit\u00e4t auf Ihrem Grundst\u00fcck mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/gruen\/geograss\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geograss<\/a>\r\n17.\tSichern Sie die Zufahrtsstra\u00dfenr\u00e4nder mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/gruen\/georoad\/\" rel=\"noopener noreferrer\" target=\"_blank\">Georoad<\/a>\r\n18.\tSch\u00fctzen Sie das Gras auf Ihrer gr\u00fcnen Auffahrt mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/gruen\/salvaverde\/\" rel=\"noopener noreferrer\" target=\"_blank\">Salvaverde<\/a>\r\n19.\tVerbessern Sie die Permeabilit\u00e4t von Gehwegen mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/gruen\/geoflor\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geofloor<\/a>\r\n20.\tErschaffen Sie einen hochresistenten gr\u00fcnen Parkplatz mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/gruen\/runfloor\/\" rel=\"noopener noreferrer\" target=\"_blank\">Runfloor<\/a>\r\n21.\tSchotterparkplatz stabilisieren mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/gruen\/geogravel\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geogravel<\/a>\r\n22.\tMachen Sie eine nachhaltige gr\u00fcne Fassade mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/gruen\/wall-y\/\" rel=\"noopener noreferrer\" target=\"_blank\">Wall-Y<\/a>\r\n23.\tVerbessern Sie die Regenwasserresistenz mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/gruen\/drainroof\/\" rel=\"noopener noreferrer\" target=\"_blank\">Drainroof<\/a>\r\n24.\tOrganisieren Sie Veranstaltungen in Ihrem Garten mit Pflasterstein <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/gruen\/plastonella\/\" rel=\"noopener noreferrer\" target=\"_blank\">Plastonella<\/a>\r\n25.\tVerlangsamen Sie den Regenwasserabfluss mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/gruen\/completa\/\" rel=\"noopener noreferrer\" target=\"_blank\">Completa<\/a>\r\n26.\tPflanzen Sie mehr B\u00e4ume und verbessern Sie die Nachhaltigkeit mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/gruen\/wannen\/\" rel=\"noopener noreferrer\" target=\"_blank\">Tubs<\/a>\r\n27.\tF\u00fcgen Sie sowohl drinnen als auch drau\u00dfen viel Gr\u00fcn hinzu mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/?post_type=products&#038;p=13035\" rel=\"noopener noreferrer\" target=\"_blank\">Demetra<\/a>\r\n28.\tVerhindern Sie \u00dcberschwemmungen mit <a href=\"https:\/\/www.geoplastglobal.com\/en\/products\/water\/aquabox\/\" rel=\"noopener noreferrer\" target=\"_blank\">Aquabox<\/a>\r\n29.\tSammeln Sie Regenwasser und verlangsamen Sie die Dispersion mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/wasser\/drainpanel\/\" rel=\"noopener noreferrer\" target=\"_blank\">Drainpanel<\/a>\r\n30.\tVerbessern Sie die Regenwasserableitung mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/wasser\/drening\/\" rel=\"noopener noreferrer\" target=\"_blank\">Drening<\/a>\r\n31.\tRegulieren Sie Abwasser mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/wasser\/drening-reflue\/\" rel=\"noopener noreferrer\" target=\"_blank\">Drening Reflue<\/a>\r\n32.\tVerwenden Sie Regenwasser f\u00fcr Ihren t\u00e4glichen Bedarf wieder mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/wasser\/neu-elevetor-tank\/\" rel=\"noopener noreferrer\" target=\"_blank\">Neu Elevetor Tank<\/a>\r\n33.\tReduzieren Sie das Hochwasserrisiko mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/wasser\/geocell\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geocell<\/a>\r\n34.\tOrganisieren Sie Outdoor-Sportarten auf modularen Oberfl\u00e4chen <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/sport\/gripper-outdoor\/\" rel=\"noopener noreferrer\" target=\"_blank\">Gripper Outdoor<\/a>\r\n35.\tOrganisieren Sie Indoor-Sportarten auf modularen Oberfl\u00e4chen <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/sport\/gripper-indoor\/\" rel=\"noopener noreferrer\" target=\"_blank\">Gripper Indoor<\/a> \r\n36.\tInstallieren Sie ganz einfach einen Tennisplatz auf Ihrem Grundst\u00fcck mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/sport\/gripper-tennis\/\" rel=\"noopener noreferrer\" target=\"_blank\">Gripper Tennis<\/a>\r\n37.\tSchaffen Sie eine Gelegenheit f\u00fcr den Wintersport mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/sport\/geoski\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geoski<\/a>\r\n38.\tVerbessern Sie die Rasenfl\u00e4chen f\u00fcr den Pferdesport mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/sport\/runfloor-pferden\/\" rel=\"noopener noreferrer\" target=\"_blank\">Runfloor Horses<\/a>\r\n39.\tLassen Sie Biofiltration zu mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/umwelt\/biodrening\/\" rel=\"noopener noreferrer\" target=\"_blank\">Biodrening<\/a>\r\n40.\tVerbesserung der Abfallaufbereitung mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/produkte\/umwelt\/biomodulo\/\" rel=\"noopener noreferrer\" target=\"_blank\">Biomodulo<\/a>\r\n41.\tF\u00fcgen Sie w\u00e4hrend der Renovierung bel\u00fcftete B\u00f6den hinzu mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/fundamente\/beluftete-boden-bei-der-renovierung\/\" rel=\"noopener noreferrer\" target=\"_blank\">Minimodulo L\u00f6sung<\/a>\r\n42.\tErstellen Sie eine bel\u00fcftete Dachschicht mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/fundamente\/belueftete-dacher-und-waenden\/\" rel=\"noopener noreferrer\" target=\"_blank\">Minimodulo L\u00f6sung<\/a>\r\n43.\tSorgen Sie f\u00fcr eine nat\u00fcrliche Bel\u00fcftung der Fundamente mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/fundamente\/fundamente-fur-wohngebaude\/\" rel=\"noopener noreferrer\" target=\"_blank\">Modulo L\u00f6sung<\/a>\r\n44.\tErstellen Sie strukturelle F\u00fcllungen f\u00fcr Treppen und Rampen mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/fundamente\/modulare-aufstiegsrampen-und-treppen\/\" rel=\"noopener noreferrer\" target=\"_blank\">Neu Elevetor L\u00f6sung<\/a>\r\n45.\tL\u00fcften Sie Fundamentw\u00e4nde mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/fundamente\/schutz-der-kellerwande\/\" rel=\"noopener noreferrer\" target=\"_blank\">Defender L\u00f6sung<\/a>\r\n46.\tVerbessern Sie die W\u00e4rmeisolierung der Fundamente mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/fundamente\/vorgefertigte-gebaeuden\/\" rel=\"noopener noreferrer\" target=\"_blank\">Modulo L\u00f6sung<\/a>\r\n47.\tBel\u00fcftete Fundamente f\u00fcr Industriegeb\u00e4ude erm\u00f6glichen mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/fundamente\/fundamente-fur-industriebauten\/\" rel=\"noopener noreferrer\" target=\"_blank\">Modulo L\u00f6sung<\/a>\r\n48.\tVerhindern Sie Frostsch\u00e4den in K\u00fchlh\u00e4usern mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/fundamente\/industrielle-kuehlhauslager\/\" rel=\"noopener noreferrer\" target=\"_blank\">Fundamentl\u00f6sungen<\/a>\r\n49.\tVerbessern Sie die Gesundheit von Bewohnern mit einer <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/fundamente\/eindringen-von-daempfen\/\" rel=\"noopener noreferrer\" target=\"_blank\">Modulo L\u00f6sung<\/a>\r\n50.\tRenovieren Sie degradierte S\u00e4ulen mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/schalungen\/sanierung-von-saulen\/\" rel=\"noopener noreferrer\" target=\"_blank\">Schalungsl\u00f6sungen<\/a>\r\n51.\tSparen Sie Kosten f\u00fcr den Poolbau mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/schalungen\/bau-von-schwimmbader-aus-stahlbeton\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geopanel L\u00f6sung<\/a> \r\n52.\tVerbessern Sie die Logistik auf der Baustelle mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/schalungen\/bunkerbau\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geopanel L\u00f6sung<\/a>\r\n53.\tBieten Sie Stabilit\u00e4t bei der S\u00e4ulenkonstruktion mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/schalungen\/realisierung-von-elliptischen-saulen\/\" rel=\"noopener noreferrer\" target=\"_blank\">Schalungsl\u00f6sungen<\/a>\r\n54.\tBeschleunigen Sie die Konstruktion durch vorgefertigte S\u00e4ulen mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/schalungen\/bau-von-fertigsaulen\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geotub L\u00f6sung<\/a>\r\n55.\tVerbessern Sie die seismische Resilienz der Struktur mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/schalungen\/anpassung-erdbebenrisiko\/\" rel=\"noopener noreferrer\" target=\"_blank\">Schalungsl\u00f6sungen<\/a>\r\n56.\tPassen Sie sich an Unterwasserkonstruktionen an mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/schalungen\/saeulen-im-wasser-wiederaufbauen\/\" rel=\"noopener noreferrer\" target=\"_blank\">Schalungsl\u00f6sungen<\/a>\r\n57.\tSch\u00fctzen Sie das Geb\u00e4ude vor Wirbelst\u00fcrmen mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/schalungen\/loesungen-fuer-hurrikansichere-gebaeude-in-florida-usa\/\" rel=\"noopener noreferrer\" target=\"_blank\">Schalungsl\u00f6sungen<\/a>\r\n58.\tReparieren Sie besch\u00e4digten Beton mit einer <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/schalungen\/reparatur-von-betonsaeulen\/\" rel=\"noopener noreferrer\" target=\"_blank\">Schalungsl\u00f6sungen<\/a>\r\n59.\tReduzieren Sie das strukturelle Gewicht des Geb\u00e4udes mit einer <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/decke\/gebaeudewiederverwendbarkeit-mit-leichtbauplatten\/\" rel=\"noopener noreferrer\" target=\"_blank\">Leichtbauplattenl\u00f6sung<\/a>\r\n60.\tErh\u00f6hen Sie die Spannweite zwischen den S\u00e4ulen auf einem Parkplatz mit einer <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/decke\/zweiachsige-decke-fur-parkhauser\/\" rel=\"noopener noreferrer\" target=\"_blank\">Plattenl\u00f6sung<\/a>\r\n61.\tReduzieren Sie die Kosten f\u00fcr die Plattenkonstruktion mit wiederverwendbaren <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/decke\/mehrwegschalung-fur-leichtbaudecken\/\" rel=\"noopener noreferrer\" target=\"_blank\">Plattenl\u00f6sungen<\/a>\r\n62.\tVerringern Sie den Betonverbrauch der Platte mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/decke\/leichte-fundament-beton-einwegschalung\/\" rel=\"noopener noreferrer\" target=\"_blank\">Neu Nautilus L\u00f6sung<\/a>\r\n63.\tReduzieren Sie die seismische Masse des Geb\u00e4udes mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/decke\/unidirektionale-decke-fur-wohngebaude\/\" rel=\"noopener noreferrer\" target=\"_blank\">Skyrail L\u00f6sung<\/a>\r\n64.\tErh\u00f6hen Sie die offene Bodenfl\u00e4che mit einer <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/decke\/zweiachsige-decke-fur-gewerbegebaude\/\" rel=\"noopener noreferrer\" target=\"_blank\">Leichtbauplanl\u00f6sung<\/a>\r\n65.\tR\u00fcsten Sie ein intensives Gartendach nach mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/gruen\/intensive-dachgarten\/\" rel=\"noopener noreferrer\" target=\"_blank\">Drainroof L\u00f6sung<\/a>\r\n66.\tGeringerer CO2-Verbrauch durch ein weitl\u00e4ufiges Gr\u00fcndach mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/gruen\/extensive-dachgarten-mit-gras\/\" rel=\"noopener noreferrer\" target=\"_blank\">Drainroof L\u00f6sung<\/a>\r\n67.\tErstellen Sie einen pflegeleichten Sedum-Dachgarten mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/gruen\/extensive-dachgarten-mit-sedum\/\" rel=\"noopener noreferrer\" target=\"_blank\">Drainroof L\u00f6sung<\/a>\r\n68.\tInstallieren Sie ein kosteng\u00fcnstiges modulares Kunststoffgitter mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/gruen\/rasenschutz-fur-temporare-veranstaltungen\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geoflor L\u00f6sung<\/a>\r\n69.\tSch\u00fctzen Sie die Baumwurzeln mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/gruen\/neu-elevatorwurzelschutz\/\" rel=\"noopener noreferrer\" target=\"_blank\">Neu Elevetor L\u00f6sung<\/a>\r\n70.\tVerbessern Sie die Luftqualit\u00e4t mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/gruen\/gruene-aussenwand\/\" rel=\"noopener noreferrer\" target=\"_blank\">Wall-Y green facade<\/a>\r\n71.\tProduzieren Sie Obst und Gem\u00fcse auf Dachfarmen mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/gruen\/urbane-dachfarmen\/\" rel=\"noopener noreferrer\" target=\"_blank\">Drainroof L\u00f6sung<\/a>\r\n72.\tVerbessern Sie die Regenwassersubdispersion mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/wasser\/untergrundbewasserung\/\" rel=\"noopener noreferrer\" target=\"_blank\">Drening Reflue L\u00f6sung<\/a>\r\n73.\tSammeln Sie Regenwasser f\u00fcr Ihren Haushaltsbedarf mit einer <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/wasser\/hausliche-regenwassernutzung\/\" rel=\"noopener noreferrer\" target=\"_blank\">Wasserl\u00f6sung<\/a>\r\n74.\tSpeichern Sie Wasser f\u00fcr den Brandschutz mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/wasser\/feuerschutzreserven\/\" rel=\"noopener noreferrer\" target=\"_blank\">Neu Elevetor Tank L\u00f6sung<\/a>\r\n75.\tRegenwasser zur Bew\u00e4sserung wiederverwenden mit einer <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/wasser\/bewasserung-von-grunanlagen\/\" rel=\"noopener noreferrer\" target=\"_blank\">Wasserl\u00f6sung<\/a>\r\n76.\tReinigen Sie das Wasser von Schadstoffen mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/wasser\/bewasserungsanlage-und-phytoreinigung\/\" rel=\"noopener noreferrer\" target=\"_blank\">Drening L\u00f6sung<\/a>\r\n77.\tEntsorgen Sie \u00fcbersch\u00fcssiges Wasser, dass auf dem Grundst\u00fcck zur\u00fcckgehalten wird mit  einer <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/wasser\/entwasserung-von-wohn-und-geschaftsgebauden\/\" rel=\"noopener noreferrer\" target=\"_blank\">Wasserl\u00f6sung<\/a>\r\n78.\tNiedrigere Kosten f\u00fcr Fertigh\u00e4user mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/mehrfachloesung\/geohouse-sozialwohnungen\/\" rel=\"noopener noreferrer\" target=\"_blank\">Geohouse Sozialwohnungen<\/a>\r\n79.\tVerbesserung der Biofiltration mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/umwelt\/biofiltration\/\" rel=\"noopener noreferrer\" target=\"_blank\">Biodrening und Biomodulo<\/a>\r\n80.\tBeschleunigen Sie den Bauprozess mit der <a href=\"https:\/\/www.geoplastglobal.com\/de\/losungen\/mehrfachloesung\/geoplast-build-fast-methode\/\" rel=\"noopener noreferrer\" target=\"_blank\">Build Fast Methode<\/a>\r\n81.\tVerbessern Sie <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-unsere-produkte-die-sicherheit-auf-der-baustelle-verbessern\/\" rel=\"noopener noreferrer\" target=\"_blank\">Sicherheit auf der Baustelle<\/a> mit unseren Produkten\r\n82.\tReduzieren Sie mit unseren Produkten die <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/wwf-bericht-2019-ueber-die-verschmutzung-durch-plastikmuell-kritische-fragen-und-aktionsplan\/\" rel=\"noopener noreferrer\" target=\"_blank\">Umweltverschmutzung durch Plastikm\u00fcll<\/a>\r\n83.\tReduzieren Sie Transport- und Lagerkosten mit unseren <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-leichte-plastikschalungen-vorteile\/\" rel=\"noopener noreferrer\" target=\"_blank\">Leichtprodukten<\/a>\r\n84.\tVerbessern Sie die st\u00e4dtische Widerstandsf\u00e4higkeit gegen \u00dcberschwemmungen mit  unseren <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-erzeugnise-die-die-staedtische-widerstandsfaehigkeit-verbessern\/\" rel=\"noopener noreferrer\" target=\"_blank\">Wasserl\u00f6sungen<\/a>\r\n85.\tVerst\u00e4rken Sie mit unseren Produkten die seismische Resilienz von <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-loesungen-fuer-hochhaeuser\/\" rel=\"noopener noreferrer\" target=\"_blank\">Hochh\u00e4usern<\/a>\r\n86.\tSch\u00fctzen Sie mit unseren L\u00f6sungen das <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/nachhaltige-erbschaft-top-geoplast-projekte\/\" rel=\"noopener noreferrer\" target=\"_blank\">architektonische Erbe<\/a>\r\n87.\tVerst\u00e4rken Sie die <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-produkte-unterstuetzen-lean-construction\/\" rel=\"noopener noreferrer\" target=\"_blank\">Lean Construction<\/a> des Projekts mit unseren L\u00f6sungen\r\n88.\tErh\u00f6hen Sie den Wiederverkaufspreis der Immobilie mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/gebaeude-die-wiederverwendet-werden-koennen-sind-nachhaltiger-und-eine-bessere-investition\/\" rel=\"noopener noreferrer\" target=\"_blank\">wiederverwendbaren Produkten<\/a>\r\n89.\tVerst\u00e4rken Sie die Widerstandsf\u00e4higkeit der St\u00e4dte mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplast-infrastrukturloesungen-verbessern-die-widerstandsfaehigkeit-von-staedten\/\" rel=\"noopener noreferrer\" target=\"_blank\">unseren Infrastrukturl\u00f6sungen<\/a>\r\n90.\tReduzieren Sie mit unseren L\u00f6sungen die <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-man-den-co2-ausstoss-von-zement-reduziert\/\" rel=\"noopener noreferrer\" target=\"_blank\">CO2 Emissionen<\/a>\r\n91.\tVerbessern Sie die <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/2020-ist-das-jahr-der-nachhaltigen-profitabilitaet\/\" rel=\"noopener noreferrer\" target=\"_blank\">nachhaltige Rentabilit\u00e4t<\/a> Ihres Projekts\r\n92.\tSparen Sie mit unseren gr\u00fcnen L\u00f6sungen <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/energiekosteneinsparungen-mit-gruenen-loesungen-von-geoplast\/\" rel=\"noopener noreferrer\" target=\"_blank\">Energiekosten<\/a>\r\n93.\tSteigern Sie den Immobilienwert mit unseren <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-unsere-gruen-und-wasserloesungen-zusammen-den-immobilienwert-steigern\/\" rel=\"noopener noreferrer\" target=\"_blank\">Gr\u00fcn- und Wasserl\u00f6sungen<\/a>\r\n94.\tMachen Sie Bauprojekte mit <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/wie-geoplast-schalungen-gebaeude-profitabler-machen\/\" rel=\"noopener noreferrer\" target=\"_blank\">unseren Schalungsl\u00f6sungen rentabler<\/a>\r\n95.\tVerbessern Sie die <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/bauprojekte-sind-mit-geoplast-fundamenten-rentabler\/\" rel=\"noopener noreferrer\" target=\"_blank\">technischen Leistungen<\/a> des Geb\u00e4udes mit unseren Fundamenten\r\n96.\tReduzieren Sie mit unseren Platten die <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/unsere-platten-reduzieren-baukosten\/\" rel=\"noopener noreferrer\" target=\"_blank\">Baukosten<\/a>\r\n97.\tReduzieren Sie mit unseren L\u00f6sungen <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/5-moeglichkeiten-um-heimkosten-zu-sparen\/\" rel=\"noopener noreferrer\" target=\"_blank\">die Haushaltskosten<\/a>\r\n98.\tSenken Sie Ihre Kosten f\u00fcr <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/geoplastschalung-fuer-leichte-strukturfuellungen\/\" rel=\"noopener noreferrer\" target=\"_blank\">Strukturf\u00fcllungen<\/a> mit unseren Fundamentl\u00f6sungen\r\n99.\t<a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/verschwenden-sie-kein-geld-mehr-fuer-den-bau\/\" rel=\"noopener noreferrer\" target=\"_blank\">Verschwenden Sie kein Geld<\/a> mehr f\u00fcr den Bau\r\n100.\tLeisten Sie sich <a href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/mit-aquabox-koennen-sie-sich-tesla-model-3-leisten\/\" rel=\"noopener noreferrer\" target=\"_blank\">mit Aquabox einen Tesla Model 3<\/a><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Unsere Produkte und L\u00f6sungen k\u00f6nnen auf viele innovative Arten kombiniert und genutzt werden. Hier sind hundert Ideen, die Sie dazu inspirieren sollen, Ihr Konstruktionsdesign zu verbessern: 1. Sch\u00e4dliche D\u00e4mpfe an den Fundamenten ausl\u00fcften mit Modulo 2. Erh\u00f6hen Sie den Geb\u00e4udeboden mit Multimodulo 3. Verbessern Sie die Schallisolierung von B\u00f6den mit [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":140960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2504],"tags":[2336,771,1153,2589,2762,1705,1828,1606,2759,1155,844],"class_list":["post-140955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construction-de","tag-build-fast-de","tag-fundamentloesungen","tag-grunelosungen","tag-lean-construction-de","tag-nachhaltigen-profitabilitaet","tag-nachhaltigkeit","tag-plattenloesungen","tag-resilience","tag-schalungsloesungen","tag-sportloesungen","tag-wasserloesungen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>100 M\u00f6glichkeiten Bauprojekte besser zu machen &#8211; Geoplast<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geoplastglobal.com\/de\/blog\/100-moeglichkeiten-bauprojekte-besser-zu-machen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"100 M\u00f6glichkeiten Bauprojekte besser zu machen &#8211; Geoplast\" \/>\n<meta property=\"og:description\" content=\"Unsere Produkte und L\u00f6sungen k\u00f6nnen auf viele innovative Arten kombiniert und genutzt werden. Hier sind hundert Ideen, die Sie dazu inspirieren sollen, Ihr Konstruktionsdesign zu verbessern: 1. Sch\u00e4dliche D\u00e4mpfe an den Fundamenten ausl\u00fcften mit Modulo 2. Erh\u00f6hen Sie den Geb\u00e4udeboden mit Multimodulo 3. Verbessern Sie die Schallisolierung von B\u00f6den mit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geoplastglobal.com\/de\/blog\/100-moeglichkeiten-bauprojekte-besser-zu-machen\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoplast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/geoplast\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-07T07:43:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-15T12:03:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2020\/09\/100-WAYS-4-DE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marija Martinovic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:site\" content=\"@Geoplast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marija Martinovic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/100-moeglichkeiten-bauprojekte-besser-zu-machen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/100-moeglichkeiten-bauprojekte-besser-zu-machen\\\/\"},\"author\":{\"name\":\"Marija Martinovic\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/person\\\/020c9bd0060fa2a0b3130cd37b971cbc\"},\"headline\":\"100 M\u00f6glichkeiten Bauprojekte besser zu machen\",\"datePublished\":\"2020-10-07T07:43:37+00:00\",\"dateModified\":\"2022-04-15T12:03:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/100-moeglichkeiten-bauprojekte-besser-zu-machen\\\/\"},\"wordCount\":1053,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/100-moeglichkeiten-bauprojekte-besser-zu-machen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/100-WAYS-4-DE.jpg\",\"keywords\":[\"Build Fast\",\"Fundamentl\u00f6sungen\",\"Grunelosungen\",\"Lean Construction\",\"Nachhaltigen Profitabilit\u00e4t\",\"Nachhaltigkeit\",\"Plattenl\u00f6sungen\",\"Resilience\",\"Schalungsl\u00f6sungen\",\"Sportl\u00f6sungen\",\"Wasserl\u00f6sungen\"],\"articleSection\":[\"Konstruktion\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/100-moeglichkeiten-bauprojekte-besser-zu-machen\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/100-moeglichkeiten-bauprojekte-besser-zu-machen\\\/\",\"name\":\"100 M\u00f6glichkeiten Bauprojekte besser zu machen &#8211; Geoplast\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/100-moeglichkeiten-bauprojekte-besser-zu-machen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/100-moeglichkeiten-bauprojekte-besser-zu-machen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/100-WAYS-4-DE.jpg\",\"datePublished\":\"2020-10-07T07:43:37+00:00\",\"dateModified\":\"2022-04-15T12:03:00+00:00\",\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/100-moeglichkeiten-bauprojekte-besser-zu-machen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/blog\\\/100-moeglichkeiten-bauprojekte-besser-zu-machen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/100-WAYS-4-DE.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/100-WAYS-4-DE.jpg\",\"width\":1240,\"height\":500},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/\",\"name\":\"Geoplast\",\"description\":\"Geoplast S.p.A.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#organization\",\"name\":\"Geoplast\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"contentUrl\":\"https:\\\/\\\/www.geoplastglobal.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/geoplast.jpg\",\"width\":1644,\"height\":1030,\"caption\":\"Geoplast\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/geoplast\",\"https:\\\/\\\/x.com\\\/Geoplast\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geoplast-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/GEOPLASTspa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geoplastglobal.com\\\/de\\\/#\\\/schema\\\/person\\\/020c9bd0060fa2a0b3130cd37b971cbc\",\"name\":\"Marija Martinovic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f926bf327fd40f703774793ef896f698790e258141e48dc50352732cc2c9def3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f926bf327fd40f703774793ef896f698790e258141e48dc50352732cc2c9def3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f926bf327fd40f703774793ef896f698790e258141e48dc50352732cc2c9def3?s=96&d=mm&r=g\",\"caption\":\"Marija Martinovic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"100 M\u00f6glichkeiten Bauprojekte besser zu machen &#8211; Geoplast","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geoplastglobal.com\/de\/blog\/100-moeglichkeiten-bauprojekte-besser-zu-machen\/","og_locale":"de_DE","og_type":"article","og_title":"100 M\u00f6glichkeiten Bauprojekte besser zu machen &#8211; Geoplast","og_description":"Unsere Produkte und L\u00f6sungen k\u00f6nnen auf viele innovative Arten kombiniert und genutzt werden. Hier sind hundert Ideen, die Sie dazu inspirieren sollen, Ihr Konstruktionsdesign zu verbessern: 1. Sch\u00e4dliche D\u00e4mpfe an den Fundamenten ausl\u00fcften mit Modulo 2. Erh\u00f6hen Sie den Geb\u00e4udeboden mit Multimodulo 3. Verbessern Sie die Schallisolierung von B\u00f6den mit [&hellip;]","og_url":"https:\/\/www.geoplastglobal.com\/de\/blog\/100-moeglichkeiten-bauprojekte-besser-zu-machen\/","og_site_name":"Geoplast","article_publisher":"https:\/\/www.facebook.com\/geoplast","article_published_time":"2020-10-07T07:43:37+00:00","article_modified_time":"2022-04-15T12:03:00+00:00","og_image":[{"width":1240,"height":500,"url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2020\/09\/100-WAYS-4-DE.jpg","type":"image\/jpeg"}],"author":"Marija Martinovic","twitter_card":"summary_large_image","twitter_creator":"@Geoplast","twitter_site":"@Geoplast","twitter_misc":{"Written by":"Marija Martinovic","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/100-moeglichkeiten-bauprojekte-besser-zu-machen\/#article","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/100-moeglichkeiten-bauprojekte-besser-zu-machen\/"},"author":{"name":"Marija Martinovic","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/person\/020c9bd0060fa2a0b3130cd37b971cbc"},"headline":"100 M\u00f6glichkeiten Bauprojekte besser zu machen","datePublished":"2020-10-07T07:43:37+00:00","dateModified":"2022-04-15T12:03:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/100-moeglichkeiten-bauprojekte-besser-zu-machen\/"},"wordCount":1053,"publisher":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#organization"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/100-moeglichkeiten-bauprojekte-besser-zu-machen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2020\/09\/100-WAYS-4-DE.jpg","keywords":["Build Fast","Fundamentl\u00f6sungen","Grunelosungen","Lean Construction","Nachhaltigen Profitabilit\u00e4t","Nachhaltigkeit","Plattenl\u00f6sungen","Resilience","Schalungsl\u00f6sungen","Sportl\u00f6sungen","Wasserl\u00f6sungen"],"articleSection":["Konstruktion"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/100-moeglichkeiten-bauprojekte-besser-zu-machen\/","url":"https:\/\/www.geoplastglobal.com\/de\/blog\/100-moeglichkeiten-bauprojekte-besser-zu-machen\/","name":"100 M\u00f6glichkeiten Bauprojekte besser zu machen &#8211; Geoplast","isPartOf":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/100-moeglichkeiten-bauprojekte-besser-zu-machen\/#primaryimage"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/100-moeglichkeiten-bauprojekte-besser-zu-machen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2020\/09\/100-WAYS-4-DE.jpg","datePublished":"2020-10-07T07:43:37+00:00","dateModified":"2022-04-15T12:03:00+00:00","inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geoplastglobal.com\/de\/blog\/100-moeglichkeiten-bauprojekte-besser-zu-machen\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.geoplastglobal.com\/de\/blog\/100-moeglichkeiten-bauprojekte-besser-zu-machen\/#primaryimage","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2020\/09\/100-WAYS-4-DE.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2020\/09\/100-WAYS-4-DE.jpg","width":1240,"height":500},{"@type":"WebSite","@id":"https:\/\/www.geoplastglobal.com\/de\/#website","url":"https:\/\/www.geoplastglobal.com\/de\/","name":"Geoplast","description":"Geoplast S.p.A.","publisher":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geoplastglobal.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.geoplastglobal.com\/de\/#organization","name":"Geoplast","url":"https:\/\/www.geoplastglobal.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","contentUrl":"https:\/\/www.geoplastglobal.com\/wp-content\/uploads\/2016\/11\/geoplast.jpg","width":1644,"height":1030,"caption":"Geoplast"},"image":{"@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/geoplast","https:\/\/x.com\/Geoplast","https:\/\/www.linkedin.com\/company\/geoplast-spa","https:\/\/www.youtube.com\/user\/GEOPLASTspa"]},{"@type":"Person","@id":"https:\/\/www.geoplastglobal.com\/de\/#\/schema\/person\/020c9bd0060fa2a0b3130cd37b971cbc","name":"Marija Martinovic","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/f926bf327fd40f703774793ef896f698790e258141e48dc50352732cc2c9def3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f926bf327fd40f703774793ef896f698790e258141e48dc50352732cc2c9def3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f926bf327fd40f703774793ef896f698790e258141e48dc50352732cc2c9def3?s=96&d=mm&r=g","caption":"Marija Martinovic"}}]}},"_links":{"self":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/140955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/comments?post=140955"}],"version-history":[{"count":9,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/140955\/revisions"}],"predecessor-version":[{"id":168994,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/posts\/140955\/revisions\/168994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/media\/140960"}],"wp:attachment":[{"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/media?parent=140955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/categories?post=140955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geoplastglobal.com\/de\/wp-json\/wp\/v2\/tags?post=140955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}